{"id":1018,"date":"2008-12-11T12:57:04","date_gmt":"2008-12-11T11:57:04","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/"},"modified":"2008-12-11T12:57:04","modified_gmt":"2008-12-11T11:57:04","slug":"otranto-vacanze-a-360%b0-dove-e-sempre-estate","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/","title":{"rendered":"Otranto &#8211; Vacanze a 360\u00b0 dove \u00e8 sempre estate"},"content":{"rendered":"<p>Posta nel punto pi\u00f9 a est della nostra penisola la citt\u00e0 di Otranto, una tra le pi\u00f9 belle di tutto il Salento, luogo simbolo del Mediterraneo, splendida realt\u00e0 turistica salentina \u00e8 conosciuta e apprezzata ovunque sia per le sue bellezze naturali che per quelle artistiche.<\/p>\n<p>Conosciuta anche come la \u201cCitt\u00e0 dei Martiri\u201d, per l\u2019eccidio turco del 1480 in cui vennero decapitati 800 otrantini sul colle della Minerva, Otranto \u00e8 una citt\u00e0 dove anche le maestose mura che la fortificano raccontano di civilt\u00e0 passate dove, passeggiando tra i monumenti o vagando per il centro storico si possono sentire echi di voci antiche che ancora non vogliono abbandonare questo posto.<\/p>\n<p>In particolar modo, visitando la citt\u00e0 \u00e8 proprio questo l\u2019elemento che maggiormente risalta ai nostri occhi, ovvero, la percezione della storia, il rispetto per il passato, quello che ancora rivive nelle maestose mura del Castello Aragonese che maestoso sorge al centro della citt\u00e0, suggestivo per l\u2019affaccio sul porto, situato accanto al piccolo ed incantevole borgo antico e nella Cattedrale, uno dei complessi architettonici pi\u00f9 ricchi del Salento, considerata la chiesa pi\u00f9 grande della Puglia&nbsp;dove \u00e8 possibile visitare il quasi millenario mosaico pavimentale,&nbsp;il pi\u00f9 grande&nbsp;al mondo, dove \u00e8 raffigurato \u201cl\u2019albero della vita\u201d e dove, a testimonianza della tessa storia, in sette armadi sono racchiusi i resti dei martiri.<\/p>\n<p>Ma oltre all&#8217;arte, alla storia e alle tradizioni, senza dubbio molto importanti, la citt\u00e0 di Otranto \u00e8 conosciuta, in particolar modo, per il suo mare limpido e&nbsp;cristallino tanto da esser premiato con le 5 vele di Legambiente e per la sua straordinaria costa, un susseguirsi di distese dorate di sabbia&nbsp; interrotte di tanto in tanto dalla presenza di torri e masserie tutto immerso nel caratteristico fascino della macchia mediterranea, fatta per lo pi\u00f9 di pini marittimi ed in parte di vegetazione mediterranea, tipica di questa zona del Salento.<\/p>\n<p>E poi, ancora i Laghi Alimini, vero patrimonio dell\u2019agro otrantino, composti da due laghi, Fontanelle (detto anche Alimini Piccolo) e Alimini Grande. Il primo \u00e8 un lago di acqua dolce di origine carsica e alimentato dalle precipitazioni meteoriche e da diverse sorgenti dette appunto fontanelle, inoltre, \u00e8 collegato ad Alimini Grande attraverso un canale, che lo va ad alimentare di acqua dolce.<\/p>\n<p>Questo e tanto, molto altro \u00e8 Otranto, cittadina veramente incantevole, quasi magica, da innamorarsene a prima vista. <\/p>\n<p>Chi trascorre una <a href=\"http:\/\/www.otrantoinfo.it\/\">vacanza a Otranto<\/a>, dunque, lo appezza per la sua atmosfera magica, le sue meraviglie tutte da scoprire, il mare, il sole, la costa da sogno.<\/p>\n<p>Un mix&nbsp; di arte, cultura e tradizione che rendono questo posto cos\u00ec unico per chi ci vive e fantastico per chi lo visita.<\/p>\n<p>Prenota subito la tua vacanza otrantina su www.salentonet.it. <\/p>\n<p>Qui, oltre a convenienti proposte, pacchetti viaggio e last minute potrai organizzare personalmente la TUA vacanza scegliendo tra le numerose soluzioni che salentonet ha riservato per te quali: Residence, Ville, Case Vacanza, Alberghi, Villaggi a Otranto e dintorni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viaggio virtuale alla scoperta di storia, arte e cultura, tradizione attraverso &#8220;la Porta d&#8217;Oriente&#8221;, Otranto, la &#8220;citt\u00e0 dalle molte acque&#8221;.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[2],"tags":[1053,1051,253,3502,4],"class_list":["post-1018","post","type-post","status-publish","format-standard","hentry","category-viaggi-e-turismo","tag-otranto","tag-puglia","tag-turismo","tag-vacanze-salento","tag-viaggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360?-dove-e-sempre-estate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Viaggio virtuale alla scoperta di storia, arte e cultura, tradizione attraverso &quot;la Porta d&#039;Oriente&quot;, Otranto, la &quot;citt\u00e0 dalle molte acque&quot;.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-11T11:57:04+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Otranto &#8211; Vacanze a 360\u00b0 dove \u00e8 sempre estate\",\"datePublished\":\"2008-12-11T11:57:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/\"},\"wordCount\":495,\"commentCount\":0,\"keywords\":[\"otranto\",\"puglia\",\"turismo\",\"vacanze salento\",\"viaggi\"],\"articleSection\":[\"Viaggi e Turismo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/\",\"name\":\"Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2008-12-11T11:57:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/viaggi-e-turismo\\\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otranto &#8211; Vacanze a 360\u00b0 dove \u00e8 sempre estate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360?-dove-e-sempre-estate\/","og_locale":"it_IT","og_type":"article","og_title":"Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing","og_description":"Viaggio virtuale alla scoperta di storia, arte e cultura, tradizione attraverso \"la Porta d'Oriente\", Otranto, la \"citt\u00e0 dalle molte acque\".","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360?-dove-e-sempre-estate\/","og_site_name":"Article Marketing","article_published_time":"2008-12-11T11:57:04+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Otranto &#8211; Vacanze a 360\u00b0 dove \u00e8 sempre estate","datePublished":"2008-12-11T11:57:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/"},"wordCount":495,"commentCount":0,"keywords":["otranto","puglia","turismo","vacanze salento","viaggi"],"articleSection":["Viaggi e Turismo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/","name":"Otranto - Vacanze a 360\u00b0 dove \u00e8 sempre estate - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2008-12-11T11:57:04+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/viaggi-e-turismo\/otranto-vacanze-a-360%b0-dove-e-sempre-estate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Otranto &#8211; Vacanze a 360\u00b0 dove \u00e8 sempre estate"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}