{"id":10682,"date":"2010-12-21T11:06:32","date_gmt":"2010-12-21T10:06:32","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/"},"modified":"2018-07-10T04:01:20","modified_gmt":"2018-07-10T02:01:20","slug":"mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/","title":{"rendered":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance"},"content":{"rendered":"<p><em>Dal 5 al 9 gennaio, al moderno Palazzo dei Congressi di Riccione, si tiene un evento imperdibile per gli appassionati delle danze metropolitane: il Mc Hip Hop Contest 2011,dove i migliori ballerini nazionali e internazionali si sfideranno per essere incoronati re della street dance<\/em><\/p>\n<p>Un mix di energia, balli, musiche e colori: dal 5 al 9 gennaio 2011 al Palacongressi di Riccione appuntamento con la sedicesima edizione dell&rsquo;<strong>Mc<\/strong> <strong>Hip Hop Contest Riccione<\/strong>, l&rsquo;evento nazionale per eccellenza della cultura hip hop. <\/p>\n<p>La manifestazione <strong>Mc Hip Hop Contest Riccione<\/strong>, organizzata da Idea s.r.l in collaborazione con Cruisin&rsquo; con il patrocinio del Comune di Riccione e della Provincia di Rimini, conferma la sua formula vincente: cinque giornate dedicate all&rsquo;urban culture, convention, stage, contest, concerti e one night con i migliori insegnanti, coreografi e ballerini nazionali e internazionali, un cast di grande prestigio decreteranno i migliori street dancer.<\/p>\n<p>Il popolo dell&rsquo;hip hop si muove da ogni parte d&rsquo;Europa (attesi gruppi da Spagna, Portogallo, Francia, Germania, Svizzera) e anche dagli Stati Uniti(si esibiranno anche i vincitori dell&rsquo;ultima edizione di American&rsquo;s next best crew!) per trasformare il <strong>Mc Hip Hop Contest Riccione<\/strong> in un laboratorio di creativit&agrave;, in un meeting che unisce, che annulla le differenze, che anticipa, anzi detta, le nuove tendenze.<\/p>\n<p>Evento imperdibile per gli appassionati delle danze metropolitane. Per l&rsquo;imminente edizione del <strong>Mc<\/strong> <strong>Hip Hop Contest Riccione<\/strong> si prevedono importanti novit&agrave; capaci di incuriosire, attrarre e stupire ancora una volta gli oltre 2000 artisti che si danno appuntamento nella citt&agrave; pi&ugrave; giovane d&rsquo;Italia, officina del divertimento, all&rsquo;avanguardia per strutture e ricettivit&agrave;..<\/p>\n<p>Per un soggiorno che racchiuda lavoro e svago, l&rsquo;<strong>Hotel Lungomare di Riccione<\/strong> &egrave; ci&ograve; che fa per voi! L&rsquo;albergo dispone di cinquantasei camere, elegantemente arredate, tutte vista mar, situato in pieno centro e vicino al Viale Ceccarini. Inoltre L&rsquo;<strong>Hotel Maestrale<\/strong>, piccolo gioiello di ospitalit&agrave; in centro a Riccione e a due passi dal mare, offre ventisei camere sapientemente arredate e curate in ogni dettaglio,tra cui dieci confortevoli Suite, che racchiudono l&rsquo;essenza della vacanza al mare. I <strong>Residence Lungomare<\/strong> offrono 43 confortevoli appartamenti, tutti in centro e a due passi dal mare, che consentono un soggiorno in piena libert&agrave; senza rinunciare all&rsquo;agio dei servizi a cinque stelle degli Hotel Lungomare e Maestrale, dei quali si pu&ograve; usufruire in ogni momento.<\/p>\n<p><em>Dal 5 al 9 gennaio, al moderno Palazzo dei Congressi di Riccione, si tiene un evento imperdibile per gli appassionati delle danze metropolitane: il Mc Hip Hop Contest 2011,dove i migliori ballerini nazionali e internazionali si sfideranno per essere incoronati re della street dance<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al Palazzo dei Congressi di Riccione, dal 5 al 9 gennaio, si svolge l&#8217;Mc Hip Hop Contest 2011, dove i migliori ballerini nazionali e internazionali si sfideranno per essere incoronati re della street dance<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[280],"tags":[20604,20603,16698],"class_list":["post-10682","post","type-post","status-publish","format-standard","hentry","category-viaggi-e-vacanze","tag-hip-hop-contest-2011","tag-hip-hop-contest-riccione","tag-hotel-4-stelle-riccione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Al Palazzo dei Congressi di Riccione, dal 5 al 9 gennaio, si svolge l&#039;Mc Hip Hop Contest 2011, dove i migliori ballerini nazionali e internazionali si sfideranno per essere incoronati re della street dance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-21T10:06:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:01:20+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance\",\"datePublished\":\"2010-12-21T10:06:32+00:00\",\"dateModified\":\"2018-07-10T02:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/\"},\"wordCount\":468,\"commentCount\":0,\"keywords\":[\"hip hop contest 2011\",\"hip hop contest riccione\",\"hotel 4 stelle riccione\"],\"articleSection\":[\"Viaggi e vacanze\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/\",\"name\":\"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-12-21T10:06:32+00:00\",\"dateModified\":\"2018-07-10T02:01:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/","og_locale":"it_IT","og_type":"article","og_title":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing","og_description":"Al Palazzo dei Congressi di Riccione, dal 5 al 9 gennaio, si svolge l'Mc Hip Hop Contest 2011, dove i migliori ballerini nazionali e internazionali si sfideranno per essere incoronati re della street dance","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/","og_site_name":"Article Marketing","article_published_time":"2010-12-21T10:06:32+00:00","article_modified_time":"2018-07-10T02:01:20+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance","datePublished":"2010-12-21T10:06:32+00:00","dateModified":"2018-07-10T02:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/"},"wordCount":468,"commentCount":0,"keywords":["hip hop contest 2011","hip hop contest riccione","hotel 4 stelle riccione"],"articleSection":["Viaggi e vacanze"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/","name":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-12-21T10:06:32+00:00","dateModified":"2018-07-10T02:01:20+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/mc-hip-hop-contest-2011-a-riccione-cinque-giorni-dedicati-alla-street-dance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"MC Hip Hop Contest 2011, a Riccione cinque giorni dedicati alla street dance"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/10682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=10682"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/10682\/revisions"}],"predecessor-version":[{"id":57838,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/10682\/revisions\/57838"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=10682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=10682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=10682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}