{"id":11027,"date":"2011-01-03T17:19:08","date_gmt":"2011-01-03T16:19:08","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/"},"modified":"2011-01-03T17:19:08","modified_gmt":"2011-01-03T16:19:08","slug":"2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/","title":{"rendered":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011?"},"content":{"rendered":"<p>Gli inizi d&rsquo;anno sono un ottimo pretesto per fare la lista dei buoni propositi. Noi di House living and business preferiamo per&ograve; indagare con voi su quegli artisti (viventi) che nel 2010 hanno fatto parlare di s&egrave; e del proprio lavoro lasciando in sospeso questioni che dovranno riprendere in mano nel 2011. Noi le andremo indagare per raccontarvi il prosieguo di quella che sar&agrave; una parte della storia dell&rsquo;arte che vivremo in diretta con i protagonisti.<\/p>\n<p>BROS, alias Daniele Nicolosi, writer milanese di 28 anni, il 12 luglio &egrave; stato prosciolto dal reato di imbrattamento per prescrizione e remissione della querela. IL FATTO: Bros viene accusato di aver &ldquo;imbrattato&rdquo; con dei graffiti il muro del carcere di San Vittore (2004), la pensilina del parcheggio delle biciclette alla fermata della metropolitana di piazzale Lodi (2007) e la sede di un&rsquo;immobiliare di via De Angeli 4 (2007). L&rsquo;agenzia immobiliare ritira la denuncia, il reato per il muro di San Vittore va in prescrizione e, per quanto riguarda la pensilina, l&rsquo;Atm avrebbe dovuto querelare Bros, che invece &egrave; stato perseguito diversamente. Si riapre il dibattito street art\/imbrattamento sui muri illegali, parla di Bros anche il New York Times nel suo <a href=\"http:\/\/www.nytimes.com\/2010\/07\/13\/world\/europe\/13iht-italy.html\" target=\"blank\">Italian Graffiti Artist Acquitted on Technicalities<\/a> che non manca di citare la frase d&rsquo;effetto &laquo;Credo che il motto colpirne uno per educarne cento sia un po retr&ograve;, non credete?&raquo; di Nicolosi. Vittorio Sgarbi ha gi&agrave; definito Bros in passato &ldquo;novello Giotto&rdquo;, ma &egrave; il Corriere della Sera a decretare che Davide (ops, ha usato il nome sbagliato!) Daniele Nicolosi &egrave; un artista, che i suoi lavori sono opere d&rsquo;arte, e lo dice in prima pagina il 4 agosto 2010, nel suo articolo Il giudice del processo a Bros: reato anche i graffiti artistici. LA DOMANDA: Vittorio Sgarbi, detrattore di Bros, inviter&agrave; il Giotto del XXI secolo alla Biennale di Venezia? Bros, graffitaro puro e crudo, accetter&agrave;?<\/p>\n<p>GIUSEPPE VENEZIANO artista neopop decisamente ironico, quarant&rsquo;anni il prossimo 22 febbraio, il 13 settembre pubblica un editoriale-confessione-giustificazione su Arslife L&rsquo;arte e la libert&agrave; d&rsquo;espressione. IL FATTO: Il 17 luglio inaugura la mostra antologica Zeitgeist dedicata all&rsquo;opera dell&rsquo;artista siciliano Giuseppe Veneziano, curata da Ivan Quaroni ed organizzata dalla Gestalt Gallery di Pietrasanta. In particolare il dipinto &ldquo;Madonna del terzo Reich&rdquo; che ritrae la Madonna con in braccio un piccolo ed opportunamente vestito Hitler, suscita un certo disappunto, tanto che nell&rsquo;articolo Veneziano si sente in dovere di raccontare la poetica del quadro &ldquo;Per quanto Hitler sia la rappresentazione pi&ugrave; eclatante del Male, &egrave; pur sempre una creatura di Dio. La Madonna, quindi, anche in un&rsquo;accezione cristiana, non pu&ograve; avere paura di Hitler.&rdquo; Noi di House living and business abbiamo duramente criticato la posizione &ldquo;giustificatoria&rdquo; dell&rsquo;artista nel nostro Panseca, Kosolapov, Veneziano&hellip; &egrave; arte o provocazione? del 14 settembre, coinvolgendo nel dibattito &ldquo;arte e provocazione&rdquo; e &ldquo;arte di regime&rdquo;, assieme ad altre, anche l&rsquo;opera di Filippo Panseca, che ha risposto sia a noi che a Giuseppe Veneziano. Il 21 settembre nel pezzo Panseca, sono io che con Craxi ho cambiato l&rsquo;immagine del PSI abbiamo pubblicato la risposta. LA DOMANDA: Dopo la mostra &ldquo;Equivoci&rdquo; presso il Museo della Mafia a Salemi, a cura di Vittorio Sgarbi, inaugurata il 29 settembre, vedremo anche il grande provocatore alla Biennale invitato da Sgarbi?<br \/>\nLeggi qui l&#8217;articolo completo&#8230; http:\/\/www.immobilia-re.eu\/house-living-and-business-rassegna-stampa-3-gennaio-2011\/2\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli inizi d\u2019anno sono un ottimo pretesto per fare la lista dei buoni propositi. Noi di House living and business preferiamo per\u00f2 indagare con voi su quegli artisti (viventi) che nel 2010 hanno fatto parlare di s\u00e8 e del proprio lavoro lasciando in sospeso questioni che dovranno riprendere in mano nel 2011. Noi le andremo indagare per raccontarvi il prosieguo di quella che sar\u00e0 una parte della storia dell\u2019arte che vivremo in diretta con i protagonisti.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[20930,20936,20933,20931,20934,20935,20932,16215],"class_list":["post-11027","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-bros","tag-classifica-artisti-2010","tag-damien-hirst","tag-daniele-nicolosi","tag-enrique-chagoya","tag-giuseppe-veneziano","tag-maurizio-cattelan","tag-rassegna-stampa-arte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa??-almeno-cos\u00ec-dicono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Gli inizi d\u2019anno sono un ottimo pretesto per fare la lista dei buoni propositi. Noi di House living and business preferiamo per\u00f2 indagare con voi su quegli artisti (viventi) che nel 2010 hanno fatto parlare di s\u00e8 e del proprio lavoro lasciando in sospeso questioni che dovranno riprendere in mano nel 2011. Noi le andremo indagare per raccontarvi il prosieguo di quella che sar\u00e0 una parte della storia dell\u2019arte che vivremo in diretta con i protagonisti.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-03T16:19:08+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"10 artisti per 10 buoni propositi, cosa ci riserva il 2011?\",\"datePublished\":\"2011-01-03T16:19:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/\"},\"wordCount\":604,\"commentCount\":0,\"keywords\":[\"Bros\",\"classifica artisti 2010\",\"Damien Hirst\",\"Daniele Nicolosi\",\"Enrique Chagoya\",\"Giuseppe Veneziano\",\"Maurizio Cattelan\",\"rassegna stampa arte\"],\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/\",\"name\":\"10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-01-03T16:19:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 artisti per 10 buoni propositi, cosa ci riserva il 2011?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa??-almeno-cos\u00ec-dicono\/","og_locale":"it_IT","og_type":"article","og_title":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing","og_description":"Gli inizi d\u2019anno sono un ottimo pretesto per fare la lista dei buoni propositi. Noi di House living and business preferiamo per\u00f2 indagare con voi su quegli artisti (viventi) che nel 2010 hanno fatto parlare di s\u00e8 e del proprio lavoro lasciando in sospeso questioni che dovranno riprendere in mano nel 2011. Noi le andremo indagare per raccontarvi il prosieguo di quella che sar\u00e0 una parte della storia dell\u2019arte che vivremo in diretta con i protagonisti.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa??-almeno-cos\u00ec-dicono\/","og_site_name":"Article Marketing","article_published_time":"2011-01-03T16:19:08+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011?","datePublished":"2011-01-03T16:19:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/"},"wordCount":604,"commentCount":0,"keywords":["Bros","classifica artisti 2010","Damien Hirst","Daniele Nicolosi","Enrique Chagoya","Giuseppe Veneziano","Maurizio Cattelan","rassegna stampa arte"],"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/","name":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011? - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-01-03T16:19:08+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/2011-un-anno-tutto-rosaa%80%a6-almeno-cos%c3%ac-dicono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"10 artisti per 10 buoni propositi, cosa ci riserva il 2011?"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=11027"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11027\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=11027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=11027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=11027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}