{"id":11072,"date":"2011-01-05T16:55:22","date_gmt":"2011-01-05T15:55:22","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/"},"modified":"2011-01-05T16:55:22","modified_gmt":"2011-01-05T15:55:22","slug":"nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/","title":{"rendered":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G"},"content":{"rendered":"<p><em><strong>L&#8217;agenzia di Parma &egrave; al lavoro per progettare il nuovo sito del marchio di moda Toy G e curer&agrave; anche la comunicazione su internet: dal SEM alla presenza sui social network, alla pianificazione di campagne banner e PayPerClick.<br \/><\/strong><\/em><br \/>Divertente, glamour, femminile: &egrave; la donna Toy G, il marchio del gruppo Cris Conf SpA, che Layoutweb ha il compito di far conoscere alle utenti di internet, sia attraverso lo studio e la progettazione di un nuovo sito, che con numerose attivit&agrave; di web marketing. Queste ultime vanno dal posizionamento sui motori di ricerca al presidio dei principali social network, dalla realizzazione di campagne banner all&#8217;invio di articoli e comunicati stampa alle principali testate on line.<\/p>\n<p>La societ&agrave;, che conta oltre 500 dipendenti e ha un fatturato anno di 160 milioni di euro, ha scelto di affidarsi all&#8217;agenzia di Parma per incrementare la visibilit&agrave; di Toy G e di puntare, a livello digitale, su una strategia di comunicazione che coinvolga il target femminile con particolare attenzione alla fascia 20-35 anni. La donna con cui Layoutweb vuole entrare in contatto &egrave; attenta alla propria immagine e ai dettagli, ma senza rinunciare alla praticit&agrave; dei capi che indossa. Le piace essere di tendenza &ldquo;24 ore su 24&rdquo; dal mattino in ufficio fino alla sera fuori con gli amici.<\/p>\n<p>Punto di partenza di questo progetto di ampio respiro &egrave; il sito, pensato con un layout grafico di forte impatto. Il concept creativo si ispira infatti al mondo Toy G e allo stile delle sue collezioni. Oltre a consultare l&#8217;area prodotti, i visitatori potranno condividere il Toy G&amp;Friends, un luogo d&#8217;incontro virtuale animato dalla redazione, dove scambiare idee e commenti sui prodotti del brand e sul mondo della moda. Infine, Layoutweb riserver&agrave; uno spazio web completamente dedicato ai rivenditori, che potr&agrave; essere attivato in modo semplice e intuitivo, per inserire informazioni utili sui singoli negozi, prodotti, iniziative, contatti.<\/p>\n<p>Per quanto riguarda il web marketing la strategia seguita da Layoutweb prevede di affiancare l&#8217;attivit&agrave; di indicizzazione e posizionamento sui motori di ricerca con piano editoriale mirato e condiviso con la societ&agrave;, che comprende attivit&agrave; di tipo redazionale e virale su blog, forum e social network, unito all&#8217;invio di comunicati stampa a siti, portali e testate on line. Campagne banner, l&#8217;invio di DEM a database profilati, campagna PayPerClick su Google.it, Facebook e YouTube completano il pacchetto.<br \/><em>La sinergia tra moda e web &egrave; giovane e ricca di opportunit&agrave;. Grazie alla partnership con Toy G e alla nostra esperienza in fatto di comunicazione su internet, vogliamo sfruttare al meglio tutte le possibilit&agrave; offerte da questo mezzo &ndash; <\/em>commenta Claudio Agazzi presidente di Layoutweb<em> &ndash; Abbiamo messo in cantiere un progetto molto strutturato che comprende la creazione del sito e la promozione sul web del marchio Toy G dal web advertising pi&ugrave; classico alla presenza sui social network. In sintesi vogliamo fare in modo che questa campagna lasci il segno e che Toy G diventi un marchio di riferimento per il nostro target&rdquo;.<\/em><\/p>\n<p>Per saperne di pi&ugrave; sui servizi di Layoutweb, dalla <strong>realizzazione di siti internet<\/strong>, al <strong>posizionamento sui motori di ricerca<\/strong>, al <strong>web marketing<\/strong> visita il sito <a href=\"http:\/\/www.layoutweb.it\">www.layoutweb.it<\/a><\/p>\n<p>Contatti:<br \/>Layoutweb, Layout Advertising Group<br \/>Public Relation Department<br \/>Simona Bonati<br \/>e-mail: bonati@layoutweb.it<br \/>sito internet: www.layoutweb.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;agenzia di Parma \u00e8 al lavoro per progettare il nuovo sito del marchio di moda Toy G e curer\u00e0 anche la comunicazione su internet: dal SEM alla presenza sui social network, alla pianificazione di campagne banner e PayPerClick.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[565],"tags":[],"class_list":["post-11072","post","type-post","status-publish","format-standard","hentry","category-web-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L&#039;agenzia di Parma \u00e8 al lavoro per progettare il nuovo sito del marchio di moda Toy G e curer\u00e0 anche la comunicazione su internet: dal SEM alla presenza sui social network, alla pianificazione di campagne banner e PayPerClick.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-05T15:55:22+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G\",\"datePublished\":\"2011-01-05T15:55:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/\"},\"wordCount\":563,\"commentCount\":0,\"articleSection\":[\"Web marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/\",\"name\":\"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-01-05T15:55:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing","og_description":"L'agenzia di Parma \u00e8 al lavoro per progettare il nuovo sito del marchio di moda Toy G e curer\u00e0 anche la comunicazione su internet: dal SEM alla presenza sui social network, alla pianificazione di campagne banner e PayPerClick.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/","og_site_name":"Article Marketing","article_published_time":"2011-01-05T15:55:22+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G","datePublished":"2011-01-05T15:55:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/"},"wordCount":563,"commentCount":0,"articleSection":["Web marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/","name":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-01-05T15:55:22+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/nuovo-sito-e-web-marketing-firmato-layoutweb-nel-2011-di-toy-g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Nuovo sito e web marketing firmato Layoutweb nel 2011 di Toy G"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=11072"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11072\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=11072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=11072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=11072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}