{"id":1151,"date":"2009-01-14T09:40:51","date_gmt":"2009-01-14T08:40:51","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/bolsena-una-storia-millenaria-ci-credereste\/"},"modified":"2009-01-14T09:40:51","modified_gmt":"2009-01-14T08:40:51","slug":"bolsena-una-storia-millenaria-ci-credereste","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/","title":{"rendered":"Bolsena, una storia millenaria&#8230; ci credereste?"},"content":{"rendered":"<p><a href=\"http:\/\/www.lago-di-bolsena.biz\/bolsena\/\">Bolsena<\/a> \u00e8 una cittadina d&#8217;impianto medievale che insiste sul lato orientale del grande lago, proprio alle pendici dei monti Volsini. Le sue origini risalgono al periodo etrusco quando la popolazione d Velzna, in seguito alla distruzione della citt\u00e0 (III sec. a.C.), vi si rifugiarono. Inizi\u00f2 dunque un periodo etrusco-romano che oggi riporta diverse testimonianza.<\/p>\n<p>In seguito all&#8217;invasione longobarda si svilupp\u00f2 un borgo medievale presso la rupe dove oggi sorge il Castello ed il quartiere medievale.<\/p>\n<p>La cittadella fior\u00ec da quando divenne patrimonio della chiesa. Si narra che 1263 proprio a Bolsena accadde il miracolo eucaristico del <strong>Corpus Domini<\/strong> dalla quale prese origine l&#8217;omonima festivit\u00e0.<\/p>\n<p>Un sacerdote boemo di allora, dubbioso sulla presenza reale di Cristo nell&#8217;Eucarestia, part\u00ec alla volta di un pellegrinaggio per Roma. Al ritorno, presso la comunit\u00e0 di Bolsena chiese di poter celebrare la S. Messa. Proprio durante  la Preghiera Eucaristica  vide le ostie sanguinare e a bagnare il corporale. Da allora non ebbe pi\u00f9 alcun dubbio. A Bolsena sono ancora conservate 3 pietre bagnate dal sangue mentre il corporele \u00e8 racchiuso in uno splendido reliquiario custodito in una cappella del <strong>Duomo di Orvieto.<\/strong><\/p>\n<p>Nel 1938 Bonifacio IX la concesse in Vicariato alla famiglia dei Monaldeschi della Cervera. Il <strong>castello Monadelschi<\/strong> (XI-XIV sec. d.C.) oggi accoglie il <strong>Museo Territoriale del Lago di Bolsena<\/strong> ricco di reperti archeologici dell&#8217;intera zona lacustre.<\/p>\n<p>Nei pressi della cittadina \u00e8 possibili visitare la <strong>zona archeologica di Poggio Mosconi<\/strong> caratterizzata della cinta muraria che racchiude l&#8217;anfiteatro di Marcatelo, luoghi di culto, il foro, una grande basilica. Nella zona archeologica si possono ancora ammirare vecchi affreschi ed eleganti pavimenti a mosaico.<\/p>\n<p>Infine rimane da annoverare la <strong>Basilica<\/strong><strong> di S. Cristina<\/strong>, un complesso architettonico che racchiude in s\u00e9 quattro chiese di epoche diverse: La Grotta di S.Cristina (dove avvenne il miracolo del Corpus Domini)e le catacombe,  l&#8217;edificio romanico, La Cappella del miracolo e la Cappella di S. Leonardo.<\/p>\n<p>Nel paese \u00e8 possibile fare delle splendite passeggiate per le vie del borgo o lungo la sponda del lago. Vi sono spiagge facilemte accessibile dotate di opportune strutture recettive. Il paese \u00e8 dotato anche di un porto turistico da cui \u00e8 possibile noleggiare posteggi, barche ed effettuare escursioni presso l&#8217;<strong>Isola Bisentina<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"http:\/\/www.lago-di-bolsena.biz\/bolsena\/\">Bolsena<\/a> \u00e8 una cittadina d&#8217;impianto medievale che insiste sul lato orientale del grande lago, proprio alle pendici dei monti Volsini. Le sue origini risalgono al periodo etrusco quando la popolazione d Velzna, in seguito alla distruzione della citt\u00e0 (III sec. a.C.), vi si rifugiarono. Inizi\u00f2 dunque un periodo etrusco-romano che oggi riporta diverse testimonianza.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[280],"tags":[3215,3209,3211,3208,3210,3212,3214,3213,253],"class_list":["post-1151","post","type-post","status-publish","format-standard","hentry","category-viaggi-e-vacanze","tag-bisentina","tag-bolsena","tag-craterico","tag-lago","tag-lago-di-bolsena","tag-marta","tag-martana","tag-sesse","tag-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsena, una storia millenaria... ci credereste? - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsena, una storia millenaria... ci credereste? - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Bolsena \u00e8 una cittadina d&#039;impianto medievale che insiste sul lato orientale del grande lago, proprio alle pendici dei monti Volsini. Le sue origini risalgono al periodo etrusco quando la popolazione d Velzna, in seguito alla distruzione della citt\u00e0 (III sec. a.C.), vi si rifugiarono. Inizi\u00f2 dunque un periodo etrusco-romano che oggi riporta diverse testimonianza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-14T08:40:51+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Bolsena, una storia millenaria&#8230; ci credereste?\",\"datePublished\":\"2009-01-14T08:40:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/\"},\"wordCount\":364,\"commentCount\":0,\"keywords\":[\"bisentina\",\"bolsena\",\"craterico\",\"lago\",\"lago di bolsena\",\"marta\",\"martana\",\"sesse\",\"turismo\"],\"articleSection\":[\"Viaggi e vacanze\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/\",\"name\":\"Bolsena, una storia millenaria... ci credereste? - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-01-14T08:40:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/bolsena-una-storia-millenaria-ci-credereste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsena, una storia millenaria&#8230; ci credereste?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsena, una storia millenaria... ci credereste? - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/","og_locale":"it_IT","og_type":"article","og_title":"Bolsena, una storia millenaria... ci credereste? - Article Marketing","og_description":"Bolsena \u00e8 una cittadina d'impianto medievale che insiste sul lato orientale del grande lago, proprio alle pendici dei monti Volsini. Le sue origini risalgono al periodo etrusco quando la popolazione d Velzna, in seguito alla distruzione della citt\u00e0 (III sec. a.C.), vi si rifugiarono. Inizi\u00f2 dunque un periodo etrusco-romano che oggi riporta diverse testimonianza.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/","og_site_name":"Article Marketing","article_published_time":"2009-01-14T08:40:51+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Bolsena, una storia millenaria&#8230; ci credereste?","datePublished":"2009-01-14T08:40:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/"},"wordCount":364,"commentCount":0,"keywords":["bisentina","bolsena","craterico","lago","lago di bolsena","marta","martana","sesse","turismo"],"articleSection":["Viaggi e vacanze"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/","name":"Bolsena, una storia millenaria... ci credereste? - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-01-14T08:40:51+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/bolsena-una-storia-millenaria-ci-credereste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Bolsena, una storia millenaria&#8230; ci credereste?"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}