{"id":11555,"date":"2008-06-11T11:37:13","date_gmt":"2008-06-11T09:37:13","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/"},"modified":"2008-06-11T11:37:13","modified_gmt":"2008-06-11T09:37:13","slug":"accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/","title":{"rendered":"Accordo tra Aaps informatica  e Redam per la modellazione di strutture aeronautiche"},"content":{"rendered":"<p class=\"Normale1\" style=\"TEXT-ALIGN: justify\">Da oggi ci sar\u00e0 anche un pezzo d\u2019Irpinia nella progettazione di aerei. AAPS Informatica sigla &nbsp;un accordo con Redam (Research and Development in Applied Mechanics) per lo sviluppo di applicativi software rivolti alla modellazione geometrica di strutture aeronautiche. La Redam \u00e8 una nota societ\u00e0 di ingegneria operante nell\u2019ambito della meccanica applicata che vanta, per suo conto, &nbsp;commesse per Alenia Aeronautica Spa sia per servizi di ingegneria industriale sia per lo sviluppo di modelli numerici di analisi strutturale.&nbsp; Nel dettaglio, Redam utilizzer\u00e0 il software \u201cGo-Mesh\u201d, prodotto dall\u2019azienda AAPS con sede madre ad Avellino e filiali a Roma e Monza, per l\u2019interfacciamento con i suoi software di settore. <\/p>\n<p style=\"TEXT-ALIGN: justify\">In pratica, il prodotto, concepito dall\u2019intelligence dell\u2019azienda irpina attiva da oltre quattordici anni nel settore dell\u2019Information &amp; Communication Technology, servir\u00e0 per la progettazione di parti meccaniche di aeroplani . Entusiasta del risultato raggiunto <strong>Angelo Galietta<\/strong>, manager AAPS divisione engineering. \u201cIl nostro software \u2013 dice \u2013 rappresenta un investimento conveniente per le imprese che credono nell\u2019innovazione tecnologica come strumento di competitivit\u00e0 reale e tangibile\u201d. \u201cEsso \u00e8 stato proprio pensato \u2013 conclude Galietta &#8211; per accelerare l\u2019introduzione di prodotti di qualit\u00e0 sul mercato a costi inferiori, ottimizzando con un approccio totalmente innovativo i processi progettuali e produttivi\u201d. L\u2019importante collaborazione instaurata testimonia l\u2019interesse crescente per l\u2019innovazione tecnologica che contraddistingue \u201cGo-Mesh\u201d i cui benefits stanno destando e polarizzando sempre pi\u00f9 l\u2019attenzione nel mercato specifico della simulazione numerica.<\/p>\n<p style=\"TEXT-ALIGN: justify\">Tra gli strumenti che vanno sempre pi\u00f9 assumendo importanza, sia per la grande impresa sia per le pmi, sono infatti da annoverare quelli definiti come simulazione numerica che consentono l\u2019analisi e la valutazione di processi complessi, riducendo senz\u2019altro le difficolt\u00e0 relative alla soluzione delle problematiche connesse.&nbsp; La possibilit\u00e0 di testare un prodotto per mezzo di tecniche di simulazione numerica, possibilmente evitando&nbsp; la costruzione di un prototipo, ha mostrato di essere estremamente efficace nella riduzione dei costi di progetto ed \u00e8 diventata uno standard per tutte quelle applicazioni in cui \u00e8 necessaria affidabilit\u00e0 e cura costruttiva.&nbsp; In quest\u2019ottica \u00e8 stato concepito il software \u201cGo-Mesh\u201d che viene utilizzato sia in fase di costruzione dei modelli geometrici che nella fase di pre-processing del flusso di analisi dei componenti. Il target \u00e8 l\u2019industria e la platea della professione specialistica. Si rivolge alle aziende che lavorano su disegni industriali di parti meccaniche quali case automobilistiche, imprese aeronautiche e di stampaggio. Ma il prodotto ha caratteristiche pi\u00f9 generalizzabili ed aspetti di impiego ben pi\u00f9 ampi. L\u2019innovazione messa in piedi presenta un forte ritorno d\u2019investimento perch\u00e8 velocizza la capacit\u00e0 di progettazione industriale. Nella realizzazione di un prototipo, il progettista d\u2019impresa potr\u00e0, infatti, lavorare, nel processo iterativo, partendo dalla griglia di calcolo (mesh) gi\u00e0 costruita la quale si adatter\u00e0 perfettamente alla parte grafica senza dover ripartire dallo step primario relativo al disegno industriale. Il tutto a beneficio di un minor sforzo e di un massimo risultato conseguito sul piano applicativo con un notevole risparmio anche economico, riducendo, nella realizzazione finale, lo sviluppo di prototipi che, grazie ad una meshatura intelligente, potranno rispecchiare subito e fedelmente&nbsp; la fisionomia dell\u2019idea progettuale di partenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019azienda irpina lancia il software  \u201cGo-Mesh\u201d ed annuncia un accordo commerciale con Redam, importante societ\u00e0 operante nel campo della meccanica applicata  partner di Alenia.  Il prodotto, dall\u2019alto contenuto innovativo, servir\u00e0 per la progettazione di parti meccaniche di aeroplani.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[21483,21484,14300,21485],"class_list":["post-11555","post","type-post","status-publish","format-standard","hentry","category-software","tag-go-mesh","tag-progettazione-industriale","tag-prototipi","tag-simulazione-numerica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L\u2019azienda irpina lancia il software \u201cGo-Mesh\u201d ed annuncia un accordo commerciale con Redam, importante societ\u00e0 operante nel campo della meccanica applicata partner di Alenia. Il prodotto, dall\u2019alto contenuto innovativo, servir\u00e0 per la progettazione di parti meccaniche di aeroplani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-11T09:37:13+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche\",\"datePublished\":\"2008-06-11T09:37:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/\"},\"wordCount\":532,\"commentCount\":0,\"keywords\":[\"Go-Mesh\",\"progettazione industriale\",\"prototipi\",\"simulazione numerica\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/\",\"name\":\"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2008-06-11T09:37:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/","og_locale":"it_IT","og_type":"article","og_title":"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing","og_description":"L\u2019azienda irpina lancia il software \u201cGo-Mesh\u201d ed annuncia un accordo commerciale con Redam, importante societ\u00e0 operante nel campo della meccanica applicata partner di Alenia. Il prodotto, dall\u2019alto contenuto innovativo, servir\u00e0 per la progettazione di parti meccaniche di aeroplani.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/","og_site_name":"Article Marketing","article_published_time":"2008-06-11T09:37:13+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche","datePublished":"2008-06-11T09:37:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/"},"wordCount":532,"commentCount":0,"keywords":["Go-Mesh","progettazione industriale","prototipi","simulazione numerica"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/","name":"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2008-06-11T09:37:13+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/accordo-tra-aaps-informatica-e-redam-per-la-modellazione-di-strutture-aeronautiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Accordo tra Aaps informatica e Redam per la modellazione di strutture aeronautiche"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=11555"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/11555\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=11555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=11555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=11555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}