{"id":12023,"date":"2010-12-07T16:56:53","date_gmt":"2010-12-07T15:56:53","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/"},"modified":"2010-12-07T16:56:53","modified_gmt":"2010-12-07T15:56:53","slug":"lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/","title":{"rendered":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso"},"content":{"rendered":"<p>Si &egrave; svolto il 26 e 27 novembre a Caserta, presso il Crowne Plaza, il congresso scientifico sullo&nbsp;stato dell&rsquo;arte in allergologia, che ha visto la prestigiosa collaborazione di numerosi docenti&nbsp;dell&rsquo;Universit&agrave; Cattolica di Roma e del presidente della<strong> Societ&agrave; Italiana Specialisti Allergologi&nbsp;Italiani.<\/strong><br \/>Delle conclusioni e dei progetti ne parla Donato Leonetti, direttore del corso, specialista in&nbsp;allergologia e presidente regionale <strong>AISAI (Associazione Italiana Specialisti Allergologi e&nbsp;Immunologi clinici<\/strong>: &laquo;<strong>L&rsquo;inquinamento ambientale<\/strong> &ndash; spiega &ndash; non solo dell&rsquo;aria, ma anche dell&rsquo;acqua&nbsp;ha determinato modificazioni ambientali che influenzano il nostro patrimonio genetico con&nbsp;ripercussioni sulle generazioni future, quindi v&agrave; rivisto il nostro rapporto con la terra che dovr&agrave;&nbsp;basarsi su un maggior rispetto&raquo;.<br \/>Numerosi e recenti studi confermano che le malattie allergiche hanno una prevalenza del 20-<br \/>30% nei bambini, prevedendo un incremento nei prossimi anni. &laquo;Esse sono attualmente sotto-&nbsp;diagnosticate e non correttamente curate, &#8211; continua &#8211; nonostante i recenti progressi nel campo della&nbsp;ricerca sia della diagnostica che della farmaceutica ne consentano un adeguato controllo. Oggi &egrave;&nbsp;possibile, attraverso una diagnosi precoce, prevenire le complicanze delle allergopatie e determinare&nbsp;una scomparsa della sintomatologia migliorando la qualit&agrave; della vita del paziente. Inoltre &egrave; possibile&nbsp;modificare la storia naturale delle malattie allergiche con trattamenti immunoterapici&raquo;.<br \/>Il corso ha integrato le conoscenze di vari specialisti: pediatri, medici di famiglia, specialisti&nbsp;pneumologi ed allergologi al fine di determinare il pi&ugrave; concreto sinergismo tra i diversi medici&nbsp;che curano i pazienti allergici.<br \/>&nbsp;<br \/>Inoltre il coinvolgimento delle associazioni, dei pazienti e delle&nbsp;associazioni che operano nel sociale ha permesso di evidenziare tematiche ambientali che&nbsp;necessitano di proposte concrete come la realizzazione di un registro tumori redatto dagli Ordini&nbsp;dei Medici, che determiner&agrave; una migliore presa di coscienza anche della politica al problema&nbsp;emergenza allergie e malattie ambientali che rappresentano una patologia sociale.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[70],"tags":[22312,4286,22313,22314],"class_list":["post-12023","post","type-post","status-publish","format-standard","hentry","category-medicina","tag-allergologia","tag-congresso","tag-immunologia-clinica","tag-registro-tumori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-07T15:56:53+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso\",\"datePublished\":\"2010-12-07T15:56:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/\"},\"wordCount\":349,\"commentCount\":0,\"keywords\":[\"allergologia\",\"congresso\",\"immunologia clinica\",\"registro tumori\"],\"articleSection\":[\"Medicina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/\",\"name\":\"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-12-07T15:56:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/","og_locale":"it_IT","og_type":"article","og_title":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing","og_description":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/","og_site_name":"Article Marketing","article_published_time":"2010-12-07T15:56:53+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso","datePublished":"2010-12-07T15:56:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/"},"wordCount":349,"commentCount":0,"keywords":["allergologia","congresso","immunologia clinica","registro tumori"],"articleSection":["Medicina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/","name":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-12-07T15:56:53+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/lo-stato-della-arte-in-allergologia-ed-immunologia-clinica-conclusioni-del-quarto-congresso-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Lo stato della arte in allergologia ed immunologia clinica, conclusioni del quarto congresso"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/12023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=12023"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/12023\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=12023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=12023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=12023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}