{"id":12977,"date":"2011-02-19T20:31:17","date_gmt":"2011-02-19T19:31:17","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/curiosit%c3%a0-e-storia-di-sondrio\/"},"modified":"2011-02-19T20:31:17","modified_gmt":"2011-02-19T19:31:17","slug":"curiosit%c3%a0-e-storia-di-sondrio","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/","title":{"rendered":"Curiosit\u00e0 e storia di Sondrio"},"content":{"rendered":"<p><strong>Sondrio e l&#8217;Albero della Libert&agrave;<\/strong><br \/>\nCon il trattato di Teglio, siglato agli inizi del Cinquecento, la citt&agrave; passa sotto il governo dei Grigioni dei quali diventa un importante centro di potere, ma, ben presto, la differenza di religione tra Grigioni protestanti e valtellinesi cattolici si acuisce sempre pi&ugrave; e sfocia in una vera e propria rivolta, il cui pretesto &egrave; rappresentato dall&#8217;uccisione dell&#8217;arciprete di <a href=\"http:\/\/www.zerodelta.net\/sondrio.php\">Sondrio<\/a>, Nicola Rusca nel 1620. L&#8217;episodio &egrave; stato definito &#8220;il sacro macello&#8221; poich&eacute; cost&ograve; la vita a oltre 400 tra funzionari retici e riformatori protestanti. In quegli anni, la citt&agrave; assunse un governo autonomo che resister&agrave; in carica fino al 1639, anno in cui il Trattato di Milano sancisce il ritorno della sovranit&agrave; grigione sull&#8217;intera valle. Per ben oltre un secolo le cose si mantengono quasi inalterate, ma alla fine del Settecento cominciano a diffondersi in tutto il Nord Italia le idee di fratellanza, uguaglianza e, soprattutto, libert&agrave; portate dalla rivoluzione francese. Al termine di un&#8217;assemblea tenutasi nella chiesa dei Santi Gervasio e Protasio, il popolo di Sondrio scende in piazza e pianta l&#8217;albero della Libert&agrave;, simbolo concreto di ribellione al potere dei Grigioni. Poco dopo, la Valtellina viene annessa alla Repubblica Cisalpina ed inserita nel Dipartimento dell&#8217;Adda e dell&#8217;Oglio.<br \/>\n<strong>Sondrio e la Statale dello Stelvio<\/strong><br \/>\nEra il 1808 quando per la prima volta si pens&ograve; alla strada dello Stelvio come al sistema pi&ugrave; rapido per mettere in comunicazione la Lombardia con il Tirolo e il resto del Regno di Baviera. Passarono, per&ograve;, oltre 10 anni prima che il governo di Vienna incaricasse ufficialmente l&#8217;ingegner Carlo Donegani di mettersi al lavoro sul progetto dell&#8217;opera. Dopo poco meno di 63 mesi di lavoro, nel 1825, la strada venne ufficialmente inaugurata ed aperta, dapprima al servizio postale, poi a un vero e proprio servizio di &#8220;diligenze&#8221; che mettevano in comunicazione Milano con la Germania. La nuova via di comunicazione rianim&ograve; traffici e commerci permettendo ai viaggiatori il transito anche durante l&#8217;inverno grazie a uomini chiamati &#8220;Rotter&#8221; che pulivano la strada con l&#8217;aiuto di pale e spazzaneve trainati da cavalli.<br \/>\nNel 1876, la strada divenne tristemente famosa a causa dell&#8217;omicidio di Madeleine Tourville da parte del marito Henry, avvenuto sopra il rifugio della Rocca Bianca. Un pastore fu testimone e denunci&ograve; l&#8217;uomo alla polizia locale, ma durante il processo si scopr&igrave; che Madeleine era la terza moglie uccisa da Henry per questioni di denaro.<br \/>\n<strong>Sondrio, la tragedia delle frane<\/strong><br \/>\nLa frana di Tresenda<br \/> Era domenica il 22 maggio 1983: alle 12,30 a causa delle forti piogge di quei giorni, una parte dei terreni coltivati a vigneto franarono a valle; una frana di fango che no perdona, che scuote il paese, la regione e l&#8217;Italia intera: in quella drammatica domenica si contarono 18 morti nella piccola frazione di Tresenda.<br \/>\nLa frana della Val di Pola<br \/> Il 17 luglio del 1987 su tutta la zona della Val di Pola cadono oltre 30 centimetri di pioggia, quasi un quarto di tutta l&#8217;acqua che precipita solitamente sull&#8217;intera valle nel corso di un anno. Con il passare dei giorni, le condizioni sembrano lentamente migliorare, ma il mattino del 28 luglio, un&#8217;immensa frana di quaranta milioni di metri cubi di terra e rocce si stacca dalle cime del Redasco abbattendosi da un&#8217;altezza di circa duecento metri sui comuni di Morignone, Sant&#8217;Antonio, Aquilone, Foliano e Castellaccio San Martino e ricoprendo completamente l&#8217;intero fondo della valle. Alla fine le vittime della spaventosa catastrofe i morti furono 53 e 1500 le persone che restarono senza casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vicende di Sondrio e dell&#8217;intera Valtellina sono da sempre state tumultuose e segnate da lotte e annessioni a regni diversi. Conoscere la montagne \u00e8 fondamentale per capire la storia e la cultura della zona.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[23],"tags":[9360,170,23303],"class_list":["post-12977","post","type-post","status-publish","format-standard","hentry","category-misteri","tag-sondrio","tag-storia","tag-valtellina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curiosit\u00e0 e storia di Sondrio - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit\u00e0-e-storia-di-sondrio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curiosit\u00e0 e storia di Sondrio - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Le vicende di Sondrio e dell&#039;intera Valtellina sono da sempre state tumultuose e segnate da lotte e annessioni a regni diversi. Conoscere la montagne \u00e8 fondamentale per capire la storia e la cultura della zona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit\u00e0-e-storia-di-sondrio\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-19T19:31:17+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Curiosit\u00e0 e storia di Sondrio\",\"datePublished\":\"2011-02-19T19:31:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/\"},\"wordCount\":581,\"commentCount\":0,\"keywords\":[\"sondrio\",\"storia\",\"Valtellina\"],\"articleSection\":[\"Misteri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/\",\"name\":\"Curiosit\u00e0 e storia di Sondrio - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-02-19T19:31:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/misteri\\\/curiosit%c3%a0-e-storia-di-sondrio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curiosit\u00e0 e storia di Sondrio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curiosit\u00e0 e storia di Sondrio - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit\u00e0-e-storia-di-sondrio\/","og_locale":"it_IT","og_type":"article","og_title":"Curiosit\u00e0 e storia di Sondrio - Article Marketing","og_description":"Le vicende di Sondrio e dell'intera Valtellina sono da sempre state tumultuose e segnate da lotte e annessioni a regni diversi. Conoscere la montagne \u00e8 fondamentale per capire la storia e la cultura della zona.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit\u00e0-e-storia-di-sondrio\/","og_site_name":"Article Marketing","article_published_time":"2011-02-19T19:31:17+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Curiosit\u00e0 e storia di Sondrio","datePublished":"2011-02-19T19:31:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/"},"wordCount":581,"commentCount":0,"keywords":["sondrio","storia","Valtellina"],"articleSection":["Misteri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/","name":"Curiosit\u00e0 e storia di Sondrio - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-02-19T19:31:17+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/misteri\/curiosit%c3%a0-e-storia-di-sondrio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Curiosit\u00e0 e storia di Sondrio"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/12977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=12977"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/12977\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=12977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=12977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=12977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}