{"id":13358,"date":"2011-03-01T16:46:29","date_gmt":"2011-03-01T15:46:29","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/"},"modified":"2011-03-01T16:46:29","modified_gmt":"2011-03-01T15:46:29","slug":"nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/","title":{"rendered":"Un nuovo modo per proteggersi dai raggi UV"},"content":{"rendered":"<p>Il <strong>sole<\/strong> &egrave; un valido alleato del nostro benessere e della nostra <strong>bellezza<\/strong>, tuttavia una prolungata esposizione ai raggi UV potrebbe rappresentare un serio pericolo per la nostra salute. Il desiderio di tintarella induce ad esporsi al sole e\/o a lampade abbronzanti, rendendo sempre pi&ugrave; frequenti le reazioni di <strong>fotosensibilizzazione<\/strong>, ossia una reattivit&agrave; esagerata a piccole dosi di radiazioni dell&#8217;ultravioletto o del visibile. Ogni arrossamento della pelle indica che c&rsquo;&egrave; stato un danneggiamento: chi ha un colorito chiaro, ma in particolar modo i bambini, gli adolescenti e gli anziani, richiedono una protezione pi&ugrave; elevata.<br \/>Oggi il &ldquo;problema sole&rdquo; pu&ograve; essere affrontato in un modo alternativo e innovativo rispetto ai protettori solari. L&rsquo;approccio differente &egrave; offerto da <strong><a href=\"http:\/\/www.proteksol.it\" target=\"_blank\">Coolibar<\/a><\/strong>, azienda leader che dal 2001 &egrave; tra le marche pi&ugrave; note nel campo dell&rsquo; <strong>abbigliamento a protezione solare<\/strong>. Coolibar sviluppa e produce esclusivamente abbigliamento cappelli ed accessori con protezione solare massima <strong>UPF 50+<\/strong> (blocco del <strong>98% dei raggi UV<\/strong>) garantendo protezione e comfort durante l&rsquo;intera vita del prodotto. Tutta la gamma dei prodotti Coolibar mira ad offrire indumenti a protezione UV che coprano quanta pi&ugrave; pelle possibile, senza rinunciare a freschezza e comodit&agrave;. Un obiettivo reso possibile grazie allo sviluppo dei pi&ugrave; affidabili tessuti a protezione solare disponibili in commercio: i tessuti <strong>SUNTECT<\/strong>&reg;.<br \/>Riconosciuti dall&rsquo; <strong>American Academy of Dermatology<\/strong>, questi offrono una combinazione unica di peso, colore, elasticit&agrave;, taglio, traspirabilit&agrave; e protezione, che consente di godere in tutta sicurezza delle attivit&agrave; all&rsquo;aria aperta. Inoltre rappresentano un valido supporto alle terapie dello specialista: ogni fibra, infatti, contiene milioni di particelle di <strong>ossido di zinco<\/strong>, un composto minerale naturale utilizzato nei migliori filtri solari ed usato tradizionalmente come lozione topica per proteggere e trattare la pelle in caso di eruzioni cutanee e scottature. L&rsquo;ossido di zinco fornisce un&rsquo;eccellente protezione, oltre a contenere antiossidanti che hanno l&rsquo;effetto di stimolare una maggiore produzione di collagene per il benessere della pelle. I <strong>test<\/strong> sui capi Coolibar sono svolti da laboratori indipendenti. Dopo un test di trasmissione UV (che misura sia i raggi UVA che UVB), il capo viene sottoposto a <strong>40 cicli di lavaggio ed esposto a 100 dosi di luce solare simulata<\/strong>, per poi ripetere un secondo test di trasmissione UV. Dopo essere stato testato, ogni prodotto viene contraddistinto da un <strong>indice di protezione solare<\/strong>, oltre che da un codice che ne consente il controllo qualit&agrave; e la tracciabilit&agrave;. Il risultato &egrave; rappresentato da capi e accessori che offrono un meraviglioso <strong>comfort<\/strong>, allontanando dalla pelle l&rsquo;umidit&agrave; e la sudorazione, mantenendo freschi e protetti chi li indossa e donando un look naturale e perfetto per ogni occasione. La qualit&agrave; dei prodotti Coolibar &egrave; garantita da uno staff medico che collabora con l&rsquo;azienda offrendo la propria consulenza sui danni causati dai raggi solari e sulle tecniche scientifiche per individuare, prevenire e curare il <strong>cancro della pelle<\/strong> e altre patologie mediche, come ad esempio il lupus, legate ad una non corretta esposizione solare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non proteggersi dai raggi UV dannosi pu\u00f2 portare danni irreversibili alla pelle. Esperimenti scientifici hanno provato che l&#8217;esposizione prolungata al sole senza protezione aumenta la probabilit\u00e0 di sviluppare il cancro alla pelle. Oggi esistono in commercio prodotti innovativi per la protezione della pelle e la prevenzione del melanoma.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[265],"tags":[23536,23541,23542,23539,23535,23543,23546,23545,23540,23538,23537,23544,13689],"class_list":["post-13358","post","type-post","status-publish","format-standard","hentry","category-salute-e-benessere","tag-abbigliamento-a-protezione-uv","tag-abbigliamento-uomo-donna-bambino","tag-benessere-della-pelle","tag-cancro-della-pelle","tag-fotosensibilizzazione","tag-invecchiamento-pelle","tag-lampade-abbronzanti","tag-lampade-solari","tag-lupus","tag-melanoma","tag-protezione-solare-anti-uv","tag-radiazioni-uv","tag-sole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuovo modo per proteggersi dai raggi UV - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuovo modo per proteggersi dai raggi UV - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Non proteggersi dai raggi UV dannosi pu\u00f2 portare danni irreversibili alla pelle. Esperimenti scientifici hanno provato che l&#039;esposizione prolungata al sole senza protezione aumenta la probabilit\u00e0 di sviluppare il cancro alla pelle. Oggi esistono in commercio prodotti innovativi per la protezione della pelle e la prevenzione del melanoma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-01T15:46:29+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Un nuovo modo per proteggersi dai raggi UV\",\"datePublished\":\"2011-03-01T15:46:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/\"},\"wordCount\":525,\"commentCount\":0,\"keywords\":[\"abbigliamento a protezione uv\",\"abbigliamento uomo donna bambino\",\"benessere della pelle\",\"cancro della pelle\",\"fotosensibilizzazione\",\"invecchiamento pelle\",\"lampade abbronzanti\",\"lampade solari\",\"lupus\",\"melanoma\",\"protezione solare anti uv\",\"radiazioni uv\",\"sole\"],\"articleSection\":[\"Salute e benessere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/\",\"name\":\"Un nuovo modo per proteggersi dai raggi UV - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-01T15:46:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuovo modo per proteggersi dai raggi UV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuovo modo per proteggersi dai raggi UV - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/","og_locale":"it_IT","og_type":"article","og_title":"Un nuovo modo per proteggersi dai raggi UV - Article Marketing","og_description":"Non proteggersi dai raggi UV dannosi pu\u00f2 portare danni irreversibili alla pelle. Esperimenti scientifici hanno provato che l'esposizione prolungata al sole senza protezione aumenta la probabilit\u00e0 di sviluppare il cancro alla pelle. Oggi esistono in commercio prodotti innovativi per la protezione della pelle e la prevenzione del melanoma.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/","og_site_name":"Article Marketing","article_published_time":"2011-03-01T15:46:29+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Un nuovo modo per proteggersi dai raggi UV","datePublished":"2011-03-01T15:46:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/"},"wordCount":525,"commentCount":0,"keywords":["abbigliamento a protezione uv","abbigliamento uomo donna bambino","benessere della pelle","cancro della pelle","fotosensibilizzazione","invecchiamento pelle","lampade abbronzanti","lampade solari","lupus","melanoma","protezione solare anti uv","radiazioni uv","sole"],"articleSection":["Salute e benessere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/","name":"Un nuovo modo per proteggersi dai raggi UV - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-01T15:46:29+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/nuovo-modo-per-proteggersi-dai-nocivi-raggi-uv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Un nuovo modo per proteggersi dai raggi UV"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=13358"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13358\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=13358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=13358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=13358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}