{"id":13517,"date":"2011-03-04T10:08:07","date_gmt":"2011-03-04T09:08:07","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/mangia-bene-e-vivi-a-lungo\/"},"modified":"2011-03-04T10:08:07","modified_gmt":"2011-03-04T09:08:07","slug":"mangia-bene-e-vivi-a-lungo","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/","title":{"rendered":"Mangia correttamente, bevi correttamente e vivi a lungo"},"content":{"rendered":"<p>Gli esseri umani nella loro storia hanno sempre cercato di scoprire quale fosse l&#8217;elisir di lunga vita. Hanno cercato tra i miti, tra i segreti della storia, attraverso il lavoro di maghi, attraverso gli studi degli alchimisti, fino alle ricerca dulla chimica del corpo umano.<br \/>Ma nulla non hanno trovato la formula magica per allungare la durata della vita, senza sapere che la risposta era ed &egrave; tuttora sotto i propri occhi. Per vivere a lungo, in forma e in benessere bisogna saper mangiare correttamente.<br \/>Sembra lo spot di un <a href=\"http:\/\/www.ilnutrizionista.eu\" title=\"nutrizionista\">nutrizionista<\/a>, ma &egrave; solo una semplice verit&agrave;.<br \/>Mangiare correttamente secondo le regole della natura umana e non secondo le regole della pubblicit&agrave;, delle aziende o peggio ancora delle case farmaceutiche.<br \/>Il corpo umano &egrave; un sitema favoloso e straordinario che necessita di carburante per creare energia, per guarire e per rinnovarsi. Se il carburante che viene inserito nel copro umano &egrave; di pessima qualit&agrave;, esso non pu&ograve; che funzionare male e nel tempo rompersi.<br \/>Come un&#8217;auto di formula1 necessita del miglior carburante possibile per ottenere prestazioni eccezionali, anche il corpo umano ha bisogno e merita il meglio per quello che riguarda il cibo.<br \/>Il meglio non significa il cibo meglio pubblicizzato o il cibo pi&ugrave; consigliato, il meglio significa il cibo che, per sua natura e per le esigenze del corpo umano si presta maggiormente all&#8217;obiettivo di nutrire. Infatti basta parlare di diete, regimi alimentari controllati, ecc. bisogna parlare di alimentazione umana.<br \/>Ad esempio:<\/p>\n<ul>\n<\/p>\n<li>Il corpo umano &egrave; fatto dell&#8217;80-85% di acqua e predilige cibi ricchi d&#8217;acqua. Tutti i pasti che sono fatti solo con piatti a basso contenuto di acqua non nutrono quanto potrebbero. I cibi che nutrono di pi&ugrave; il corpo sono frutta e verdure cotte. <\/li>\n<li>Il corpo umano digerisce in un ambiente o acido o basico. Mescolare un cibo che si digerisce in ambiente acido (proteine) e un cibo che si digerisce in un ambiente basico (carboidrati e zuccheri) crea un ambiente poco efficace perch&egrave; i succhi gastrici acidi e quelli basici tendono a neutralizzarsi. Aumentano conseguentemente i tempi di digestione, i cibi fermentano e marciscono nello stomaco, e in definitiva il corpo non viene nutrito quando necessita.<\/li>\n<li>La frutta va mangiata lontano dai pasti. L&#8217;abitudine comune &egrave; quella di mangiare la frutta dopo un lauto pasto. Non ce nulla di pi&ugrave; sbagliato. La frutta viene digerita nella parte bassa dello stomaco. Quindi quando viene ingerita dopo un pasto, nell&#8217;apparato digerente la frutta trova ostacoli e deve aspettare che glia ltri cibi vengono digeriti prima di poter essere digerita anch&#8217;essa. Qusto per&ograve; provoca un abbattimento dell&#8217;assimilazione delle sostanze nutritive della frutta stessa e un aumento enorme di sostanze che fanno ingrassare e creano molte tossine nel corpo che andranno smaltite. Invece mangiando la frutta a stomaco vuoto viene digerita completamente in meno di un&#8217;ora e si assimilano tutte le sostanze nutritive<\/li>\n<p> \n<\/ul>\n<p>Questi sono solo 2 esempio di piccole regole che servono per migliorare l&#8217;alimentazione umana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mangiare correttamente secondo le regole della natura umana e non secondo le regole della pubblicit\u00e0, delle aziende o peggio ancora delle case farmaceutiche.<br \/>Il corpo umano \u00e8 un sitema favoloso e straordinario che necessita di carburante per creare energia, per guarire e per rinnovarsi. Se il carburante che viene inserito nel copro umano \u00e8 di pessima qualit\u00e0, esso non pu\u00f2 che funzionare male e nel tempo rompersi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[162],"tags":[23713],"class_list":["post-13517","post","type-post","status-publish","format-standard","hentry","category-dieta-e-nutrizione","tag-nutrizionista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Mangiare correttamente secondo le regole della natura umana e non secondo le regole della pubblicit\u00e0, delle aziende o peggio ancora delle case farmaceutiche.Il corpo umano \u00e8 un sitema favoloso e straordinario che necessita di carburante per creare energia, per guarire e per rinnovarsi. Se il carburante che viene inserito nel copro umano \u00e8 di pessima qualit\u00e0, esso non pu\u00f2 che funzionare male e nel tempo rompersi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-04T09:08:07+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Mangia correttamente, bevi correttamente e vivi a lungo\",\"datePublished\":\"2011-03-04T09:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/\"},\"wordCount\":505,\"commentCount\":0,\"keywords\":[\"nutrizionista\"],\"articleSection\":[\"Dieta e Nutrizione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/\",\"name\":\"Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-04T09:08:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/mangia-bene-e-vivi-a-lungo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mangia correttamente, bevi correttamente e vivi a lungo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/","og_locale":"it_IT","og_type":"article","og_title":"Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing","og_description":"Mangiare correttamente secondo le regole della natura umana e non secondo le regole della pubblicit\u00e0, delle aziende o peggio ancora delle case farmaceutiche.Il corpo umano \u00e8 un sitema favoloso e straordinario che necessita di carburante per creare energia, per guarire e per rinnovarsi. Se il carburante che viene inserito nel copro umano \u00e8 di pessima qualit\u00e0, esso non pu\u00f2 che funzionare male e nel tempo rompersi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/","og_site_name":"Article Marketing","article_published_time":"2011-03-04T09:08:07+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Mangia correttamente, bevi correttamente e vivi a lungo","datePublished":"2011-03-04T09:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/"},"wordCount":505,"commentCount":0,"keywords":["nutrizionista"],"articleSection":["Dieta e Nutrizione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/","name":"Mangia correttamente, bevi correttamente e vivi a lungo - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-04T09:08:07+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/mangia-bene-e-vivi-a-lungo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Mangia correttamente, bevi correttamente e vivi a lungo"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=13517"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13517\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=13517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=13517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=13517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}