{"id":13899,"date":"2011-03-14T16:10:36","date_gmt":"2011-03-14T15:10:36","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/private-banking-per-tutti-2\/"},"modified":"2011-03-14T16:10:36","modified_gmt":"2011-03-14T15:10:36","slug":"private-banking-per-tutti-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/","title":{"rendered":"Private banking per tutti"},"content":{"rendered":"<p><strong style=\"mso-bidi-font-weight: normal;\">La notizia in breve<\/strong> &ndash; Vincenzo Montanaro, fondatore di ThinkYou, studio professionale specializzato nell&rsquo;offerta di <strong>servizi per l&#8217;investimento <\/strong><strong style=\"mso-bidi-font-weight: normal;\">e consulenza finanziaria indipendente<\/strong>, lancia un servizio per <strong>consentire anche ai<\/strong> <strong>piccoli risparmiatori<\/strong> di <strong>accedere al mondo della finanza<\/strong>. Una risposta alla crisi e un sostegno alle famiglie in difficolt&agrave; che desiderano tutelare il proprio patrimonio e liberarsi dal monopolio bancario.<br \/>\n La crisi non molla la presa e continua a stringere nella sua morsa aziende e famiglie. Una situazione difficile che ha spinto Vincenzo Montanaro, fondatore di ThinkYou, studio professionale specializzato nell&rsquo;offerta di <strong>servizi per l&#8217;investimento <\/strong><strong style=\"mso-bidi-font-weight: normal;\">e consulenza finanziaria indipendente<\/strong>, a promuovere un servizio per consentire anche ai <strong>piccoli risparmiatori<\/strong> di <strong>accedere al mondo della finanza<\/strong>.<br \/>\nSpecializzato nella gestione di grandi capitali e importanti patrimoni, l&rsquo;imprenditore bolognese ha deciso di mettere il proprio know-how al servizio di tutti coloro che desiderano <strong>difendere i propri risparmi o integrare le proprie rendite<\/strong>.<br \/>\n&ldquo;<em style=\"mso-bidi-font-style: normal;\">I risultati ottenuti fino ad oggi <\/em>&ndash; spiega Montanaro &ndash;<em style=\"mso-bidi-font-style: normal;\"> mi hanno convinto a compiere un gesto concreto verso le tante famiglie colpite dalla crisi e liberarle dal giogo bancario che limita le proposte a soluzioni solo in minima parte redditizie<\/em>&rdquo;.<br \/>\nAttraverso una consulenza personalizzata a cifra calmierata (meno di 100 euro) Vincenzo Montanaro propone cos&igrave; <strong>un&rsquo;analisi approfondita della situazione finanziaria delle persone<\/strong> che a lui si rivolgono, indicando punti critici e situazioni sconvenienti. Analogamente, <strong>prende in esame la condizione patrimoniale delle famiglie<\/strong>, per consigliare come tutelare i propri beni e far generare loro rendite comode in questi tempi non certo floridi.<br \/>\n&ldquo;<em style=\"mso-bidi-font-style: normal;\">Le banche propongono prodotti, io offro consigli<\/em> &ndash; afferma Montanaro &ndash; <em style=\"mso-bidi-font-style: normal;\">affinch&eacute; il pubblico scelga liberamente. Come consulente indipendente sono libero da ordini di scuderia e incentivi alla vendita. Mi interessa aiutare le persone e dimostrare che <strong>esiste anche una finanza buona<\/strong> capace, non solo quella che specula con le conseguenze a cui tutti abbiamo assistito<\/em>&rdquo;.<\/p>\n<p>Una chiave di lettura indipendente in attesa della ripresa e una consulenza a 360&deg; per capire la propria situazione, con la possibilit&agrave; di integrare il proprio reddito attraverso una libera scelta. &ldquo;<strong><em style=\"mso-bidi-font-style: normal;\">Io mi limito a mostrare la situazione individuale<\/em><\/strong> &ndash; conclude Montanaro &ndash; <em style=\"mso-bidi-font-style: normal;\">e le opportunit&agrave; presenti, ma <strong>la scelta &egrave; sempre del cliente<\/strong> che pu&ograve; anche continuare a operare tramite il proprio istituto bancario, ma <strong>con uno sguardo pi&ugrave; ampio<\/strong> sul panorama finanziario internazionale e le proprie possibilit&agrave;<\/em>&rdquo;. <\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">ThinkYou<\/strong><br \/> Strada Maggiore, 32<br \/> 40125 Bologna<br \/>\nTel. \/ Fax +39 051 264841<br \/> <a href=\"mailto:info@thinkyou.it\">info@thinkyou.it<\/a> www.thinkyou.it<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">Ufficio stampa ThinkYou <\/strong><br \/>\nMatteo Barboni &#8211; 3496172546<br \/>\nCommunication Manager &amp; P.R.<br \/> press@thinkyou.it matteo.barboni@libero.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nasce a Bologna la prima formula innovativa per l\u2019accesso al mondo della finanza anche per piccoli risparmiatori. Una risposta di un affermato consulente bolognese alla richiesta delle famiglie nel perdurare della difficile contingenza economica<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[16549,2260,1351],"class_list":["post-13899","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-consulente","tag-finanza","tag-risparmio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Private banking per tutti - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Private banking per tutti - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nasce a Bologna la prima formula innovativa per l\u2019accesso al mondo della finanza anche per piccoli risparmiatori. Una risposta di un affermato consulente bolognese alla richiesta delle famiglie nel perdurare della difficile contingenza economica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-14T15:10:36+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Private banking per tutti\",\"datePublished\":\"2011-03-14T15:10:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/\"},\"wordCount\":440,\"commentCount\":0,\"keywords\":[\"consulente\",\"finanza\",\"risparmio\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/\",\"name\":\"Private banking per tutti - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-14T15:10:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/private-banking-per-tutti-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Private banking per tutti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Private banking per tutti - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/","og_locale":"it_IT","og_type":"article","og_title":"Private banking per tutti - Article Marketing","og_description":"Nasce a Bologna la prima formula innovativa per l\u2019accesso al mondo della finanza anche per piccoli risparmiatori. Una risposta di un affermato consulente bolognese alla richiesta delle famiglie nel perdurare della difficile contingenza economica","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/","og_site_name":"Article Marketing","article_published_time":"2011-03-14T15:10:36+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Private banking per tutti","datePublished":"2011-03-14T15:10:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/"},"wordCount":440,"commentCount":0,"keywords":["consulente","finanza","risparmio"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/","name":"Private banking per tutti - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-14T15:10:36+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/private-banking-per-tutti-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Private banking per tutti"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=13899"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/13899\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=13899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=13899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=13899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}