{"id":14140,"date":"2011-03-22T09:33:17","date_gmt":"2011-03-22T08:33:17","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/"},"modified":"2011-03-22T09:33:17","modified_gmt":"2011-03-22T08:33:17","slug":"vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/","title":{"rendered":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta"},"content":{"rendered":"<p><strong>Riva di Franciacorta<\/strong>, progetto vitivinicolo nato dalla passione per la terra e il fascino per il vino della famiglia Riva, parteciper&agrave; con le sue esclusive bollicine a <a href=\"http:\/\/www.rivadifranciacorta.it\/riva-di-franciacorta-a-vinitaly-2011.html\" target=\"_blank\" title=\"Riva di Franciacorta a Vinitaly 2011\"><strong>Vinitaly 2011<\/strong><\/a>, la rassegna pi&ugrave; grande del mondo dedicata al vino e ai distillati. Giunto alla sua 45 edizione, Vinitaly ospiter&agrave;, <strong>dal 7 all&rsquo;11 aprile, le esclusive bollicine della Cantina Riva di Franciacorta presso lo stand D2, Padiglione Lombardia. <\/strong><br \/><strong>Fondata nel 1990, la Cantina sorge a Fantecolo di Provaglio d&rsquo;Iseo <\/strong>nel cuore della Franciacorta. La conoscenza delle diverse attitudini del suolo ha permesso ai tecnici qualificati di personalizzare la coltivazione delle differenti variet&agrave; di vite, che oggi occupano circa <strong>34 ettari tra i comuni di Passirano, Monterotondo e Paderno, nel cuore della Franciacorta. <\/strong><br \/>Vinitaly 2011 rappresenta l&rsquo;occasione perfetta scoprire l<strong>&rsquo;eleganza del Brut, la piacevolezza del Saten, le note fragranti del Ros&egrave; e la complessit&agrave; aromatica di Rivalto. <\/strong>I vini Riva di Franciacorta si riconoscono per la loro personalit&agrave;, la freschezza, la bassa gradazione alcolica, le tonalit&agrave; chiare, il vivace bouquet olfattivo e l&rsquo;acidit&agrave; sostenuta.<br \/>La gamma di vini proposta dalla cantina bresciana comprende anche due vini fermi: il r<strong>osso Longobardo, piacevole ed equilibrato, e il bianco Dioniso<\/strong>, fresco, sapido e fruttato. Ideali per valorizzare i momenti di festa, le bollicine Riva di Franciacorta hanno un&#8217;identit&agrave; strutturata, sapientemente costruita attraverso la personalizzazione delle metodologie di vinificazione.<br \/>La filosofia Riva di Franciacorta si concretizza attraverso scelte operate nel <strong>rispetto del territorio e della sua tipicit&agrave;.<\/strong> Sono lo studio per conoscere e approfondire la cultura del buon vino, la dedizione al lavoro e la precisione in ogni fase di trasformazione della materia prima a proporre vini sinceri, figli di questa terra straordinaria, ma capaci di distinguersi per il carattere forte e riconoscibile.<br \/>Il tratto distintivo dei<strong> vini Riva di Franciacorta<\/strong> &egrave; la loro qualit&agrave; gi&agrave; premiata a livello internazionale e scelta da Alitalia per rappresentare l&rsquo;eccellenza delle bollicine italiane nel mondo. Brut riva di Franciacorta &egrave; stato infatti inserito nella selezione di prodotti top, serviti sui voli business di Alitalia. Un servizio di bordo realizzato con il patrocinio del Ministero delle Politiche Agricole Alimentari e Forestali per promuovere nel mondo le eccellenze enogastronomiche italiane.<br \/>Riva di Franciacorta vi aspetta allo <strong>stand D2 del Padiglione Lombardia, zona Franciacorta,<\/strong> presso &#8211; Veronafiere &#8211; V.le del Lavoro, Verona Giorni d&rsquo;apertura: gioved&igrave; 7, venerd&igrave; 8, sabato 9, domenica 10, luned&igrave; 11 aprile 2011 Orari d&rsquo;apertura: gioved&igrave;\/domenica: continuato dalle 9.30 alle 18.30; luned&igrave;: continuato dalle 9.30 alle 16.30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dallo Stand D2 del Palaexpo Lombardia di Vinitaly, la Cantina Riva di Franciacorta completer\u00e0 con i suoi vini il patrimonio enologico in mostra a Verona.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[24331,24199,24330],"class_list":["post-14140","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-riva-di-franciacorta-a-vinitaly-2011","tag-vini-franciacorta","tag-vinitaly-2011"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dallo Stand D2 del Palaexpo Lombardia di Vinitaly, la Cantina Riva di Franciacorta completer\u00e0 con i suoi vini il patrimonio enologico in mostra a Verona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-22T08:33:17+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta\",\"datePublished\":\"2011-03-22T08:33:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/\"},\"wordCount\":434,\"commentCount\":0,\"keywords\":[\"Riva di Franciacorta a Vinitaly 2011\",\"Vini Franciacorta\",\"Vinitaly 2011\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/\",\"name\":\"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-22T08:33:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/","og_locale":"it_IT","og_type":"article","og_title":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing","og_description":"Dallo Stand D2 del Palaexpo Lombardia di Vinitaly, la Cantina Riva di Franciacorta completer\u00e0 con i suoi vini il patrimonio enologico in mostra a Verona.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/","og_site_name":"Article Marketing","article_published_time":"2011-03-22T08:33:17+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta","datePublished":"2011-03-22T08:33:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/"},"wordCount":434,"commentCount":0,"keywords":["Riva di Franciacorta a Vinitaly 2011","Vini Franciacorta","Vinitaly 2011"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/","name":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-22T08:33:17+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/vinitaly-2011-dal-padiglione-lombardia-riva-di-franciacorta-presenta-il-meglio-della-propria-produzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Vintaly 2011: il meglio delle bollicine Riva di Franciacorta"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14140"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14140\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}