{"id":14323,"date":"2011-03-30T14:11:45","date_gmt":"2011-03-30T12:11:45","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/"},"modified":"2011-03-30T14:11:45","modified_gmt":"2011-03-30T12:11:45","slug":"mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/","title":{"rendered":"MC-link sceglie AVM per \u201cPianeta Affari\u201d"},"content":{"rendered":"<p>MC-link, azienda che ha contribuito in modo significativo all&#8217;evoluzione della telematica Italiana, ha scelto i rivoluzionari prodotti AVM FRITZ!Box come piattaforma hardware su cui &egrave; imperniato il nuovo pacchetto di servizi di connettivit&agrave; Internet e telefonia dedicati a professionisti e alle piccole aziende. &ldquo;Pianeta Affari &egrave; un servizio integrato di telefonia e accesso ad Internet che consente ai professionisti e alla piccola impresa di avere un unico interlocutore per le proprie esigenze di comunicazione e di poter contare sulla qualit&agrave; riconosciuta dei servizi Internet di MC-link&rdquo;, afferma Stefano Massucci, Direttore Generale di MC-link. <br \/>L&rsquo;operatore di telecomunicazioni ha passato al vaglio i modem \/ router ed i telefoni dei pi&ugrave; noti vendor, riscontrando nei dispositivi AVM la piattaforma hardware pi&ugrave; adeguata per la sua nuova offerta business, che prevede connettivit&agrave; ADSL fino a 10Mbps con banda minima garantita di 512 Kbps, due numerazioni telefoniche geografiche, traffico incluso per le chiamate su numeri fissi nazionali e verso alcune direttrici internazionali, di cui la clientela potr&agrave; avvalersi impiegando il modem\/router wireless FRITZ!Box Fon WLAN 7270 ed i tre telefoni DECT FRITZ!Fon MT-F in dotazione. Cinque caselle di posta elettronica IMAP da 2GByte complete di Antispam e Antivirus, servizio Mobile Connect per la sincronizzazione su smartphone, dominio, spazio web e indirizzo IP statico completano la soluzione Pianeta Affari Basic. Il servizio &egrave; offerto in promozione fino al 31 maggio 2011 con il primo mese di canone in omaggio per due anni.<br \/>Giovanni Cristi, Project Manager di AVM, aggiunge: &ldquo;Con il FRITZ!Box 7270 i clienti impiegheranno una soluzione all-in-one che integra un centralino telefonico dotato di stazione base DECT di nuova generazione, 5 segreterie telefoniche personalizzabili, la funzione voice- e fax-to-mail per garantire la massima reperibilit&agrave; degli interlocutori aziendali anche qualora si trovino fuori sede, oltre che l&rsquo;accesso a tutti i servizi di rete con connettivit&agrave; wireless o cablata, tra cui la funzionalit&agrave; print-server per la condivisione delle stampanti, la funzionalit&agrave; NAS \/ WebDAV per la condivisione in rete di<br \/>hard-disk fisici o repository virtuali e l&rsquo;integrazione di servizi DynDNS per accedere ai propri contenuti digitali anche da remoto.&rdquo; <br \/>&ldquo;I professionisti e le aziende che vorranno aderire alla soluzione Pianeta Affari di MC-link, potranno altres&igrave; ridurre notevolmente i costi operativi della propria infrastruttura di telecomunicazioni e di rete, sostituendo con un solo dispositivo fino a 8 diverse appliance&rdquo; conclude Stefano Massucci di MC-link. Con il FRITZ!Fon MT-F gli utenti disporranno altres&igrave; di uno strumento per gestire le rubriche centralizzate del FRITZ!Box, gli elenchi delle chiamate ricevute, condotte o perse e numerose funzioni del 7270 in dotazione. I cordless FRITZ!Fon MT-F, integrati nel pacchetto, supportano la telefonia in alta definizione attraverso il nuovo standard CAT-iq, e consentono all&rsquo;utente sia di usufruire della cifratura del traffico &ldquo;voce&rdquo; offerta dal FRITZ!Box, sia di avvalersi di servizi Internet avanzati (email, feed rss, podcast, internet radio) attraverso il telefono.<br \/>Il connubio dei servizi MC-link e della piattaforma AVM oggetto del pacchetto business &ldquo;Pianeta Affari&rdquo; offre tanti e tali vantaggi alla clientela che l&rsquo;operatore ha ritenuto opportuno indire per i propri installatori su tutto il territorio nazionale workshop commerciali e tecnici in collaborazione con AVM.<br \/>&ldquo;Siamo molto lieti di aver superato con successo i severi test condotti da MC-link e di essere parte integrante di una soluzione che offre alla clientela business servizi di connettivit&agrave; all&rsquo;avanguardia e prodotti innovativi e completi&rdquo; afferma Gianni Garita, Sales Manager di AVM per l&rsquo;Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019operatore di telecomunicazioni presenta un nuovo pacchetto di connettivit\u00e0 e telefonia \u201cflat\u201d, con funzionalit\u00e0 di centralino per la clientela business interamente basato sui prodotti FRITZ! del noto produttore berlinese AVM \/ Massima funzionalit\u00e0: Internet a banda larga, telefonia IP, Wireless-N e DECT di nuova generazione<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[303],"tags":[],"class_list":["post-14323","post","type-post","status-publish","format-standard","hentry","category-telecomunicazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a?cpianeta-affaria??\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L\u2019operatore di telecomunicazioni presenta un nuovo pacchetto di connettivit\u00e0 e telefonia \u201cflat\u201d, con funzionalit\u00e0 di centralino per la clientela business interamente basato sui prodotti FRITZ! del noto produttore berlinese AVM \/ Massima funzionalit\u00e0: Internet a banda larga, telefonia IP, Wireless-N e DECT di nuova generazione\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-30T12:11:45+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"MC-link sceglie AVM per \u201cPianeta Affari\u201d\",\"datePublished\":\"2011-03-30T12:11:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/\"},\"wordCount\":602,\"commentCount\":0,\"articleSection\":[\"Telecomunicazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/\",\"name\":\"MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-30T12:11:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/telecomunicazioni\\\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MC-link sceglie AVM per \u201cPianeta Affari\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a?cpianeta-affaria??\/","og_locale":"it_IT","og_type":"article","og_title":"MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing","og_description":"L\u2019operatore di telecomunicazioni presenta un nuovo pacchetto di connettivit\u00e0 e telefonia \u201cflat\u201d, con funzionalit\u00e0 di centralino per la clientela business interamente basato sui prodotti FRITZ! del noto produttore berlinese AVM \/ Massima funzionalit\u00e0: Internet a banda larga, telefonia IP, Wireless-N e DECT di nuova generazione","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a?cpianeta-affaria??\/","og_site_name":"Article Marketing","article_published_time":"2011-03-30T12:11:45+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"MC-link sceglie AVM per \u201cPianeta Affari\u201d","datePublished":"2011-03-30T12:11:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/"},"wordCount":602,"commentCount":0,"articleSection":["Telecomunicazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/","name":"MC-link sceglie AVM per \u201cPianeta Affari\u201d - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-30T12:11:45+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/telecomunicazioni\/mc-link-sceglie-avm-per-a%80cpianeta-affaria%80%9d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"MC-link sceglie AVM per \u201cPianeta Affari\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14323"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14323\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}