{"id":14472,"date":"2011-03-28T17:46:44","date_gmt":"2011-03-28T15:46:44","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/"},"modified":"2018-07-10T04:32:33","modified_gmt":"2018-07-10T02:32:33","slug":"filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/","title":{"rendered":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta"},"content":{"rendered":"<p><em><em>Unire maternit&agrave; e femminilit&agrave; con il rispetto per il pianeta &egrave; ormai una peculiarit&agrave; delle mamme pi&ugrave; all&#8217;avanguardia, &egrave; uno stile di vita fatto di scelte consapevoli e ponderate, &egrave; possibile e divertente.<\/em> Conosciamo <strong><a href=\"http:\/\/it.wikipedia.org\/wiki\/Filippa_Lagerb%C3%A4ck\" target=\"_blank\" title=\"Filippa Lagerback - Wikipedia\">Filippa Lagerb&auml;ck<\/a><\/strong> come conduttrice, attrice e showgirl, e per la sua attuale presenza a <strong>Che tempo che fa<\/strong>. La sua bellezza ed eleganza sono esemplari, ma Filippa non &egrave; solo una bella presentatrice in tv. &Egrave; anche mamma ecologica e compagna di Daniele Bossari, dalla cui unione &egrave; nata Stella, nel 2003. Filippa &egrave; una mamma molto attiva nelle campagne per la salute del pianeta, e noi l&#8217;abbiamo intervistata per consocere un po&#8217; della sua vita di mamma ecologica e blogger. Filippa ha origini svedesi, e l&#8217;ambientalismo le scorre quindi nel sangue fin dalla nascita. In una citt&agrave; come Milano &egrave; per&ograve; difficile trovare spazi verdi e luoghi d&#8217;incontro per condividere idee verdi, anche se <strong>BimbimBici<\/strong> &egrave; uno dei tantissimi eventi, di cui sar&agrave; madrina a maggio, a cui Filippa &egrave; molto orgogliosa di partecipare. Ecco come si racconta per Mamme nella Rete. <strong>Mamme nella Rete &#8211; Seguiamo il tuo blog e abbiamo notato in pi&ugrave; occasioni il tuo forte impegno per l&#8217;ambiente. Lo spirito ecologista fa parte delle tue origini svedesi oppure sei pi&ugrave; attenta all&#8217;ambiente da quando sei mamma? <\/strong>Filippa Lagerb&auml;ck &#8211; In Svezia l&#8217;amore e il rispetto verso la natura sono innati. Abbiamo una legge che rende la natura patrimonio di tutti, cio&egrave; puoi andare dove vuoi, fare il bagno in qualche lago, raccogliere i mirtilli e i funghi, piantare la tenda e passare la notte, tutto senza bisogno di permesso, l&#8217;unica cosa che devi fare e lasciare tutto come l&#8217;hai trovato! Essendo quindi &#8220;tua&#8221; la natura, &egrave; ovvio che la tratterai bene! <strong>MNR &#8211; Le differenze tra Stoccolma e Milano sono immense, vero?<\/strong> <\/em>FL &#8211; In una grande citt&agrave; come Milano, sento un p&ograve; la mancanza del verde, soprattutto ora che sono mamma. Io sono cresciuta con i laghi, i boschi e i campi davanti a casa, in libert&agrave;. Un p&ograve; mi sento in colpa facendo crescere mia figlia in una citt&agrave;, ed &egrave; anche per questo che mi sono iscritta a Genitori Antismog, per poter migliorare, tutti insieme, la citt&agrave; in cui viviamo. Per fortuna abbiamo anche un piccolo nido tutto nostro in Umbria, dove &egrave; nata Stella, e dove trascorriamo parte dell&#8217;anno. L&agrave; Stella corre libera tra i campi e sulle strade bianche a piedi nudi, e io sono cos&igrave; felice di vederla cos&igrave;! <\/p>\n<p> <strong>MNR &#8211; Quali sono le manifestazioni ambientaliste a cui sei pi&ugrave; orgogliosa di aver partecipato e perch&eacute;? <\/strong> <br \/>FL &#8211; Con i <strong>Genitori Antismog<\/strong> sono felice di andare in piazza per fare vedere la nostra presenza e sentire la nostra voce, sensibilizzando i cittadini e le persone che decidono per noi, per ottenere cambiamenti reali. Sono felice di partecipare alle giornate di Ciclobby, BicinFesta di primavera (l&#8217;8 maggio sar&ograve; anche madrina di BimbimBici) Sono stata con I like Mi dall&#8217;inizio: una nuova pagina su facebook fondata da Edoardo Croci dove parliamo BENE della nostra citt&agrave;, portando suggerimenti per come migliorala. Credo che parlare bene ed essere positivi sia la strada giusta, e che criticare e basta non porti a niente. Ero davvero fiera di poter essere sulla copertina di Sette insieme alla mia figlia sul numero che parlava dello smog, mettendo &#8220;la faccia&#8221; per una causa cos&igrave; importante. Ma soprattutto credo che le cose pi&ugrave; importanti si facciano in casa, parlando e insegnando ai nostri figli come trattare bene e salvaguardare il pianeta! Mia figlia &egrave; sostenitrice WWF, partecipa alle manifestazioni ed &egrave; molto consapevole, a scuola, l&#8217;International School of Milan, parlano spesso dell&#8217;ecologia e dell&#8217;ambiente. <\/p>\n<p><strong> MNR &#8211; Cosa deve fare una mamma per essere ecologica? Quali sono le azioni imprescindibili per salvaguardare il pianeta e la salute dei propri figli? <\/strong><br \/>FL &#8211; Sabato 26 marzo c&#8217;era l&#8217;<strong>Earth Hour<\/strong>, eravamo a una cena da un&#8217;amica, e ho fatto spegnere tutte le luci. Abbiamo cenato a lume di candela, molto pi&ugrave; bello e romantico e&#8230;ecologico! Le bambine erano coinvolte e si sono divertite! Non voglio per&ograve; diventare angosciante e rompiscatole, anche se continuo a dire alle mie amiche di usare di pi&ugrave; la bici che non la macchina, di non buttare le sigarette per terra e tante altre piccole importanti cose come riciclare vestiti e giocattoli, spegnere le luci, staccare i caricabatterie quando non in uso (un libro bellissimo che consiglio a tutti bimbi &egrave; 10 cose che posso fare per aiutare il mio pianeta). Credo che il cambiamento debba nascere dentro di te, la voglia di cambiare le abitudini, anche piccole cose, ma che se fatte in tanti portano a risultati importanti. Non prendere la macchina per andare pochi metri, usare di pi&ugrave; la bici o le gambe, rispettare i spazi comuni, fare la raccolta differenziata, non sprecare l&#8217;acqua (qui &egrave; pi&ugrave; brava mia figlia, che mi rimprovera sempre!) comprare frutta e verdura di stagione, di coltivazione locale. Se insegniamo tutto questo anche ai bambini, rendendoli dei gesti naturali e perch&egrave; no, anche divertenti, potremo amare di pi&ugrave; la nostra citt&agrave;, dove viviamo e dove crescono i nostri figli, trattandola bene e rendendola pi&ugrave; bella per tutti! <\/p>\n<p><strong> MNR &#8211; Come concili lavoro e famiglia? Fai fatica a seguire tutto quanto oppure la tua vita &egrave; tutto sommato tranquilla? <\/strong> <br \/>FL &#8211; Sono una mamma molto presente, la famiglia prima di tutto. Lavorando a Milano, riesco benissimo a dividermi tra il lavoro e la casa. Porto tutti i giorni Stella a scuola (a piedi), di pomeriggio facciamo i compiti insieme e la porto alle sue attivit&agrave; varie. Non mi faccio dei problemi per&ograve;, se devo stare via qualche notte, cos&igrave; passer&agrave; il tempo con il suo pap&agrave;, facendo tutte quelle cose che non fanno quando c&#8217;&egrave; la mamma, legando ancora di pi&ugrave;! <\/p>\n<p> <strong>MNR &#8211; Come sogni il futuro dei tuoi figli? <\/strong> <br \/>FL &#8211; Sogno un futuro pi&ugrave; consapevole, con pi&ugrave; rispetto e verit&agrave;, un risveglio collettivo per quanto riguarda tutto: natura, ambiente, politica. Banalmente dobbiamo capire che il mondo &egrave; uno (almeno per quello che sappiamo), ed &egrave; la nostra casa. Se la rispettiamo e la teniamo pulita, anche il futuro dei nostri figli ne trarr&agrave; giovamento. <\/p>\n<p> <strong> MNR &#8211; Applichi alcune regole eco anche sul set o nel camerino? Se si, in che modo? <\/strong> <br \/>FL &#8211; No, niente in particolare, cerco ovviamente di spegnere le tanti luci quando esco dal camerino. In Rai inoltre si fa la raccolta differenziata. Con il bel tempo cerco di arrivare al lavoro in bici, ma non &egrave; sempre possibile. Sogno, e spero che si realizzi il desiderio di acquistare una macchina elettrica per la famiglia! Grazie a Filippa per averci dedicato il suo tempo e i suoi modi sempre gentili e allegri. <\/p>\n<p>Il blog di Filippa Lagerb&auml;ck &#8211; www.planetfil.net<br \/>\nPer info: press@mammenellarete.it www.mammenellarete.it &ndash; Facebook &ndash; Twitter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unire maternit\u00e0 e femminilit\u00e0 con il rispetto per il pianeta \u00e8 ormai una peculiarit\u00e0 delle mamme pi\u00f9 all&#8217;avanguardia, \u00e8 uno stile di vita fatto di scelte consapevoli e ponderate, \u00e8 possibile e divertente.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[55],"tags":[24548,24547,260,24544,24545,24542,24549,24546,24543,8032],"class_list":["post-14472","post","type-post","status-publish","format-standard","hentry","category-ambiente","tag-ambientalismo","tag-daniele-bossari","tag-ecologia","tag-ecomamma","tag-ecomamme","tag-filippa-lagerback","tag-filippa-lagerback-mamma-ecologica","tag-mamma-ecologica","tag-mamma-vip","tag-maternita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%c3%a4ck-mamma-ecologica-si-racconta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Unire maternit\u00e0 e femminilit\u00e0 con il rispetto per il pianeta \u00e8 ormai una peculiarit\u00e0 delle mamme pi\u00f9 all&#039;avanguardia, \u00e8 uno stile di vita fatto di scelte consapevoli e ponderate, \u00e8 possibile e divertente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%c3%a4ck-mamma-ecologica-si-racconta\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-28T15:46:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:32:33+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta\",\"datePublished\":\"2011-03-28T15:46:44+00:00\",\"dateModified\":\"2018-07-10T02:32:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/\"},\"wordCount\":1196,\"commentCount\":0,\"keywords\":[\"ambientalismo\",\"Daniele Bossari\",\"ecologia\",\"ecomamma\",\"ecomamme\",\"Filippa Lagerb\u00e4ck\",\"Filippa Lagerb\u00e4ck mamma ecologica\",\"mamma ecologica\",\"mamma vip\",\"maternit\u00e0\"],\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/\",\"name\":\"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-03-28T15:46:44+00:00\",\"dateModified\":\"2018-07-10T02:32:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%c3%a4ck-mamma-ecologica-si-racconta\/","og_locale":"it_IT","og_type":"article","og_title":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing","og_description":"Unire maternit\u00e0 e femminilit\u00e0 con il rispetto per il pianeta \u00e8 ormai una peculiarit\u00e0 delle mamme pi\u00f9 all'avanguardia, \u00e8 uno stile di vita fatto di scelte consapevoli e ponderate, \u00e8 possibile e divertente.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%c3%a4ck-mamma-ecologica-si-racconta\/","og_site_name":"Article Marketing","article_published_time":"2011-03-28T15:46:44+00:00","article_modified_time":"2018-07-10T02:32:33+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta","datePublished":"2011-03-28T15:46:44+00:00","dateModified":"2018-07-10T02:32:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/"},"wordCount":1196,"commentCount":0,"keywords":["ambientalismo","Daniele Bossari","ecologia","ecomamma","ecomamme","Filippa Lagerb\u00e4ck","Filippa Lagerb\u00e4ck mamma ecologica","mamma ecologica","mamma vip","maternit\u00e0"],"articleSection":["Ambiente"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/","name":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-03-28T15:46:44+00:00","dateModified":"2018-07-10T02:32:33+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/filippa-lagerb%25c3%25a4ck-mamma-ecologica-si-racconta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Filippa Lagerb\u00e4ck, mamma ecologica, si racconta"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14472"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14472\/revisions"}],"predecessor-version":[{"id":59276,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14472\/revisions\/59276"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}