{"id":14542,"date":"2011-03-30T10:34:04","date_gmt":"2011-03-30T08:34:04","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/master-o-lavoro-3\/"},"modified":"2018-07-10T04:30:31","modified_gmt":"2018-07-10T02:30:31","slug":"master-o-lavoro-3","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/","title":{"rendered":"Master o lavoro?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg\" border=\"0\" alt=\"master o lavoro\" width=\"391\" height=\"307\" \/><\/p>\n<p><strong>Master o lavoro?<\/strong> Dopo la laurea qual &egrave; la scelta pi&ugrave; azzeccata per: trovare il lavoro che mi piace, non farmi sfruttare (oltre un limite di decenza), avere un contratto a tempo (in)determinato, fare carriera partendo dal verso giusto e intraprendere una strada che non mi faccia pi&ugrave; tornare indietro? <br \/>Miei cari, la brutta notizia &egrave; che nessuna di queste due possibilit&agrave; regala una targhetta d&#8217;ottone sulla scrivania a pochi giorni dalla discussione della tesi. <br \/>La bella notizia &egrave; che avete la personale e legittima facolt&agrave; di scegliere tra master o lavoro, in base ad una serie di elementi soggettivi (ci&ograve; che volete fare, situazione individuale, carattere) ed altri oggettivi che, ora, andremo a vedere.<br \/><strong>Master o lavoro? <\/strong><br \/>Chi si pone questa domanda &egrave; evidentemente ad un punto cruciale del proprio cammino e, in qualche modo, ha scelto un indirizzo che richiederebbe una specifica di titolo in pi&ugrave; o una preparazione professionalizzante. <br \/>Nello specifico:<br \/>&#8211; frequentare un master post laurea non equivale a pagarsi un&#8217;occupazione sicura. Neppure quando lo stage, garantito, &egrave; frutto di un valido lavoro di placement dell&#8217;ente di formazione.<br \/>Un master valido risulta un&#8217;esperienza gratificante se intrapreso con l&#8217;obiettivo di assumere competenze riconoscibili che incrementano non solo il cv, ma anche e soprattutto il proprio livello qualitativo sul mercato. <br \/>Da questo punto di vista non &egrave; necessario, spesso, spendere decine di migliaia di euro per conseguire un diploma di master: esistono moltissime offerte di master che prevedono una sensibile riduzione di rette di frequenza.<br \/>Se alla domanda <strong>master o lavoro?<\/strong>, la possibilit&agrave; pi&ugrave; fattiva sembra quella di lanciarsi di testa nel mondo del lavoro, bisogna che valutiate con cura:<br \/>&#8211; quanto l&#8217;esigenza economica del momento gravi sulla scelta. <br \/>Impegnarsi in collaborazioni saltuarie che contribuiscono al mantenimento e diano il tempo per perfezionarsi negli studi &egrave; una cosa; decidere di buttarsi nel primo ruolo disponibile col compromesso di allontanarsi completamente dall&#8217;indirizzo che si &egrave; intrapreso all&#8217;universit&agrave; &egrave; ben altra decisione. Non sempre reversibile. Qui gioca un ruolo fondamentale la propria capacit&agrave; di crearsi un network di contatti, informazioni e voci attinenti al contesto che vi interessa.<br \/>Nessuno, infatti, agenzie per il lavoro comprese, potranno effettuare ricerca oculata al posto vostro perch&eacute; solo voi potete sviluppare una totale consapevolezza di ci&ograve; che vorrete fare!<br \/>&#8211; quanto un&#8217;inesperienza pratica o una mancata preparazione di contenuto di quel settore potrebbero rendervi dei &#8216;tuttofare&#8217;, partendo dal famigerato ufficio fotocopie (che, all&#8217;inizio, non solo non &egrave; in assoluto un male, ma anche un modo per osservare e impossessarvi dei trucchi del mestiere) rallentando una crescita e un&#8217;assunzione di responsabilit&agrave; che, nel caso di uno studio di alta formazione, avrebbe potuto portarvi a velocizzare il passaggio.<br \/>Tra <strong>master o lavoro <\/strong>come vedete la scelta va a toccare una serie di variabili che mutano rispetto:<br \/>. all&#8217;aspettativa che ciascuno attende dalla scelta.<br \/>. al senso che la parola &#8216;lavoro&#8217; assume. Esiste il lavoro inteso come prima esperienza di iniziazione al mercato, in cui esprimere la propria aderenza a un dato settore individuato; esiste poi il lavoro inteso in termini pi&ugrave; generali, su cui non si proietta quell&#8217;investimento di energie, tempi, fatiche finalizzate al collocamento in un posto ben preciso, che solitamente determina la scelta seguire un master.<br \/>In bocca al lupo a ciascuno di voi: non smettete mai di pensare che l&agrave; fuori esista un posto preciso per voi. Da qualche parte, c&#8217;&egrave; e va solo trovato.<\/p>\n<p>Per approfondire:<br \/>. Come scegliere un master? <br \/>. Master o specialistica ? <br \/>. Studio e lavoro vanno ancora a braccetto?<br \/>. Master: i settori che lo richiedono <\/p>\n<p>E tu, cosa pensi di fare: <strong>master o lavoro?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Master o lavoro? Dopo la laurea qual \u00e8 la scelta pi\u00f9 azzeccata per: trovare il lavoro che mi piace, non farmi sfruttare (oltre un limite di decenza), avere un contratto a tempo (in)determinato, fare carriera partendo dal verso giusto e intraprendere una strada che non mi faccia pi\u00f9 tornare indietro?<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[2656],"tags":[24583],"class_list":["post-14542","post","type-post","status-publish","format-standard","hentry","category-istruzione","tag-master-o-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Master o lavoro? - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Master o lavoro? - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Master o lavoro? Dopo la laurea qual \u00e8 la scelta pi\u00f9 azzeccata per: trovare il lavoro che mi piace, non farmi sfruttare (oltre un limite di decenza), avere un contratto a tempo (in)determinato, fare carriera partendo dal verso giusto e intraprendere una strada che non mi faccia pi\u00f9 tornare indietro?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-30T08:34:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Master o lavoro?\",\"datePublished\":\"2011-03-30T08:34:04+00:00\",\"dateModified\":\"2018-07-10T02:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/\"},\"wordCount\":611,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-kW5iZc0FUbg\\\/TZCeNDp2LOI\\\/AAAAAAAAAIo\\\/fYddZCRW-B8\\\/s1600\\\/Master+o+lavoro.jpg\",\"keywords\":[\"master o lavoro?\"],\"articleSection\":[\"Istruzione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/\",\"name\":\"Master o lavoro? - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-kW5iZc0FUbg\\\/TZCeNDp2LOI\\\/AAAAAAAAAIo\\\/fYddZCRW-B8\\\/s1600\\\/Master+o+lavoro.jpg\",\"datePublished\":\"2011-03-30T08:34:04+00:00\",\"dateModified\":\"2018-07-10T02:30:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#primaryimage\",\"url\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-kW5iZc0FUbg\\\/TZCeNDp2LOI\\\/AAAAAAAAAIo\\\/fYddZCRW-B8\\\/s1600\\\/Master+o+lavoro.jpg\",\"contentUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-kW5iZc0FUbg\\\/TZCeNDp2LOI\\\/AAAAAAAAAIo\\\/fYddZCRW-B8\\\/s1600\\\/Master+o+lavoro.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/master-o-lavoro-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Master o lavoro?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Master o lavoro? - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/","og_locale":"it_IT","og_type":"article","og_title":"Master o lavoro? - Article Marketing","og_description":"Master o lavoro? Dopo la laurea qual \u00e8 la scelta pi\u00f9 azzeccata per: trovare il lavoro che mi piace, non farmi sfruttare (oltre un limite di decenza), avere un contratto a tempo (in)determinato, fare carriera partendo dal verso giusto e intraprendere una strada che non mi faccia pi\u00f9 tornare indietro?","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/","og_site_name":"Article Marketing","article_published_time":"2011-03-30T08:34:04+00:00","article_modified_time":"2018-07-10T02:30:31+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Master o lavoro?","datePublished":"2011-03-30T08:34:04+00:00","dateModified":"2018-07-10T02:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/"},"wordCount":611,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg","keywords":["master o lavoro?"],"articleSection":["Istruzione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/","name":"Master o lavoro? - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg","datePublished":"2011-03-30T08:34:04+00:00","dateModified":"2018-07-10T02:30:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#primaryimage","url":"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg","contentUrl":"http:\/\/3.bp.blogspot.com\/-kW5iZc0FUbg\/TZCeNDp2LOI\/AAAAAAAAAIo\/fYddZCRW-B8\/s1600\/Master+o+lavoro.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/master-o-lavoro-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Master o lavoro?"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14542"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14542\/revisions"}],"predecessor-version":[{"id":59183,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14542\/revisions\/59183"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}