{"id":14852,"date":"2011-04-09T16:02:14","date_gmt":"2011-04-09T14:02:14","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/"},"modified":"2018-07-10T04:13:47","modified_gmt":"2018-07-10T02:13:47","slug":"primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/","title":{"rendered":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II"},"content":{"rendered":"<p>Papa Giovanni Paolo II verr&agrave; beatificato, in seguito al riconoscimento di diversi miracoli, tra cui si ricordano 251 guarigioni inspiegabili.<br \/> La data scelta &egrave; quella del 1 maggio 2011, come annunciato dal portavoce Vaticano padre Lombardi, scelta non casuale trattandosi della Domenica in Albis cio&egrave; la prima domenica successiva alla Pasqua.<br \/> Le spoglie di Giovanni Paolo II verranno esposte ai fedeli, a partire dal giorno della beatificazione, davanti l&rsquo;Altare della Confessione nella Basilica di San Pietro.<br \/> Il programma, gratuito per tutti i fedeli che giungeranno a Roma, sar&agrave; suddiviso in tre giornate.<\/p>\n<p> La prima giornata si svolger&agrave; in data Sabato 30 aprile 2011 dalle ore 20.00 alle 22.30 al Circo Massimo e sar&agrave; dedicata alla veglia di preparazione.<br \/> Sar&agrave; guidata dal cardinale Agostino Vallini al quale si unir&agrave; in collegamento video anche il Papa Benedetto XVI .<\/p>\n<p> La seconda giornata &egrave; fissata per Domenica 1 maggio 2001, dalle 10.00 di mattina in piazza San Pietro, e sar&agrave; dedicata alle celebrazioni per la beatificazione presiedute dal Santo Padre.<br \/> La partecipazione &egrave; libera e gratuita, le spoglie saranno esposte davanti l&rsquo;Altare della Confessione sino al termine del flusso dei fedeli.<br \/> L&rsquo;accesso all&rsquo;area della Basilica di San Pietro sar&agrave; regolato dalle autorit&agrave; di Pubblica Sicurezza.<\/p>\n<p> La terza e ultima giornata si terr&agrave; Luned&igrave; 2 maggio 2011, dalle ore 10.30 in piazza San Pietro e sar&agrave; dedicata alla celebrazione della Messa di ringraziamento, presieduta dal Cardinale Tarcisio Bertone, segretario di Stato.<\/p>\n<p> L&rsquo;evento, come previsto, vedr&agrave; arrivare a Roma migliaia di turisti italiani e stranieri che hanno gi&agrave; fatto registrare il tutto esaurito negli alberghi e nei b&amp;b vicino al Vaticano.<br \/> Le stime sono di un milione di pellegrini, sul piano organizzativo sar&agrave; quindi necessario un grande lavoro per accogliere al meglio la folla dei fedeli, &egrave; previsto ad esempio l&rsquo;uso di maxi schermi dislocati per la citt&agrave;, al fine di favorire una migliore distribuzione dei turisti nelle diverse zone adiacenti alla Citt&agrave; del Vaticano.<br \/>\nLa rete dei trasporti sar&agrave; potenziata, la metro di Roma rester&agrave; aperta fino alle 2 di notte, ci sar&agrave; un incremento del numero dei treni nelle ore di punta e un anticipo delle ore di partenza alle 4 di mattina. Per garantire la sicurezza delle migliaia di persone che si riverseranno in Piazza San Pietro, verranno schierati oltre 3000 volontari della protezione civile a cui si aggiungeranno 3000 uomini della Polizia municipale. Sul versante dell&#8217;emergenza sanitaria, verrano assicurati posti letto ospedalieri dalle A.sl. per far fronte ad eventuali interventi di pronto soccorso.<br \/>\nSono previste inoltre due tendopoli per i pellegrini, la prima verr&agrave; sistemata vicino al porto di Civitavecchia a beneficio dei turisti proventienti principalmente dalla Spagna, la seconda sar&agrave; situata a Fiumicino per un totale di 1000 posti di accoglienza disponibili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Migliaia di pellegrini sono attesi nella Capitale per l&#8217;evento. Il programma delle tre giornate in dettaglio.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[6193,24385,24945,910,24946,3130,24944,251],"class_list":["post-14852","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-a","tag-beatificazione","tag-giovanni","tag-maggio","tag-paolo","tag-papa","tag-primo","tag-roma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Migliaia di pellegrini sono attesi nella Capitale per l&#039;evento. Il programma delle tre giornate in dettaglio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-09T14:02:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:13:47+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II\",\"datePublished\":\"2011-04-09T14:02:14+00:00\",\"dateModified\":\"2018-07-10T02:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/\"},\"wordCount\":483,\"commentCount\":0,\"keywords\":[\"a\",\"beatificazione\",\"giovanni\",\"maggio\",\"paolo\",\"papa\",\"primo\",\"roma\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/\",\"name\":\"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-04-09T14:02:14+00:00\",\"dateModified\":\"2018-07-10T02:13:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/","og_locale":"it_IT","og_type":"article","og_title":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing","og_description":"Migliaia di pellegrini sono attesi nella Capitale per l'evento. Il programma delle tre giornate in dettaglio.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/","og_site_name":"Article Marketing","article_published_time":"2011-04-09T14:02:14+00:00","article_modified_time":"2018-07-10T02:13:47+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II","datePublished":"2011-04-09T14:02:14+00:00","dateModified":"2018-07-10T02:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/"},"wordCount":483,"commentCount":0,"keywords":["a","beatificazione","giovanni","maggio","paolo","papa","primo","roma"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/","name":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-04-09T14:02:14+00:00","dateModified":"2018-07-10T02:13:47+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/primo-maggio-a-roma-per-la-beatificazione-di-papa-giovanni-paolo-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Primo maggio a Roma per la Beatificazione di Papa Giovanni Paolo II"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14852"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14852\/revisions"}],"predecessor-version":[{"id":58440,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14852\/revisions\/58440"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}