{"id":14980,"date":"2011-04-13T18:27:37","date_gmt":"2011-04-13T16:27:37","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/abbigliamento-vintage-torino-collezione-privata\/"},"modified":"2011-04-13T18:27:37","modified_gmt":"2011-04-13T16:27:37","slug":"abbigliamento-vintage-torino-collezione-privata","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/","title":{"rendered":"Abbigliamento vintage Torino &#8211; Collezione Privata"},"content":{"rendered":"<p>La moda punto di incontro tra vecchio e nuovo, volge affascinata lo sguardo al passato arricchendosi di abiti e accessori di un tempo: parliamo di<strong style=\"font-weight: bold;\">abbigliamento vintage<\/strong>.<br \/>Il termine vintage deriva dal francese &#8220;l&#8217;auge du vin&#8221;. L&#8217;<strong style=\"font-weight: bold;\">abbigliamento vintage<\/strong> si rif&agrave; a capi di epoche passate che sono tornati in auge negli anni grazie alla loro particolarit&agrave; o qualit&agrave;, divenendo dei veri e propri oggetti di culto. Non stiamo parlando assolutamente di abbigliamento usato ma di capi unici, irriproducibili e irripetibili.<br \/><a href=\"http:\/\/www.shoppingdonna.it\/moda\/abbigliamento_donna_uomo\/piemonte\/torino\/collezioneprivata-torino.html\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1055\" src=\"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg\" border=\"0\" alt=\"abbigliamento vintage Torino\" title=\"abbigliamento vintage Torino\" width=\"485\" height=\"480\" \/><\/a><br \/><strong style=\"font-weight: bold;\">Abbigliamento vintage a Torino<\/strong><br \/><strong style=\"font-weight: bold;\">Collezione Privata<\/strong> in zona Crocetta, a 5 minuti dalla centralissima via Roma di <strong style=\"font-weight: bold;\">Torino<\/strong>, &egrave; una boutique che propone <strong style=\"font-weight: bold;\">abbigliamento vintage a Torino <\/strong>insieme a capi contemporanei, oltre a proposte d&rsquo;arredo e arredi di modernariato e di design ed una raffinata selezione di biancheria e pizzi d&#8217;epoca di fine &#8216;800 e &#8216;900.<br \/>L&rsquo;idea nasce dal talento di Eleonora Grandi, architetto e designer, animata da un grande spirito e dalla voglia di unire una delle sue pi&ugrave; grandi passioni, il <strong style=\"font-weight: bold;\">vintage<\/strong>, alla voglia di moda e ricercatezza per la casa, la persona e l&rsquo;arredo.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1057\" src=\"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/collezione-privata-abbigliamento-vintage-torino.jpg\" border=\"0\" alt=\"collezione privata- abbigliamento vintage torino\" title=\"collezione privata- abbigliamento vintage torino\" width=\"353\" height=\"605\" \/><br \/>La boutique <strong style=\"font-weight: bold;\">Collezione Privata<\/strong>,<strong style=\"font-weight: bold;\"> <\/strong>arredamento e <strong style=\"font-weight: bold;\">abbigliamento vintage a Torino<\/strong> &egrave; quindi un&rsquo;autentica galleria d&rsquo;arte dove alle tendenze del momento &egrave; sostituita la filosofia moderna ed iper contemporanea di vivere la casa e creare il proprio look con personalit&agrave; e in grande stile, lasciandosi guidare nella scelta dall&rsquo;istinto e dall&rsquo;emozione che ogni articolo per la sua ricercatezza e grazia suggerisce.<br \/>Per questo fine in negozio trovano posto articoli unici e di ricerca e tutto farebbe pensare a prezzi elevatissimi, invece a distinguere l&rsquo;attivit&agrave; della boutique &egrave; persino l&rsquo;ottimo rapporto qualit&agrave; prezzo: determinato dalla costante ricerca di pezzi originali e preziosi, il cui valore aggiunto &egrave; la preziosit&agrave; della storia che raccontano.<br \/>Per l&rsquo;<strong style=\"font-weight: bold;\">abbigliamento vintage,<\/strong> <strong style=\"font-weight: bold;\">Collezione Privata<\/strong> propone a <strong style=\"font-weight: bold;\">Torino<\/strong> moda donna dagli &rsquo;30 fino agli anni &rsquo;80 di marchi famosi, proposte anni&rsquo;90 anche nuove e con cartellino, gioielli e bijoux di ricerca.<\/p>\n<p>Mentre per la casa le proposte sono varie: dagli arredi ai complementi, ai tendaggi ai quadri, tutto pensato e suggerito con studio d&rsquo;interni e progettazione. <strong style=\"font-weight: bold;\">Collezione Privata<\/strong> &egrave; la tua guida al nuovo chic, per idee che fanno del tuo stile e della tua casa un connubio unico e particolare: semplicemente perfetto.<br \/>E voi cosa pensate del <strong style=\"font-weight: bold;\">vintage<\/strong>??<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbigliamento vintage a Torino. Collezione Privata in zona Crocetta, a 5 minuti dalla centralissima via Roma di Torino, \u00e8 una boutique che propone abbigliamento vintage a Torino insieme a capi contemporanei, oltre a proposte d\u2019arredo e arredi di modernariato e di design ed una raffinata selezione di biancheria e pizzi d&#8217;epoca di fine &#8216;800 e &#8216;900.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[308],"tags":[8414,25101,25102,2555,389],"class_list":["post-14980","post","type-post","status-publish","format-standard","hentry","category-shopping","tag-abbigliamento-vintage","tag-abbigliamento-vintage-torino","tag-collezione-privata","tag-torino","tag-vintage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abbigliamento vintage Torino - Collezione Privata - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abbigliamento vintage Torino - Collezione Privata - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Abbigliamento vintage a Torino. Collezione Privata in zona Crocetta, a 5 minuti dalla centralissima via Roma di Torino, \u00e8 una boutique che propone abbigliamento vintage a Torino insieme a capi contemporanei, oltre a proposte d\u2019arredo e arredi di modernariato e di design ed una raffinata selezione di biancheria e pizzi d&#039;epoca di fine &#039;800 e &#039;900.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-13T16:27:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Abbigliamento vintage Torino &#8211; Collezione Privata\",\"datePublished\":\"2011-04-13T16:27:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/\"},\"wordCount\":412,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.shoppingdonna.it\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/abbigliamento-vinta-a-Torino.jpg\",\"keywords\":[\"abbigliamento vintage\",\"abbigliamento vintage torino\",\"collezione privata\",\"Torino\",\"vintage\"],\"articleSection\":[\"Shopping\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/\",\"name\":\"Abbigliamento vintage Torino - Collezione Privata - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.shoppingdonna.it\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/abbigliamento-vinta-a-Torino.jpg\",\"datePublished\":\"2011-04-13T16:27:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.shoppingdonna.it\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/abbigliamento-vinta-a-Torino.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.shoppingdonna.it\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/abbigliamento-vinta-a-Torino.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/shopping\\\/abbigliamento-vintage-torino-collezione-privata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abbigliamento vintage Torino &#8211; Collezione Privata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abbigliamento vintage Torino - Collezione Privata - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/","og_locale":"it_IT","og_type":"article","og_title":"Abbigliamento vintage Torino - Collezione Privata - Article Marketing","og_description":"Abbigliamento vintage a Torino. Collezione Privata in zona Crocetta, a 5 minuti dalla centralissima via Roma di Torino, \u00e8 una boutique che propone abbigliamento vintage a Torino insieme a capi contemporanei, oltre a proposte d\u2019arredo e arredi di modernariato e di design ed una raffinata selezione di biancheria e pizzi d'epoca di fine '800 e '900.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/","og_site_name":"Article Marketing","article_published_time":"2011-04-13T16:27:37+00:00","og_image":[{"url":"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Abbigliamento vintage Torino &#8211; Collezione Privata","datePublished":"2011-04-13T16:27:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/"},"wordCount":412,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg","keywords":["abbigliamento vintage","abbigliamento vintage torino","collezione privata","Torino","vintage"],"articleSection":["Shopping"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/","name":"Abbigliamento vintage Torino - Collezione Privata - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg","datePublished":"2011-04-13T16:27:37+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#primaryimage","url":"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg","contentUrl":"http:\/\/blog.shoppingdonna.it\/wp-content\/uploads\/2011\/04\/abbigliamento-vinta-a-Torino.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/shopping\/abbigliamento-vintage-torino-collezione-privata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Abbigliamento vintage Torino &#8211; Collezione Privata"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=14980"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/14980\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=14980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=14980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=14980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}