{"id":15183,"date":"2011-04-19T15:12:14","date_gmt":"2011-04-19T13:12:14","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/"},"modified":"2011-04-19T15:12:14","modified_gmt":"2011-04-19T13:12:14","slug":"g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/","title":{"rendered":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java"},"content":{"rendered":"<p>Secondo le ultime analisi condotte dai G Data SecurityLabs, i criminali online si stanno concentrando sempre di pi&ugrave; sulle falle di sicurezza di Java per distribuire malware per computer. Questa tipologia di malware ha dominato le classiche per i primi mesi del 2011. Solo nel mese di Marzo ci sono state ad esempio cinque tipologie di Trojan nella Top 10 del malware che hanno preso di mira le vulnerabilit&agrave; di Java o Javascript. G Data ha inoltre evidenziato un aumento della presenza di siti manipolati nelle classifiche dei motori di ricerca. L&rsquo;obbiettivo in questo caso &egrave; ingannare gli utenti degli stessi motori di ricerca o dei social network facendo cliccare loro dei siti infetti. G Data si aspetta un ulteriore incremento di entrambe queste due strategie nei prossimi mesi. Le falle di sicurezza nei plug-in dei browser stanno giocando un ruolo sempre pi&ugrave; grande nell&rsquo;infezione dei sistemi Windows. L&rsquo;industria del malware si sta focalizzando sulle vulnerabilit&agrave; di Java fin dalla fine dell&rsquo;anno passato. &ldquo;Per questo motivo gli utenti non dovrebbero disattivare la funzione di aggiornamento automatico di Java ed installare tutte le ultime patch. &Egrave; facile e semplice controllare le versioni installate dei programmi Java utilizzando il sito <a href=\"http:\/\/www.java.com\/en\/download\/installed.jsp\">http:\/\/www.java.com\/en\/download\/installed.jsp<\/a>,&#8221;, spiega Ralf Benzm&uuml;ller, Head of G Data SecurityLabs. &#8220;Per mesi abbiamo osservato un aumento nel malware che manipola i click sui siti Internet in modo tale da migliorarne il ranking. I cosiddetti attacchi &#8216;clickjacking&#8217; fanno in modo che i siti di malware vengano considerati pi&ugrave; affidabili nei motori di ricerca e nei social network.&rdquo; Clickjacking: Il Website ranking inganna gli utenti e li porta verso contenuti pericolosi<br \/>La manipolazione del ranking dei siti Internet nei motori di ricerca (SEO) o nei social network &egrave; recentemente diventata una pratica molto popolare tra i criminali online. Questi utilizzano il cosiddetto &ldquo;clickjacking&rdquo; nei social network per posizionare i siti infetti con malware nelle migliori posizioni in classifica. Trojan.JS.Clickjack &egrave; stato uno dei programmi malware di questo tipo ad entrare nella Top 10 del Malware di Marzo 2011. Quando dei siti idonei sono visitati questo programma genera click sul bottone &ldquo;mi piace&rdquo; di Facebook senza che l&rsquo;&rsquo;utente se ne accorga. Questo tipicamente consente ai siti delle presunte celebrit&agrave; di entrare nelle prime posizioni in classica dei motori di ricerca per determinate parole chiave. Metodologia<br \/>La Malware Information Initiative (MII) si basa sulla forza della community online community ed ogni utente delle soluzioni di sicurezza di G Data ne pu&ograve; far parte. L&rsquo;unico prerequisito &egrave; quello di attivare questa funzione all&rsquo;interno dei programmi G Data. Se un attacco malware viene respinto questo evento viene riportato in maniera completamente anonima ai G Data SecurityLabs dove i dati vengono archiviati ed analizzati statisticamente. Informazioni sulla Top 10 del Malware &ndash; Marzo 2011 Trojan.Wimad.Gen.1<br \/>Questo Trojan si presenta come un normale file audio .wma che pu&ograve; essere ascoltato solo dopo aver installato uno speciale codec\/decoder in windows. Se questo file viene aperto, viene installato nel malware. Questo file audio infetto &egrave; solitamente distribuito attraverso i network P2P. Java.Trojan.Downloader.OpenConnection.AI<br \/>Questo Trojan downloader si trova in applet Java manipolate presenti su alcuni siti Internet. Quando l&rsquo;applet viene scaricata, viene generato un URL. Il downloader lo utilizza per scaricare un file eseguibile maligno sul Pc dell&rsquo;utente e lo lancia. Questo downloader sfrutta la vulnerabilit&agrave; CVE-2010-0840 per eludere il Java sandbox e cos&igrave; scrivere dati localmente. Win32.Ramnit.N<br \/>Win32.Ramnit.N &egrave; un classico file infector che infetta file eseguibili (.exe), librerie dinamiche (.dll) e file HTML contenuti nell&rsquo;Hard Disk. Dope aver eseguito un file eseguibile infetto o aver caricato un file .dll infetto, un altro eseguibile viene copiato sul Pc. Viene quindi creata una funzione di auto start per lanciare il file infetto ad ogni reboot. L&rsquo;infector si connette a molteplici server via http o https e scansiona ogni cartella presente sull&rsquo;Hard Disk infettando molti, se non tutti, i file exe, .dll e HTML con un dropper. I file HTML infetti contengono uno script VB che copia il file infector quando un utente apre un sito utilizzando IE. Comunque dalla versione 6.0 IE chiede preventivamente se lo script debba essere lanciato. Worm.Autorun.VHG<br \/>Questo programma malware &egrave; un worm che utilizza la funzione autorun.inf nei sistemi operativi Windows per distribuire se stesso. Utilizza sistemi di archiviazione removibili come le stick USB o gli Hard disk portatili. &Egrave; un internet e network worm che sfrutta la vulnerabilit&agrave; CVE-2008-4250. Trojan.AutorunINF.Gen<br \/>Questo &egrave; un software generico di riconoscimento che identifica file maligni autorun.inf, conosciuti o sconosciuti. I file autorun.inf sono file di auto start che vengono sfruttati per distribuire malware attraverso stick USB, periferiche rimovibili di archiviazione, CD e DVD. Java.Trojan.Downloader.OpenConnection.AN<br \/>Questo Trojan downloader si trova in applet Java manipolate presenti su alcuni siti Internet. Quando l&rsquo;applet viene scaricata, viene generato un URL. Il downloader lo utilizza per scaricare un file eseguibile maligno sul Pc dell&rsquo;utente e lo lancia. Questo downloader sfrutta la vulnerabilit&agrave; CVE-2010-0840 per eludere il Java sandbox e cos&igrave; scrivere dati sul sistema. JS:Redirector-EP [Trj]<br \/>Un redirector reindirizza I visitatori di un sito su un altro sito. Il tutto avviene sfruttando, per esempio, la funzione&rdquo; obfuscation&rdquo; di Javascript in modo che l&rsquo;URL desiderato sia soltanto digitato nel browser dell&rsquo;utente. Il redirector in se stesso non compromette il sistema, ma reindirizza l&rsquo;utente su siti potenzialmente pericolosi senza che l&rsquo;utente lo voglia. Java:Agent-DM [Trj]<br \/>Questo programma malware basato su Java &egrave; un&rsquo;applet di download che sfrutta una falla di sicurezza (CVE-2010-0840) per eludere i meccanismi di protezione sandbox e scaricare malware addizionale sul computer. Una volta che l&rsquo;applet ha ingannato il sandbox, pu&ograve; direttamente scaricare e lanciare file .exe, cosa che una semplice applet non potrebbe fare perch&eacute; bloccata dal Java sandbox. Trojan.JS.Clickjack.A<br \/>Trojan.JS.Clickjack.A &egrave; un Javascript mascherato incorporato su alcuni siti Internet. Come suggerisce il nome stesso , utilizza tecniche di &ldquo;clickjacking&rdquo; per ingannare i visitatori dei sit Internet e farli cliccare su link o contenuti senza che questi siano avvisati. Un IFRAME invisibile viene generato sul sito Internet maligno contenente il bottone &ldquo;mi piace&rdquo; di Facebbok. Il Javascript muove continuamente questo IFRAME con la posizione del cursore e quando l&rsquo;utente clicca sul sito (per esempio sul buttone &ldquo;Play&rdquo; di un sito di video) automaticamente, e senza accorgersene, clicca anche sul buttone &ldquo;mi piace&rdquo; e lo attiva. Java.Trojan.Exploit.Bytverify.N<br \/>Questa minaccia sfrutta una falla di sicurezza presente in Java Bytecode Verifier e presente in applet Java manipolate su certi siti Internet. Questo codice maligno pu&ograve;, per esempio, avviare il download di Trojan, dopodich&eacute; &egrave; possibile prendere il controllo del computer della vittima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I plug-in dei browser pieni di falle per la sicurezza diventano una minaccia reale. G Data analizza la situazione del malware nel mese di Marzo 2011<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[559],"tags":[2033,866],"class_list":["post-15183","post","type-post","status-publish","format-standard","hentry","category-sicurezza","tag-java","tag-malware"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"I plug-in dei browser pieni di falle per la sicurezza diventano una minaccia reale. G Data analizza la situazione del malware nel mese di Marzo 2011\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-19T13:12:14+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java\",\"datePublished\":\"2011-04-19T13:12:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/\"},\"wordCount\":1201,\"commentCount\":0,\"keywords\":[\"java\",\"malware\"],\"articleSection\":[\"Sicurezza\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/\",\"name\":\"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-04-19T13:12:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/sicurezza\\\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/","og_locale":"it_IT","og_type":"article","og_title":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing","og_description":"I plug-in dei browser pieni di falle per la sicurezza diventano una minaccia reale. G Data analizza la situazione del malware nel mese di Marzo 2011","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/","og_site_name":"Article Marketing","article_published_time":"2011-04-19T13:12:14+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java","datePublished":"2011-04-19T13:12:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/"},"wordCount":1201,"commentCount":0,"keywords":["java","malware"],"articleSection":["Sicurezza"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/","name":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-04-19T13:12:14+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/sicurezza\/g-data-il-50%25252525-della-top-10-del-malware-di-marzo-prende-di-mira-le-falle-di-sicurezza-di-java\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"G Data: Il 50% della top 10 del malware di Marzo prende di mira le falle di sicurezza di Java"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=15183"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15183\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=15183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=15183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=15183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}