{"id":15595,"date":"2011-05-01T14:19:11","date_gmt":"2011-05-01T12:19:11","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/"},"modified":"2011-05-01T14:19:11","modified_gmt":"2011-05-01T12:19:11","slug":"un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/","title":{"rendered":"Un libro da vivere. Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino."},"content":{"rendered":"<p><strong>Un libro da vivere<\/strong><\/p>\n<p><em>Luned&igrave; 30 maggio 2011 ore 19.00<\/em><br \/><em>Presentazione del libro <\/em><em><strong>L&#8217;Ultima passeggiata<\/strong><\/em><em> di Gabriella Guidi Gambino. <\/em><br \/><em>Accanto all&#8217;autrice, Cinzia Tani e Paola Gelsomino. Inchiesta di Guido Zaccagnini. <\/em><br \/><em>Ricostruzione interattiva di scene e personaggi del romanzo.<\/em><br \/><em>Sala Vittoria Colonna, via Vittoria Colonna, 11<\/em><br \/><em>Roma<\/em><\/p>\n<p><em>Ingresso libero fino a esaurimento posti<\/em><\/p>\n<p><em>&laquo;&Egrave; l&#8217;una di notte. Una ragazza passa veloce sul lungotevere Marzio. &Egrave; vestita di scuro, con abiti dimessi. La vede un giovane impiegato di commercio, di ritorno a casa. Ode un colpo d&#8217;arma da fuoco. Si volta: la ragazza &egrave; scomparsa.&raquo;<\/em><\/p>\n<p>Gabriella Guidi Gambino, scrittrice, poetessa e giornalista romana, incontrer&agrave; i lettori sabato 30 maggio 2011, alle ore 18.30, presso &hellip; in via Vittoria Colonna, per presentare il suo nuovo romanzo <em>L&#8217;Ultima passeggiata<\/em>, Mursia. I personaggi e le situazioni del libro tratto dal delitto romano del lungotevere Marzio del 1918, prenderanno vita all&#8217;interno del salone delle feste di Palazzo Cortese, nel cuore di Roma. <br \/>Gli ospiti saranno introdotti nell&#8217;atmosfera dell&#8217;intrigante noir psicologico attraverso immagini della Roma anni Venti, che li accompagneranno all&rsquo;interno di una suggestiva ricostruzione interattiva di luoghi e personaggi del romanzo. Per la prima volta lo spazio-tempo romanzesco si aprir&agrave; al pubblico, in una dimensione sospesa tra passato e presente. Un vivido affresco dell&#8217;Italia prima e dopo la Grande Guerra, della Roma vivace e godereccia degli anni Dieci e della citt&agrave; sconvolta del decennio successivo, sullo sfondo del quale si giocano le sorti dei personaggi de <em>L&#8217;Ultima passeggiata<\/em>.<br \/>L&#8217;evento coinvolger&agrave; attivamente lo spettatore, guidato lungo un percorso attraverso le pagine del libro, in un viaggio che lo metter&agrave; faccia a faccia con volti, passioni, atmosfere del delitto romano, tenendo in serbo per lui scioccanti colpi di scena. Come la giovane investigatrice del romanzo, sar&agrave; chiamato a ricostruire la storia tassello per tassello, inseguendo una verit&agrave; che quanto pi&ugrave; sembra a portata di mano, tanto pi&ugrave; si rivela inarrivabile.<br \/>Gabriella Guidi Gambino racconter&agrave; la genesi de <em>L&#8217;Ultima passeggiata<\/em>, il percorso che l&#8217;ha portata alla scelta del giallo di cronaca, una storia lontana nel tempo e che tuttavia chiama in causa le eterne passioni dell&#8217;animo umano. Cosa abbia significato affondare la penna in una storia cos&igrave; oscura, nella violenza, nel male e al contempo come questo l&#8217;abbia portata oltre l&#8217;orizzonte della vicenda, alla ricerca di un sentimento di purezza e innocenza.<br \/>Accanto all&#8217;autrice interverranno Cinzia Tani e Paola Gelsomino, esperte delle dinamiche del delitto e del comportamento umano nel sociale, che, guidate dall&#8217;inchiesta di Guido Zaccagnini, condurranno un&#8217;analisi volta a svelare i meccanismi nascosti che muovono il dramma della giovane Beatrice Cortese.<\/p>\n<p><strong>Gabriella Guidi Gambino<\/strong><strong> <\/strong>vive e lavora a Roma. Ha pubblicato i romanzi <em>Venuto da lontano<\/em><em> <\/em>(1979) e <em>Ti scrivo per confessarti<\/em><em> <\/em>(1989), i racconti <em>Alina e altre storie<\/em><em> <\/em>(2000), le raccolte poetiche <em>Terra nuova <\/em>(1986), <em>Segreti silenzi<\/em><em> <\/em>(1993), <em>L&#8217;ombra dei giorni <\/em>(2002) e <em>Dov&#8217;&egrave; il tuo canto <\/em>(2007), la ricerca antologica <em>Parole e Segni<\/em><em> <\/em>(1998). Ha collaborato con quotidiani e riviste, tra cui la &laquo;Fiera letteraria&raquo;, &laquo;la rivista del Cinematografo&raquo; &laquo;il Gazzettino&raquo; e &laquo;il Tempo&raquo;, in rubriche di attualit&agrave; culturale. Ha realizzato servizi televisivi con testi e regie per la Rai. Ha ricevuto il Premio &laquo;Citt&agrave; di Roma&raquo; (1986) per la narrativa inedita, il Premio &laquo;Chianciano&raquo; (1987) per la poesia opera prima e il Premio &laquo;Fregene&raquo; per la poesia (1993). <\/p>\n<p><strong>Paola Gelsomino <\/strong>&egrave; esperta in comunicazione interpersonale, comunicazione sociale, studiosa di comportamento umano sia singolo che applicato alle dinamiche di gruppo. <strong>Analista di fenomeni sociali. Life and Business Coach. <\/strong>Formatore senior in materie dove l&rsquo;individuo &egrave; protagonista in sede lavorativa. Scrittrice di testi, relazioni, libri. Titolare di &ldquo;Agenzia Progresso&rdquo;. Presidente dell&#8217;associazione &ldquo;La Fondazione dell&#8217;Europa&rdquo;. Titolare della collana &ldquo;I Personaggi&rdquo;, storie di imprenditori pubblicate dal gruppo Sigem editori.<\/p>\n<p><strong>Cinzia Tani <\/strong>&egrave; autrice e conduttrice di programmi radiofonici e televisivi Rai, tra cui le rubriche gialle &ldquo;Delitti d&#8217;amore&rdquo; (2004), &ldquo;Misteri e delitti&rdquo; (2005), &ldquo;Delitti&rdquo; (2006), &ldquo;Tutti i particolari di cronaca&rdquo; (2009-2010), le rubriche letterarie &ldquo;Libro e&#8230;&rdquo; e &ldquo;Lezioni di scrittura&rdquo; (2011). Pubblica nel 2011 il suo ultimo libro &ldquo;Io sono un&#8217;assassina. Storie di ragazze che uccidono&rdquo;, Mondadori. Insegna Scrittura alla Luiss di Roma. Ha ricevuto il Premio Scanno, il Premio Campiello, il Premio Presidenza del Consiglio, il Premio Orient-Express, il Premio Fenice-Europa, il Premio Maria Teresa di Lascia, il Premio Internazionale Federico II.<\/p>\n<p><strong>Guido Zaccagnini<\/strong> musicista e compositore, ha firmato le musiche del film &ldquo;Roma, Paris, Barcelona&rdquo; (Premio De Sica 1989); dei documentari &ldquo;Ultimo minuto&rdquo;, &ldquo;Geo e Geo&rdquo;, &ldquo;Il decalogo dei Taliban&rdquo;; di sceneggiati radiofonici e fiction. Come critico musicale ha collaborato con quotidiani, settimanali e riviste specializzate. Ha partecipato a spettacoli teatrali e televisivi e da anni conduce programmi musicali per Radio Tre. Insegna storia della Musica al Conservatorio &ldquo;F. Morlacchi&rdquo; di Perugia e all&#8217;Universit&agrave; &ldquo;Roma Tre&rdquo;.<\/p>\n<p>Info,contatti e accrediti stampa:<\/p>\n<p>INVENTAEVENTI SRL<br \/>Tel 0698188901<br \/>Fax 0698188903<br \/>Cel 3386812902<br \/><a href=\"mailto:carlacaiafa@inventaeventi.com\" class=\"western\">carlacaiafa@inventaeventi.com<\/a><br \/>www.inventaeventi.com<\/p>\n<p>Ufficio stampa Mursia 02 67378502 <br \/>press@mursia.com <br \/>www.mursia.com <br \/>Librerie consigliate:<\/p>\n<p><strong>Libreria Croce<\/strong><br \/>Corso Vittorio Emanuele II, 156<br \/>00186 Roma<\/p>\n<p><strong>Libreria Croce Rossella e C. srl<\/strong><br \/>Viale Cortina d&#8217;Ampezzo, 351<br \/>00135 Roma <\/p>\n<p><strong>Libreria Manzoni<\/strong><\/p>\n<p>Viale dei Parioli, 16 <br \/>00197 Roma <\/p>\n<p><strong>Libreria Maraldi<\/strong><\/p>\n<p>Viale dei Bastioni di Michelangelo, 7<br \/>00192 Roma<\/p>\n<p><strong>Libreria Velitti<\/strong> <\/p>\n<p>Piazza Stefano Jacini, 1<br \/>00191 Roma<\/p>\n<p><strong>Velitti Cartotecnica<\/strong> <br \/>Via Vigna Stelluti, 12<br \/>00191 Roma<\/p>\n<p><strong>Libreria Mursia<\/strong><br \/>Via Galvani, 24<br \/>20124 Milano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 30 maggio 2011 ore 19.00<br \/>Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino. <br \/>Accanto all&#8217;autrice, Cinzia Tani e Paola Gelsomino. Inchiesta di Guido Zaccagnini. <br \/>Ricostruzione interattiva di scene e personaggi del romanzo.<br \/>Sala Vittoria Colonna, via Vittoria Colonna, 11<br \/>Roma<\/p>\n<p>Ingresso libero fino a esaurimento posti<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[88],"tags":[],"class_list":["post-15595","post","type-post","status-publish","format-standard","hentry","category-libri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un libro da vivere. Presentazione del libro L&#039;Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un libro da vivere. Presentazione del libro L&#039;Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 30 maggio 2011 ore 19.00Presentazione del libro L&#039;Ultima passeggiata di Gabriella Guidi Gambino. Accanto all&#039;autrice, Cinzia Tani e Paola Gelsomino. Inchiesta di Guido Zaccagnini. Ricostruzione interattiva di scene e personaggi del romanzo.Sala Vittoria Colonna, via Vittoria Colonna, 11Roma Ingresso libero fino a esaurimento posti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-01T12:19:11+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Un libro da vivere. Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino.\",\"datePublished\":\"2011-05-01T12:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/\"},\"wordCount\":910,\"commentCount\":0,\"articleSection\":[\"Libri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/\",\"name\":\"Un libro da vivere. Presentazione del libro L'Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-05-01T12:19:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un libro da vivere. Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un libro da vivere. Presentazione del libro L'Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/","og_locale":"it_IT","og_type":"article","og_title":"Un libro da vivere. Presentazione del libro L'Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing","og_description":"Luned\u00ec 30 maggio 2011 ore 19.00Presentazione del libro L'Ultima passeggiata di Gabriella Guidi Gambino. Accanto all'autrice, Cinzia Tani e Paola Gelsomino. Inchiesta di Guido Zaccagnini. Ricostruzione interattiva di scene e personaggi del romanzo.Sala Vittoria Colonna, via Vittoria Colonna, 11Roma Ingresso libero fino a esaurimento posti","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/","og_site_name":"Article Marketing","article_published_time":"2011-05-01T12:19:11+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Un libro da vivere. Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino.","datePublished":"2011-05-01T12:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/"},"wordCount":910,"commentCount":0,"articleSection":["Libri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/","name":"Un libro da vivere. Presentazione del libro L'Ultima passeggiata di Gabriella Guidi Gambino. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-05-01T12:19:11+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/un-libro-da-vivere-presentazione-del-libro-lultima-passeggiata-di-gabriella-guidi-gambino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Un libro da vivere. Presentazione del libro L&#8217;Ultima passeggiata di Gabriella Guidi Gambino."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=15595"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15595\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=15595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=15595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=15595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}