{"id":15613,"date":"2011-05-02T11:34:38","date_gmt":"2011-05-02T09:34:38","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/"},"modified":"2011-05-02T11:34:38","modified_gmt":"2011-05-02T09:34:38","slug":"sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/","title":{"rendered":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale"},"content":{"rendered":"<p><a href=\"\/uploads\/images\/u_6440\/thumb_integrazione.gif\" class=\"image\"><br \/><\/a> La sicurezza di un edificio dipende da molti fattori non sempre controllabili: posizione, elementi architettonici crimino-deterrenti, ma anche da fattori controllabili come <strong>l&#8217;autosorveglianza <\/strong> effettuata dagli abitanti stessi dell&#8217;edificio o da attivit&agrave; commerciali che indirettamente svolgono una funzione di sentinella nel controllo dell&#8217;ambiente circostante. Nei condomini di medie-grandi dimensioni tuttavia l&#8217;autosorveglianza &egrave; di difficile attuazione in quanto l&#8217;alto numero di persone presenti nel medesimo edificio diminuisce, se non annulla, il grado di controllo reciproco: non si pu&ograve; conoscere tutte le persone che entrano dal portone! Spesso infatti si incontrano sulle scale persone che non si sono mai viste e ci si chiede se sono effettivamente abitanti del condominio o semplici &ldquo; <strong>infiltrati&rdquo; <\/strong> che possono minare la sicurezza dei reali inquilini. Da quanto appena scritto emerge chiaramente quale sia l&#8217;elemento di debolezza della maggior parte dei complessi condominiali e il rischio a cui si pu&ograve; incorrere. <strong>Le dimensioni del complesso e la struttura archittettonica favoriscono l&#8217;ingresso furtivo di elementi estranei al condominio, con la consequenziale possibilit&agrave; che possano verificarsi aggressioni a scopo di rapina, atti vandalici o sabotatori agli impianti condominiali. <\/strong> Tali rischi, in particolare le aggressioni a scopo di rapina, costituiscono una minaccia, prima che reale, psicologica in quanto limitano considerevolmente la percezione di sicurezza degli abitanti condominiali. Per garantire una ragionevole sicurezza agli spazi condominiali <strong>rivetta sistemi<\/strong> propone soluzioni integrate di sicurezza in grado di elevare considerevolmente la sicurezza effettiva e percepita dei condomini. Le soluzioni proposte integrano soluzioni di: &bull;\t<strong>controllo degli accessi condominiali<\/strong> &bull;\t<strong>videosorveglianza di aree sensibili<\/strong> &bull;\t<strong>controllo con barriere infrarossi-micoonde del perimetro condominiale <\/strong> Tali soluzioni permettono di: &bull;\tsviluppare una strategia preventiva e dissuasoria nei confronti dei malviventi &bull;\taumentare la percezione di sicurezza da parte degli inquilini &bull;\tabbandonare il portierato notturno sostituendolo con un efficace &ldquo;portierato elettronico&rdquo;. (Il risparmio in sicurezza e in soldi &egrave; evidente). &bull;\tAvere un pronto intervento delle forze dell&rsquo;ordine in relazione alle chiamate di allarme. <strong>CONTROLLO ACCESSI CONDOMINIO<\/strong> Il portone condominiale &egrave; l&#8217;unico baluardo difensivo che separa la vostra sicurezza domestica dal mondo esterno: non vi &egrave; mai capitato di temere che qualcuno potesse <strong>replicare <\/strong><strong>le chiavi <\/strong> del portone? (in un condominio le possibilit&agrave; che venga perso un mazzo di chiavi &egrave; molto alto!!). Non vi piacerebbe che qualcuno vi avvisasse sul telefonino se ci fosse qualche tentativo di intrusione furtivo nel palazzo? (qualora un maleintenzionato entrasse in possesso delle chiavi del portone potrebbe nascondersi sulle scale per poi aggredire i nostri cari pi&ugrave; indifesi, un rischio tremendo ma evitabile). Non sarebbe bello poter eliminare l&#8217;uso delle scomode e facilmente replicabili chiavi? La risposta a queste domande &egrave; facile e non pu&ograve; che essere affermativa. Ancora pi&ugrave; facile &egrave; la soluzione a questa serie di problemi: <strong>UN SISTEMA DI CONTROLLO DEGLI ACCESSI<\/strong> Con un sistema di controllo degli accessi &egrave; possibile aprire e chiudere porte, cancelli, garage, serrande e sbarre di parcheggi condominiali, in generale ogni accesso dotato di elettro-serratura o motore. <strong>L&#8217;apertura avviene avvicinando la chiave elettronica <\/strong> o la tessera dotata di transponder all&#8217;antenna ricevente. Il raggio di funzionamento &egrave; di 5 cm dall&#8217;antenna. Tale antenna pu&ograve; essere posizionata, per esempio, all&#8217;interno di scatole per interruttori, murata sotto l&#8217;intonaco, o a vista. <strong>Rivetta Sistemi<\/strong> da oltre 30 anni propone soluzioni di sicurezza integrata semplici ma efficaci in base alle effettive esigenze dell&#8217;utente finale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei grandi condomini si sente maggiormente il bisogno di controllare chi effetivamente entra nello stabile. Per incrementare la sicurezza condominiale bisogna strutturare un sistema di sicurezza integrato costituito da videosorveglianza, controllo elettronico degli accessi e protezione perimetrale.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[129],"tags":[25889,25888,25886,25887],"class_list":["post-15613","post","type-post","status-publish","format-standard","hentry","category-aziende","tag-antintrusione-condominio","tag-controllo-accessi-condominio","tag-sicurezza-condominio","tag-videosorveglianza-condominio-milano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nei grandi condomini si sente maggiormente il bisogno di controllare chi effetivamente entra nello stabile. Per incrementare la sicurezza condominiale bisogna strutturare un sistema di sicurezza integrato costituito da videosorveglianza, controllo elettronico degli accessi e protezione perimetrale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-02T09:34:38+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale\",\"datePublished\":\"2011-05-02T09:34:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/\"},\"wordCount\":568,\"commentCount\":0,\"keywords\":[\"antintrusione condominio\",\"controllo accessi condominio\",\"Sicurezza condominio\",\"videosorveglianza condominio milano\"],\"articleSection\":[\"Aziende\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/\",\"name\":\"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-05-02T09:34:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/","og_locale":"it_IT","og_type":"article","og_title":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing","og_description":"Nei grandi condomini si sente maggiormente il bisogno di controllare chi effetivamente entra nello stabile. Per incrementare la sicurezza condominiale bisogna strutturare un sistema di sicurezza integrato costituito da videosorveglianza, controllo elettronico degli accessi e protezione perimetrale.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/","og_site_name":"Article Marketing","article_published_time":"2011-05-02T09:34:38+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale","datePublished":"2011-05-02T09:34:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/"},"wordCount":568,"commentCount":0,"keywords":["antintrusione condominio","controllo accessi condominio","Sicurezza condominio","videosorveglianza condominio milano"],"articleSection":["Aziende"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/","name":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-05-02T09:34:38+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/sicurezza-integrata-nei-condomini-controllo-accessi-videosorveglianza-e-protezione-perimetrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Sicurezza integrata nei condomini: controllo accessi, videosorveglianza e protezione perimetrale"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=15613"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/15613\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=15613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=15613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=15613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}