{"id":16666,"date":"2011-05-26T11:46:19","date_gmt":"2011-05-26T09:46:19","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/axioma-primo-partner-italiano-di-vaadin\/"},"modified":"2011-05-26T11:46:19","modified_gmt":"2011-05-26T09:46:19","slug":"axioma-primo-partner-italiano-di-vaadin","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/","title":{"rendered":"Axioma primo partner italiano di Vaadin"},"content":{"rendered":"<p>26 maggio 2011, Milano &ndash; <strong>Axioma SpA annuncia oggi la sua partnership con Vaadin<\/strong> che le consentir&agrave; di fornire servizi di sviluppo di <strong>Rich Web Application<\/strong> basate sul <strong>framework open source Vaadin<\/strong>. La partnership con Vaadin consente ad Axioma di offrire architettura, design, e servizi di implementazione con la tecnologia Vaadin per applicazioni web. Axioma ha utilizzato Vaadin in un ambiente J2EE e ha realizzato l&#8217;<strong>integrazione tra Vaadin e Spring<\/strong>. Il risultato di questo lavoro si traduce in <strong>applicazioni web pi&ugrave; efficienti<\/strong>, <strong>sempre disponibili<\/strong>, <strong>affidabili<\/strong> e <strong>pi&ugrave; piacevoli per l&#8217;utente finale<\/strong>. Sono applicazioni che funzionano su <strong>qualsiasi database<\/strong> e usufruibili anche in <strong>ambienti cloud<\/strong>. Inoltre grazie a Vaadin la produttivit&agrave; nello sviluppo di applicazioni web &egrave; cresciuta esponenzialmente. Axioma utilizza Vaadin da diversi anni, durante i quali ha aumentato le sue competenze nello sviluppo di applicazioni con questo framework. Ora, con la partnership, Axioma sar&agrave; ancora pi&ugrave; qualificata per offrire servizi di consulenza e supporto a chiunque voglia sviluppare <strong>applicazioni in Java<\/strong> all&#8217;avanguardia. &ldquo;<em>Grazie a Vaadin, siamo riusciti a ottenere il massimo nella creazione dei nostri prodotti software. Con Axioma Value Application CRM per esempio abbiamo fornito ai nostri clienti soluzioni flessibili e innovative<\/em>&rdquo;, dice Tullio Bettinazzi di Axioma. <br \/><strong>Vaadin &#8211; Interfaccia utente &ldquo;Rich Web&rdquo;<\/strong><br \/>Vaadin &egrave; una tecnologia web open source per sviluppare Rich Internet Application (RIA) in Java. Con stack di sviluppo molto pi&ugrave; semplici, Vaadin offre all&#8217;utente un&#8217;esperienza piacevole sul web.<br \/> &ldquo;<em>Axioma offrir&agrave; in Italia la sua esperienza nello sviluppo di applicazioni web di alto livello basate su Vaadin o su altre tecnologie open source<\/em>&rdquo; dice Sami Ekblad di Vaadin. &ldquo;<em>E noi continueremo a lavorare con loro in stretta collaborazione per massimizzare l&#8217;utilizzo della tecnologia e degli strumenti Vaadin<\/em>&rdquo;. Se vuoi saperne di pi&ugrave; sui servizi di Axioma, visita il sito <a href=\"http:\/\/www.axioma.it\/\">www.axioma.it<\/a> o http:\/\/vaadin.com\/partners\/Axioma<\/p>\n<p>Chi &egrave; Axioma S.p.A. Axioma offre soluzioni software gestionali che creano valore per l&#8217;impresa. Propone soluzioni specifiche per i settori Industria, Servizi, Moda, Turismo, e altre soluzioni gestionali quali la gestione della produzione, il configuratore di prodotto, l&#8217;archiviazione elettronica dei documenti, la business intelligence e il CRM. In particolare il CRM &egrave; una soluzione creata con Vaadin per offrire agli utenti una soluzione pi&ugrave; funzionale, facile da usare, flessibile, piacevole e utila al lavoro di tutti i giorni. L&#8217;applicazione &egrave; stata infatti creata per supportare la forza vendita nella sua ttivit&agrave; quotidiana. Axioma ha stretto inoltre rapporti di partnership con Vaadin, potente piattaforma tecnologica open source per sviluppare con Java applicazioni disponibili via web. Dal 1979, le soluzioni di Axioma hanno aiutato le imprese a creare valore <br \/>Chi &egrave; Vaadin Ltd.<br \/>Vaadin Ltd &egrave; l&#8217;azienda dietro al framework open source Vaadin, usato da migliaia di sviluppatori professionisti in pi&ugrave; di 150 paesi per costruire interfaccia web di alta qualit&agrave;. Per scaricare gratis <br \/>Vaadin Framework, o saperne di pi&ugrave; sugli strumenti add-on, il supporto e i servizi, visita il sito vaadin.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Axioma ha stretto una partnership con Vaadin, il fornitore di framework open source per applicazioni web<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[26813,2551,26814,26810,26812,26811,13890,20372,26815],"class_list":["post-16666","post","type-post","status-publish","format-standard","hentry","category-software","tag-applicazioni-java","tag-axioma","tag-axioma-e-vaadin","tag-framework","tag-framework-axioma","tag-framework-vaadin","tag-spring","tag-vaadin","tag-vaadin-e-axioma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Axioma primo partner italiano di Vaadin - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Axioma primo partner italiano di Vaadin - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Axioma ha stretto una partnership con Vaadin, il fornitore di framework open source per applicazioni web\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-26T09:46:19+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Axioma primo partner italiano di Vaadin\",\"datePublished\":\"2011-05-26T09:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/\"},\"wordCount\":511,\"commentCount\":0,\"keywords\":[\"applicazioni Java\",\"Axioma\",\"axioma e vaadin\",\"framework\",\"framework axioma\",\"framework vaadin\",\"Spring\",\"vaadin\",\"vaadin e axioma\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/\",\"name\":\"Axioma primo partner italiano di Vaadin - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-05-26T09:46:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/axioma-primo-partner-italiano-di-vaadin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Axioma primo partner italiano di Vaadin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Axioma primo partner italiano di Vaadin - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/","og_locale":"it_IT","og_type":"article","og_title":"Axioma primo partner italiano di Vaadin - Article Marketing","og_description":"Axioma ha stretto una partnership con Vaadin, il fornitore di framework open source per applicazioni web","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/","og_site_name":"Article Marketing","article_published_time":"2011-05-26T09:46:19+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Axioma primo partner italiano di Vaadin","datePublished":"2011-05-26T09:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/"},"wordCount":511,"commentCount":0,"keywords":["applicazioni Java","Axioma","axioma e vaadin","framework","framework axioma","framework vaadin","Spring","vaadin","vaadin e axioma"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/","name":"Axioma primo partner italiano di Vaadin - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-05-26T09:46:19+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/axioma-primo-partner-italiano-di-vaadin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Axioma primo partner italiano di Vaadin"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/16666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=16666"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/16666\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=16666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=16666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=16666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}