{"id":17310,"date":"2011-06-14T09:03:07","date_gmt":"2011-06-14T07:03:07","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/"},"modified":"2018-07-10T05:11:26","modified_gmt":"2018-07-10T03:11:26","slug":"per-telepass-il-rischio-di-credito-diventa-una-leva-di-business","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/","title":{"rendered":"Per Telepass il rischio di credito diventa una leva di business"},"content":{"rendered":"<p><strong style=\"mso-bidi-font-weight: normal;\">Milano, 15 giugno 2011<\/strong> &ndash; Telepass ha scelto SAS per far fronte a due necessit&agrave;: sviluppare modelli di rating accurati e valutare il rischio legato alle principali controparti, ad esempio i consorzi di autotrasportatori, soggetti non patrimonializzati la cui affidabilit&agrave; &egrave; difficile da verificare con le tradizionali analisi di bilancio. La soluzione SAS mette a disposizione del management un dashboard direzionale che consente di avere una visione realistica del credito aziendale.<\/p>\n<p><em style=\"mso-bidi-font-style: normal;\">&ldquo;La nostra attivit&agrave; poggia sostanzialmente sul credito, cio&egrave; sul pagamento posticipato da parte del cliente del servizio erogato ai caselli autostradali &#8211; <\/em>spiega <strong style=\"mso-bidi-font-weight: normal;\">Dante Antognoni<\/strong>, Responsabile Amministrazione e Finanza di Telepass<em style=\"mso-bidi-font-style: normal;\">. Mentre il rischio di credito &egrave; minimo per i clienti family o business garantiti dagli istituti finanziari presso cui hanno sottoscritto il contratto, l&#8217;esposizione al rischio pu&ograve; diventare critica nel caso di particolari controparti, come i Consorzi e le Societ&agrave; di servizi degli autotrasportatori&rdquo;.<\/em><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><\/p>\n<p>Si tratta di circa trentacinque controparti che consorziano un numero elevato di trasportatori e che, pur rappresentando una quota limitata della base clienti, generano un fatturato annuo di circa 960 milioni di euro, pari ad un quarto del transato Telepass complessivo (circa 4 miliardi di Euro). <br \/><em style=\"mso-bidi-font-style: normal;\"> <\/em><br \/><em style=\"mso-bidi-font-style: normal;\">&ldquo;Abbiamo scelto SAS perch&eacute; assicura una copertura funzionale completa dell&#8217;intero processo di valutazione del credito&rdquo; <\/em>&ndash; conclude Antognoni<em style=\"mso-bidi-font-style: normal;\">. &ldquo;&Egrave; uno strumento di cui si avverte fortemente l&#8217;esigenza, soprattutto nei confronti di quei clienti non garantiti da istituti finanziari e che potrebbero generare un impatto sul conto economico in termini di perdite su crediti, di qui la necessit&agrave; di un monitoraggio costante e puntuale capace di evidenziare gli indicatori critici&rdquo;.<\/em><\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">TELEPASS<\/strong><br \/>Costituita nel 2007 e controllata dalla societ&agrave; Autostrade per l&rsquo;Italia, svolge attivit&agrave; relative all&rsquo;emissione, commercializzazione e gestione dei sistemi di pagamento elettronico Telepass e Viacard. I numeri di Telepass sono quelli di una grande e solida realt&agrave; capace di garantire fiducia ai suoi partner commerciali e ai suoi clienti. Con oltre 7,5 milioni di Telepass circolanti, di cui 1,3 milioni abbinati alla tessera Premium, nel 2010 la societ&agrave; ha intermediato oltre 4 miliardi di euro di pedaggi.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">SAS<\/strong><br \/>SAS &egrave; la maggiore societ&agrave; di software e servizi di Business Analytics e la pi&ugrave; grande societ&agrave; indipendente nel mercato della Business Intelligence, con oltre 11.000 dipendenti e un fatturato globale di 2,43 miliardi di dollari. Il 23% dei ricavi annuali vengono reinvestiti in Ricerca e Sviluppo. SAS mantiene da 35 anni un trend di crescita e di redditivit&agrave; ininterrotto fin dalla sua fondazione. Attraverso soluzioni innovative fornite nell&rsquo;ambito di un framework integrato e con oltre 50.000 installazioni, SAS aiuta le imprese a migliorare le performance e a veicolare valore aiutando i manager a prendere decisioni migliori in tempi brevi. SAS fornisce dal 1976 alle aziende di tutto il mondo THE POWER TO KNOW&reg;. In Italia dal 1986, oggi ha una struttura di 330 persone operative nelle sedi di Milano, Roma, Mestre e Torino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Telepass ha scelto SAS per sviluppare modelli di rating accurati e valutare il rischio legato alle principali controparti, ad esempio i consorzi di autotrasportatori.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[27416,13180,27415,9801,24326,27414],"class_list":["post-17310","post","type-post","status-publish","format-standard","hentry","category-software","tag-business-analytics","tag-business-intelligence","tag-dante-antognoni","tag-risk-management","tag-sas","tag-telepass"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Per Telepass il rischio di credito diventa una leva di business - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per Telepass il rischio di credito diventa una leva di business - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Telepass ha scelto SAS per sviluppare modelli di rating accurati e valutare il rischio legato alle principali controparti, ad esempio i consorzi di autotrasportatori.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-14T07:03:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T03:11:26+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Per Telepass il rischio di credito diventa una leva di business\",\"datePublished\":\"2011-06-14T07:03:07+00:00\",\"dateModified\":\"2018-07-10T03:11:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/\"},\"wordCount\":497,\"commentCount\":0,\"keywords\":[\"Business Analytics\",\"Business Intelligence\",\"Dante Antognoni\",\"risk management\",\"SAS\",\"Telepass\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/\",\"name\":\"Per Telepass il rischio di credito diventa una leva di business - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-06-14T07:03:07+00:00\",\"dateModified\":\"2018-07-10T03:11:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per Telepass il rischio di credito diventa una leva di business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Per Telepass il rischio di credito diventa una leva di business - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/","og_locale":"it_IT","og_type":"article","og_title":"Per Telepass il rischio di credito diventa una leva di business - Article Marketing","og_description":"Telepass ha scelto SAS per sviluppare modelli di rating accurati e valutare il rischio legato alle principali controparti, ad esempio i consorzi di autotrasportatori.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/","og_site_name":"Article Marketing","article_published_time":"2011-06-14T07:03:07+00:00","article_modified_time":"2018-07-10T03:11:26+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Per Telepass il rischio di credito diventa una leva di business","datePublished":"2011-06-14T07:03:07+00:00","dateModified":"2018-07-10T03:11:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/"},"wordCount":497,"commentCount":0,"keywords":["Business Analytics","Business Intelligence","Dante Antognoni","risk management","SAS","Telepass"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/","name":"Per Telepass il rischio di credito diventa una leva di business - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-06-14T07:03:07+00:00","dateModified":"2018-07-10T03:11:26+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/per-telepass-il-rischio-di-credito-diventa-una-leva-di-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Per Telepass il rischio di credito diventa una leva di business"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/17310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=17310"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/17310\/revisions"}],"predecessor-version":[{"id":60887,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/17310\/revisions\/60887"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=17310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=17310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=17310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}