{"id":18291,"date":"2011-07-15T13:00:28","date_gmt":"2011-07-15T11:00:28","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/"},"modified":"2011-07-15T13:00:28","modified_gmt":"2011-07-15T11:00:28","slug":"workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/","title":{"rendered":"Workshop di webmarketing turistico \u201cPrepariamoci all&#8217;arrivo di Google Panda\u201d"},"content":{"rendered":"<p><strong>Data: 27 luglio 2011 <\/strong><br \/><strong>Luogo: Hotel Ca&#8217; Sagredo, Venezia <\/strong><br \/><strong>Orario: dalle 9 alle 13<\/strong><\/p>\n<p><strong>Google Panda<\/strong>, il nuovo algoritmo del motore di ricerca che ha cambiato le regole di indicizzazione sul web, sta per arrivare in Italia. Vi sentite preparati ad affrontare questa nuova sfida lanciata dal colosso di Mountain View?<\/p>\n<p>Questo sar&agrave; l&#8217;argomento principe del prossimo workshop tenuto da <strong>Venezia.net srl all&#8217;Hotel Ca&#8217; Sagredo, in Venezia, il 27 luglio 2011<\/strong>. I soggetti a cui &egrave; dedicata la giornata di formazione sono i <strong>Manager degli Hotel<\/strong>. <\/p>\n<p> Naturalmente si parler&agrave; anche di<strong> Social Media Marketing<\/strong> e soprattutto di Facebook, il secondo sito web pi&ugrave; visitato al mondo, nonch&eacute; di <strong>Revenue Management,<\/strong> cio&egrave; come determinare l&#8217;hotel pricing a seconda dei segmenti di clientela e del periodo dell&#8217;anno.<\/p>\n<p>Come dicevamo, a breve, anche in Italia sta per approdare <strong>Google Panda.<\/strong> Per ora l&#8217;applicazione di questo nuovo algoritmo &egrave; stata attivata solo in altri paesi, questo ci offre l&#8217;opportunit&agrave; di studiare meglio l&#8217;evolversi della situazione e di arrivare ben preparati. <\/p>\n<p>Se in precedenza, per essere primi su Google, bastava posizionarsi con delle parole chiave precise ed avere tanti link in entrata, adesso conta moltissimo anche <strong>come presentare le informazioni ai tuoi possibili clienti<\/strong>. In particolare, &egrave; importante <strong><em>scrivere in maniera professionale ed approfondita<\/em><\/strong> e fornire contenuti che siano di reale utilit&agrave; per i tuoi lettori.<\/p>\n<p>Il nuovo algoritmo di Google &egrave; ancora imperfetto, acerbo e, durante i primi mesi di lancio sui server, ha finito per investire anche tanti siti di riconosciuta qualit&agrave;, che non si pensava potessero in alcun modo essere penalizzati.<\/p>\n<p>Il segnale di Google comunque &egrave; forte e chiaro: <strong><em>per attirare nuovi visitatori nel vostro sito, bisogna lavorare sui contenuti del portale della struttura alberghiera<\/em><\/strong> e per farlo &egrave; necessario che questo sia dinamico e facilmente implementabile.<\/p>\n<p><strong>Facebook<\/strong>, con i suoi 750 milioni di utenti, &egrave; <strong>il luogo ideale per promuovere la propria struttura alberghiera<\/strong>: nella seconda parte del workshop verranno affrontate le maggiori novit&agrave; su come rendere pi&ugrave; interessante la <strong>pagina facebook dell&#8217;Hotel<\/strong>. Se un tempo l&#8217;utente cercava su Google, oggi la tendenza &egrave; farlo su Facebook e il motivo &egrave; semplice: nei social network, accanto alle informazioni istituzionali, l&#8217;utente pu&ograve; trovare anche i commenti degli altri clienti e quindi farsi un&#8217;idea precisa della<strong> web reputation dell&#8217;albergo.<\/strong> Inoltre non mancher&agrave; di essere trattato anche l&#8217;ingresso nel mondo Social di Google con +1. Per ora &egrave; solo agli inizi ma ha gi&agrave; raggiunto 10 milioni di utenti. <\/p>\n<p>La Venezia.net srl si occupa da anni e con successo di <strong>Revenue Management<\/strong>: questo utile e valido strumento per ottimizzare i profitti dell&#8217;Albergo verr&agrave; brevemente approfondito anch&#8217;esso durante la mattinata.<\/p>\n<p>Si tratta quindi di un workshop assolutamente imperdibile per i Titolari e Direttori d&#8217;Albergo che desiderano essere al passo coi tempi e rendere il loro Hotel la miglior scelta sul web.<\/p>\n<p>Il costo del workshop &egrave; di 30&euro; a persona.<br \/>per maggiori info: tel 0415384485, commerciale3@venezia.net,<a href=\"http:\/\/www.venezianetsrl.com\/\"> www.venezianetsrl.com<\/a><\/p>\n<p><em>Tania Danieli<\/em><br \/><em>Ufficio stampa Venezia.net srl<\/em><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google Panda, il nuovo algoritmo del motore di ricerca che ha cambiato le regole di indicizzazione sul web, sta per arrivare in Italia. Vi sentite preparati ad affrontare questa nuova sfida lanciata dal colosso di Mountain View?<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[565],"tags":[456,440,28283,17866,11976,253,2054],"class_list":["post-18291","post","type-post","status-publish","format-standard","hentry","category-web-marketing","tag-eventi","tag-formazione","tag-google-panda","tag-revenue-management","tag-social-media-marketing","tag-turismo","tag-webmarketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop di webmarketing turistico \u201cPrepariamoci all&#039;arrivo di Google Panda\u201d - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a?cprepariamoci-allarrivo-di-google-pandaa??\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop di webmarketing turistico \u201cPrepariamoci all&#039;arrivo di Google Panda\u201d - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Google Panda, il nuovo algoritmo del motore di ricerca che ha cambiato le regole di indicizzazione sul web, sta per arrivare in Italia. Vi sentite preparati ad affrontare questa nuova sfida lanciata dal colosso di Mountain View?\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-15T11:00:28+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Workshop di webmarketing turistico \u201cPrepariamoci all&#8217;arrivo di Google Panda\u201d\",\"datePublished\":\"2011-07-15T11:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/\"},\"wordCount\":509,\"commentCount\":0,\"keywords\":[\"eventi\",\"formazione\",\"google panda\",\"revenue management\",\"social media marketing\",\"turismo\",\"webmarketing\"],\"articleSection\":[\"Web marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/\",\"name\":\"Workshop di webmarketing turistico \u201cPrepariamoci all'arrivo di Google Panda\u201d - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-07-15T11:00:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/web-marketing\\\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop di webmarketing turistico \u201cPrepariamoci all&#8217;arrivo di Google Panda\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop di webmarketing turistico \u201cPrepariamoci all'arrivo di Google Panda\u201d - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a?cprepariamoci-allarrivo-di-google-pandaa??\/","og_locale":"it_IT","og_type":"article","og_title":"Workshop di webmarketing turistico \u201cPrepariamoci all'arrivo di Google Panda\u201d - Article Marketing","og_description":"Google Panda, il nuovo algoritmo del motore di ricerca che ha cambiato le regole di indicizzazione sul web, sta per arrivare in Italia. Vi sentite preparati ad affrontare questa nuova sfida lanciata dal colosso di Mountain View?","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a?cprepariamoci-allarrivo-di-google-pandaa??\/","og_site_name":"Article Marketing","article_published_time":"2011-07-15T11:00:28+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Workshop di webmarketing turistico \u201cPrepariamoci all&#8217;arrivo di Google Panda\u201d","datePublished":"2011-07-15T11:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/"},"wordCount":509,"commentCount":0,"keywords":["eventi","formazione","google panda","revenue management","social media marketing","turismo","webmarketing"],"articleSection":["Web marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/","name":"Workshop di webmarketing turistico \u201cPrepariamoci all'arrivo di Google Panda\u201d - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-07-15T11:00:28+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/web-marketing\/workshop-di-webmarketing-turistico-a%80cprepariamoci-allarrivo-di-google-pandaa%80%9d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Workshop di webmarketing turistico \u201cPrepariamoci all&#8217;arrivo di Google Panda\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/18291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=18291"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/18291\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=18291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=18291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=18291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}