{"id":1867,"date":"2009-04-27T11:53:14","date_gmt":"2009-04-27T09:53:14","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/yoga-e-tantra-un-nuovo-blog-in-rete\/"},"modified":"2009-04-27T11:53:14","modified_gmt":"2009-04-27T09:53:14","slug":"yoga-e-tantra-un-nuovo-blog-in-rete","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/","title":{"rendered":"Yoga e Tantra un Nuovo Blog in Rete"},"content":{"rendered":"<p style=\"BACKGROUND: white; MARGIN: 0cm 7.5pt 13.5pt 0cm; LINE-HEIGHT: normal\">Anche qui da noi il fenomeno sta dilagando. In pochi anni le riviste che si dedicano a questa disciplina si sono triplicate, da due a sei, e i centri yoga sono in aumento in tutte le citt\u00e0. Si calcola che attualmente, nella penisola ci siano pi\u00f9 di un milione di praticanti. <\/p>\n<p>  Yoga una pratica completa<\/p>\n<p>A dispetto di quello che si crede, \u00e8 la pratica pi\u00f9 completa e antica a noi disponibile, dove il corpo, la mente e lo spirito, vengono allenati per raggiungere un equilibrio perfetto.<\/p>\n<p>Il corpo si modella anche meglio che in una palestra.<\/p>\n<p>Con la pratica, la struttura scheletrica memorizza una postura pi\u00f9 corretta da adottare, correggendo malformazioni radicate dalle cattive abitudini della vita moderna, la massa muscolare si tonifica assumendo forza e resistenza.<\/p>\n<p>  Yoga e la respirazione<\/p>\n<p>Attraverso una corretta respirazione e raccogliendoci in noi stessi per alcuni minuti al giorno, alleniamo la mente ad essere pi\u00f9 stabile.<\/p>\n<p>A livello pratico questo vuole dire acquisire, serenit\u00e0, concentrazione e giusto discernimento per tutte le complesse decisioni che dobbiamo affrontare nella vita quotidiana.<\/p>\n<p>  Yoga \u00e8 la vita<\/p>\n<p>Possiamo dire che lo yoga \u00e8 il nostro libretto d\u2019istruzioni della vita. Se ci atteniamo ai consigli e suggerimenti espressi negli insegnamenti dai grandi Maestri troveremo serenit\u00e0, salute ed equilibrio nella nostra vita.<\/p>\n<p>  Yoga per tutte le et\u00e0<\/p>\n<p>Lo yoga si adatta tutti, ed \u00e8 una disciplina completa, dove non si ha bisogno di attrezzi speciali perch\u00e9, i pi\u00f9 grandi attrezzi sono il nostro corpo e la nostra mente.<\/p>\n<p>Sviluppare un corpo tonico e flessibile \u00e8 possibile a tutte le et\u00e0.<\/p>\n<p>  Yoga e sport<\/p>\n<p>Lo yoga non \u00e8 considerato uno sport ma \u00e8 la madre di tutti gli sport. Gli atleti di successo lo praticano regolarmente per accrescere le loro prestazioni. Infatti aumentare la capacit\u00e0 polmonare, la concentrazione e diminuisce l\u2019ansia da competizione.<\/p>\n<p>  Yoga \u00e8 felicit\u00e0<\/p>\n<p>Ansia, stress, una miriade di problemi e la qualit\u00e0 della nostra vita decade.<\/p>\n<p><strong>Il blog vuole sfatare l\u2019errata convinzione che lo Yoga sia solo una disciplina ginnica in realt\u00e0 lo yoga \u00e8 anche una incredibile psicotecnica per il potenziamento di s\u00e9 stessi.<\/strong><\/p>\n<p style=\"BACKGROUND: white; MARGIN: 0cm 7.5pt 13.5pt 0cm; LINE-HEIGHT: normal\">Il blog abbraccia varie aree tematiche Veda, Yoga Tantra, Meditazione, Motivazione, per favorire la divulgazione &nbsp;saranno disponibili sul sito risorse gratuite come &nbsp;video e postcast.<\/p>\n<p style=\"BACKGROUND: white; MARGIN: 0cm 7.5pt 13.5pt 0cm; LINE-HEIGHT: normal\">Venendo dal mondo editoriale sar\u00e0 dato ampio spazio ad &nbsp;interviste a personalit\u00e0 di livello internazionale che si sono distinte per i loro studi ed i loro insegnamenti.<\/p>\n<p style=\"MARGIN: 0cm 0cm 10pt\">Il blog&nbsp; vuole essere una comunit\u00e0 che condivide &nbsp;esperienze e&nbsp; teorie, chiunque pu\u00f2 collaborare inviando articoli, commenti, materiali.<\/p>\n<p>Non possiamo comprare la felicit\u00e0 al supermercato ma possiamo conquistarla lavorando su noi stessi, e lo yoga \u00e8 una delle vie pi\u00f9 collaudate per arrivarci.<\/p>\n<p style=\"MARGIN: 0cm 0cm 10pt\">Potete visitare il sito all\u2019indirizzo : <a href=\"http:\/\/www.umbertoassandri.com\/\">www.umbertoassandri.com<\/a><\/p>\n<p style=\"MARGIN: 0cm 0cm 10pt\">Namast\u00e8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oltre oceano lo Yoga \u00e8 diventato un fenomeno di massa. Alla mattina prima di andare al lavoro da Toronto, Vancouver, Seattle o New York, l\u2019impiegato di banca, la top manager, lo studente o la casalinga, si ritrovano in un centro per praticare yoga.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[154],"tags":[979,5950,1239],"class_list":["post-1867","post","type-post","status-publish","format-standard","hentry","category-web","tag-blog","tag-tantra","tag-yoga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yoga e Tantra un Nuovo Blog in Rete - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga e Tantra un Nuovo Blog in Rete - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Oltre oceano lo Yoga \u00e8 diventato un fenomeno di massa. Alla mattina prima di andare al lavoro da Toronto, Vancouver, Seattle o New York, l\u2019impiegato di banca, la top manager, lo studente o la casalinga, si ritrovano in un centro per praticare yoga.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-27T09:53:14+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Yoga e Tantra un Nuovo Blog in Rete\",\"datePublished\":\"2009-04-27T09:53:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/\"},\"wordCount\":460,\"commentCount\":0,\"keywords\":[\"blog\",\"tantra\",\"yoga\"],\"articleSection\":[\"Web\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/\",\"name\":\"Yoga e Tantra un Nuovo Blog in Rete - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-04-27T09:53:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/yoga-e-tantra-un-nuovo-blog-in-rete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yoga e Tantra un Nuovo Blog in Rete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yoga e Tantra un Nuovo Blog in Rete - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/","og_locale":"it_IT","og_type":"article","og_title":"Yoga e Tantra un Nuovo Blog in Rete - Article Marketing","og_description":"Oltre oceano lo Yoga \u00e8 diventato un fenomeno di massa. Alla mattina prima di andare al lavoro da Toronto, Vancouver, Seattle o New York, l\u2019impiegato di banca, la top manager, lo studente o la casalinga, si ritrovano in un centro per praticare yoga.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/","og_site_name":"Article Marketing","article_published_time":"2009-04-27T09:53:14+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Yoga e Tantra un Nuovo Blog in Rete","datePublished":"2009-04-27T09:53:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/"},"wordCount":460,"commentCount":0,"keywords":["blog","tantra","yoga"],"articleSection":["Web"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/","name":"Yoga e Tantra un Nuovo Blog in Rete - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-04-27T09:53:14+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/yoga-e-tantra-un-nuovo-blog-in-rete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Yoga e Tantra un Nuovo Blog in Rete"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}