{"id":18999,"date":"2011-08-20T18:24:34","date_gmt":"2011-08-20T16:24:34","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/ville-giardini-e-palazzi-a-firenze\/"},"modified":"2018-07-10T04:20:47","modified_gmt":"2018-07-10T02:20:47","slug":"ville-giardini-e-palazzi-a-firenze","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/","title":{"rendered":"Ville, giardini e palazzi a Firenze"},"content":{"rendered":"<p><strong>Palazzo Nonfinito<\/strong> <br \/> Il suo nome dice gi&agrave; molto sul questo palazzo: non fu mai terminato, n&eacute; all&#8217;esterno n&egrave; all&#8217;interno. Voluto nel 1592 da Alessandro Strozzi, fu progettato da Buontalenti, ma alterne vicende fecero s&igrave; che la sua edificazione prosegu&igrave; prima con G. Battista Caccini e con il Cigoli poi, fino ai primi del Seicento. Una leggenda narra che il palazzo fu voluto da un giovane amante del gioco e dissipatore di patrimoni affidato ad Alessandro Strozzi che, al fine di vedere terminata la propria residenza nell&#8217;arco di un anno stipul&ograve; un patto con il diavolo promettendo in cambio la propria anima, ma quando fu tempo di eseguire le decorazioni il giovane chiese fregi a carattere sacro ed il diavolo si dilegu&ograve; in un lampo maledicendolo e gridando &ldquo;non finito, non finito!&rdquo;.<br \/> Oggi &egrave; sede del Museo di Antropologia ed Etnologia dell&#8217;Universit&agrave; di Firenze, fondato nel 1869 ad opera del famoso studioso di antropologia Paolo Mantegazza.<br \/>\n<strong>Opificio delle Pietre Dure<\/strong><br \/> La manifattura fu fondata da Ferdinando I de&#8217; Medici nel 1588 ed ebbe come sede iniziale il Casino San Marco e poi il piano terra degli Uffizi fino al definitivo trasferimento, sul finire del &#8216;700, nell&#8217;ex monastero di San Niccol&ograve; a Cafaggio.<br \/> Dal 1952 vi ha sede un museo accanto ad un moderno centro specializzato nel restauro, La fisionomia del Museo non corrisponde ad una precisa volont&agrave; collezionistica, ma &egrave; piuttosto riflesso della vita e delle vicende della secolare attivit&agrave; produttiva. Le creazioni pi&ugrave; prestigiose, oggetto sovente di dono da parte dei granduchi fiorentini, sono conservate nelle regge e nei musei di tutta Europa, mentre nei laboratori di produzione sono rimaste opere incompiute, o risultato di modifiche e smontaggi successivi. Questa raccolta, che comprende esemplari di grande suggestione e raffinatezza, &egrave; comunque sufficiente a delineare un percorso storico della manifattura che si snoda attraverso tre secoli. Resta inoltre un&#8217;importante riserva di marmi antichi e di pietre dure raccolte in funzione della tecnica del commesso.<br \/>\n<strong>Palazzo dell&#8217;Arte della Lana<\/strong><br \/> L&#8217;edificio, costruito alla fine del secolo XIIl dalla potentissima corporazione dell&#8217;Arte della Lana, che ne fece la propria sede a partire dal 1308 &egrave; formato da una casa-torre cui si addossa una costruzione pi&ugrave; bassa. In quegli anni infatti la produzione e lavorazione della lana rappresentava una fiorentissima attivit&agrave; per Firenze in citt&agrave; erano attivi ben 300 laboratori che lavoravano oltre 100.000 pezze di tessuto l&#8217;anno, impegnando un terzo della popolazione attiva di Firenze.<\/p>\n<p><strong>Le Ville Universitarie alle porte di Firenze<\/strong><br \/> A testimonianza del profilo e della tradizione cosmopolita del capoluogo toscano, citiamo alcuni edifici tanto pregevoli dal punto di vista architettonico quanto particolari per la loro odierna destinazione d&#8217;uso: si tratta di Villa I Tatti e Villa Schifanoia, Villa Le Balze, Villa La Pietra<br \/>\n<strong>Villa I Tatti<\/strong>: nel 1900, Bernard Berenson, eminente storico e critico dell&#8221;arte tardo medievale e rinascimentale, stabil&igrave; qui la propria residenza e vi visse fino alla sua morte nel 1959 . Egli lasci&ograve; in eredit&agrave; la propriet&agrave; e la sua ricca collezione di libri, fotografie e opere d&#8217;arte alla Harvard University, che vi ha stabilito la sede del Centro di Studi del Rinascimento Italiano.<br \/>\n<strong>Villa Schifanoia<\/strong>: nata sui resti di un antico casale, ha subito nei secoli numerosi rifacimenti, ampliamenti e passaggi di mano. Nel 1927 divenne propriet&agrave; dell&#8217;ambasciatore americano presso la Santa Sede Myron Taylor che vi conserv&ograve; la propria collezione d&#8217;arte e vi allest&igrave; un magnifico giardino all&#8217;italiana. Nel 1986 la tenuta venne acquistata dallo Stato Italiano che la adib&igrave; a Istituto Universitario Europeo.<br \/>\n<strong>Villa Le Balze<\/strong>: Sorge su di un versante della collina nei pressi di Fiesole. Fu progettata da Cecil Pinsent per volere del filosofo americano Charles Augustus Strong. Ceduta dalla figlia di Strong nel dicembre del 1979 alla Georgetown University per volont&agrave; del padre, ospita ora gli studenti dell&#8217;ateneo durante il loro soggiorno di studio della lingua e cultura italiana.<br \/>\n<strong>Villa La Pietra<\/strong>: nel 1400 di propriet&agrave; del banchiere Francesco Sassetti, pass&ograve; nel 1546 alla famiglia Capponi che apport&ograve; alcune modifiche alla costruzione donandole l&#8217;aspetto che possiamo ammirare tutt&#8217;ora. Il magnifico giardino invece fu realizzato dai coniugi Acton. Il figlio Harold, alla propria morte la don&ograve; alla New York University.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; tanto ricca l&#8217;offerta artistica e storica di questa citt\u00e0 e del suo circondario che non \u00e8 possibile esaurirne la descrizione in poche pagine; proveremo quindi a fornire alcune indicazioni utili alla conoscenza ed alla visita di qualcuno degli edifici pi\u00f9 particolari della zona.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-18999","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ville, giardini e palazzi a Firenze - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ville, giardini e palazzi a Firenze - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"E&#039; tanto ricca l&#039;offerta artistica e storica di questa citt\u00e0 e del suo circondario che non \u00e8 possibile esaurirne la descrizione in poche pagine; proveremo quindi a fornire alcune indicazioni utili alla conoscenza ed alla visita di qualcuno degli edifici pi\u00f9 particolari della zona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-20T16:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:20:47+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Ville, giardini e palazzi a Firenze\",\"datePublished\":\"2011-08-20T16:24:34+00:00\",\"dateModified\":\"2018-07-10T02:20:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/\"},\"wordCount\":708,\"commentCount\":0,\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/\",\"name\":\"Ville, giardini e palazzi a Firenze - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-08-20T16:24:34+00:00\",\"dateModified\":\"2018-07-10T02:20:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ville-giardini-e-palazzi-a-firenze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ville, giardini e palazzi a Firenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ville, giardini e palazzi a Firenze - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/","og_locale":"it_IT","og_type":"article","og_title":"Ville, giardini e palazzi a Firenze - Article Marketing","og_description":"E' tanto ricca l'offerta artistica e storica di questa citt\u00e0 e del suo circondario che non \u00e8 possibile esaurirne la descrizione in poche pagine; proveremo quindi a fornire alcune indicazioni utili alla conoscenza ed alla visita di qualcuno degli edifici pi\u00f9 particolari della zona.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/","og_site_name":"Article Marketing","article_published_time":"2011-08-20T16:24:34+00:00","article_modified_time":"2018-07-10T02:20:47+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Ville, giardini e palazzi a Firenze","datePublished":"2011-08-20T16:24:34+00:00","dateModified":"2018-07-10T02:20:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/"},"wordCount":708,"commentCount":0,"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/","name":"Ville, giardini e palazzi a Firenze - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-08-20T16:24:34+00:00","dateModified":"2018-07-10T02:20:47+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ville-giardini-e-palazzi-a-firenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Ville, giardini e palazzi a Firenze"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/18999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=18999"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/18999\/revisions"}],"predecessor-version":[{"id":58769,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/18999\/revisions\/58769"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=18999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=18999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=18999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}