{"id":19006,"date":"2011-08-21T21:02:48","date_gmt":"2011-08-21T19:02:48","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/dolore-al-piede-neuroma-di-morton\/"},"modified":"2018-07-10T04:21:01","modified_gmt":"2018-07-10T02:21:01","slug":"dolore-al-piede-neuroma-di-morton","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/","title":{"rendered":"Dolore al piede : Neuroma di Morton"},"content":{"rendered":"<p>Beh forse tutti non sanno cosa sia il<strong> Neuroma di Morton .<\/strong> E&#8217; una patologia degenerativa di uno o pi&ugrave; nervi plantari. &Egrave; generalmente localizzato nello spazio fra il terzo e il quarto metatarso, ma anche nello spazio tra il secondo e il terzo, tra il quarto e quinto e, molto raramente tra il primo e il secondo. Si tratta di un <strong>dolore al piede<\/strong> fortissimo tanto che costringe a togliersi la calzatura pur di alleviare la sensazione di dolore al piede di tipo nevralgico . Le cause sono molteplici , tra queste ricordiamo :<\/p>\n<ul><\/p>\n<li>uso di calzature eccessivamente strette <\/li>\n<p><\/p>\n<li>portare in maniera prolungata tacchi a spillo <\/li>\n<p><\/p>\n<li>ipercarico avampodalico<\/li>\n<p><\/p>\n<li>alterazioni morfologiche del piede <\/li>\n<p><\/p>\n<li>microtraumi del piede <\/li>\n<p><\/p>\n<li>scompensi di tipo posturale <\/li>\n<p><\/ul>\n<p>Spesso il tutto &egrave; &ldquo;condito&rdquo; da un grosso stress del sistema nervoso che aumenta e accelera la comparsa del<strong> neuroma di Morton<\/strong> ! Cosa fare quindi quando ci si trova ad affrontare un tale <strong>dolore al piede<\/strong> ? Sicuramente a mio parere la cosa pi&ugrave; sbagliata e fasciare o peggio ancora ingessare il piede . Questo perch&egrave; si limiterebbe la normale circolazione linfatica che in questi casi andrebbe addirittura stimolata per una veloce rigenerazione dei tessuti infiammati ! Sicuramente va alleggerito il carico sul piede , indossate calzature pi&ugrave; comode , controllare che non ci siano microfratture ( lo deve stabilire una lastra ) e farsi visitare da un medico specialista ! Una volta fatti questi passaggi bisogna allentare tutte le fasce muscolari e nervose nel piede ! Personalmente ho avuto sempre grandi risultati ( &#8230;e anche in tempi brevi &hellip;.) nel risolvere questo problema ! Nel video-corso massaggio base spiego come effettuare questi passaggi . L&#8217;accesso &egrave; immediato e gratuito e ti aiuter&agrave; a risolvere molti di questi problemi ! Questi dolori sulla <strong>pianta del piede<\/strong> generalmente durano da qualche settimana a qualche mese !  L&#8217;intento dell&#8217;operatore &egrave; di allentare la tensione muscolare e nervosa del piede ! E&#8217; di fondamentale importanza massaggiare con l&#8217;intento di &ldquo;aprire &ldquo; gli spazi che si trovano tra un metatarso e l&#8217;altro (vedi la direzione delle frecce rosse nella foto qui accanto ) ! Allentando bene questa zona , aumenta lo spazio per il passaggio del nervo ! Quest&#8217;ultimo tende subito a disinfiammarsi se non si trova in una situazione di oppressione e il <strong>dolore al piede<\/strong> ha un improvviso cambio di direzione ! Personalmente ho insegnato queste tecniche a diversi miei clienti ( o meglio &hellip;..ai loro partner &hellip;.) per effettuare il trattamento anche a casa &hellip; Nel prossimo post , parler&ograve; della &#8220;spina calcaneare&#8221; Buon lavoro quindi ! info@zoneriflesse.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri come alleviare il dolore al piede ! Ecco spiegato nello specifico come migliorare il neuroma di Morton senza la chirurgia<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[109],"tags":[28848,28849],"class_list":["post-19006","post","type-post","status-publish","format-standard","hentry","category-medicina-altenativa","tag-dolore-piede","tag-neuroma-di-morton"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dolore al piede : Neuroma di Morton - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolore al piede : Neuroma di Morton - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Scopri come alleviare il dolore al piede ! Ecco spiegato nello specifico come migliorare il neuroma di Morton senza la chirurgia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-21T19:02:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:21:01+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Dolore al piede : Neuroma di Morton\",\"datePublished\":\"2011-08-21T19:02:48+00:00\",\"dateModified\":\"2018-07-10T02:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/\"},\"wordCount\":418,\"commentCount\":0,\"keywords\":[\"dolore piede\",\"neuroma di Morton\"],\"articleSection\":[\"Medicina altenativa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/\",\"name\":\"Dolore al piede : Neuroma di Morton - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-08-21T19:02:48+00:00\",\"dateModified\":\"2018-07-10T02:21:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina-altenativa\\\/dolore-al-piede-neuroma-di-morton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dolore al piede : Neuroma di Morton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolore al piede : Neuroma di Morton - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/","og_locale":"it_IT","og_type":"article","og_title":"Dolore al piede : Neuroma di Morton - Article Marketing","og_description":"Scopri come alleviare il dolore al piede ! Ecco spiegato nello specifico come migliorare il neuroma di Morton senza la chirurgia","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/","og_site_name":"Article Marketing","article_published_time":"2011-08-21T19:02:48+00:00","article_modified_time":"2018-07-10T02:21:01+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Dolore al piede : Neuroma di Morton","datePublished":"2011-08-21T19:02:48+00:00","dateModified":"2018-07-10T02:21:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/"},"wordCount":418,"commentCount":0,"keywords":["dolore piede","neuroma di Morton"],"articleSection":["Medicina altenativa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/","name":"Dolore al piede : Neuroma di Morton - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-08-21T19:02:48+00:00","dateModified":"2018-07-10T02:21:01+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina-altenativa\/dolore-al-piede-neuroma-di-morton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Dolore al piede : Neuroma di Morton"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=19006"}],"version-history":[{"count":3,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19006\/revisions"}],"predecessor-version":[{"id":58777,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19006\/revisions\/58777"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=19006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=19006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=19006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}