{"id":19216,"date":"2011-08-30T16:35:29","date_gmt":"2011-08-30T14:35:29","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/occhio-della-dea\/"},"modified":"2018-07-10T04:21:31","modified_gmt":"2018-07-10T02:21:31","slug":"occhio-della-dea","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/","title":{"rendered":"Occhio della Dea, Stefano GIovanni Muscolino"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg\" border=\"0\" width=\"226\" height=\"320\" \/><br \/>L&#8217;Occhio della Dea, dell&#8217;autore esordiente Stefano Giovanni Muscolino, &egrave; un romanzo d&#8217;avventura d&#8217;ispirazione storica con una buona dose di fantasy, il cui protagonista racconta le sue gesta come se il tutto fosse la sua stessa autobiografia. Per cui il racconto procede in prima persona e si compone in ben 376 pagine suddivise il XXI capitoli, ogni capitolo presenta un&#8217;icona introduttiva realizzata dallo stesso autore. Ma veniamo alla storia vera e propria, Crist&ograve;bal Ortega &egrave; un giovane ragazzo che vive su di un&#8217;isola tropicale nel 1572 governata dagli spagnoli, la sua origine &egrave; mista (da parte di padre spagnolo e da parte di madre indigeno, precisamente della trib&ugrave; dei quemi). Fin da piccolo si ritrova orfano e senza una famiglia a cui far riferimento, viene cresciuto come se fosse suo figlio dal gestore di una taverna, Ferdinandez Valencia, insieme alla di questi figlia legittima Christina. I due ragazzi ormai cresciuti, iniziano a provare qualcosa di pi&ugrave; di una semplice amicizia, ma nessuno dei due &egrave; ancora pronto per dichiararsi. La vita tranquilla di Crist&ograve;bal, come del villaggio, viene per&ograve; interrotta dall&#8217;arrivo di una nave dei corsari, con al capo Sir Henry Murdock. Con la speranza di un lavoro migliore, il giovane verr&agrave; convinto a salire sulla nave, senza per&ograve; rendersi conto di cosa lo attenda, una volta scoperto il trucco sar&agrave; ormai difficile venirne fuori e la sua vita si trasformer&agrave; in un incubo, soprattutto quando dopo la sua fuga dalla nave inglese, sar&agrave; l&#8217;amata Christina a finire catturata. Di qui in poi le cose si complicano e far&agrave; il suo intervento l&#8217;elemento fantasy rappresentato da una ragazza colpita da una maledizione, costretta ad avere l&#8217;aspetto di un&#8217;arpia. La maledizione sar&agrave; legata sia alla nave dei corsari Occhio della Dea, sia alla storia del villaggio e anche alla storia pi&ugrave; intima e personale di Crist&ograve;bal. Sapr&agrave; il nostro eroe risolvere tutti questi enigmi e riportare la pace nel villaggio? naturalmente non sar&agrave; solo, durante le sue avventure conoscer&agrave; diversi amici e preziosi alleati. Il libro &egrave; acquistabile online, sia in versione ebook, pdf o epub, sia in versione classica cartacea. Anche la copertina &egrave; stata creata dallo stesso autore. Su questo romanzo &egrave; stata creata anche una pagina su facebook che potete trovare cercando Occhio della dea, e vi &egrave; anche un blog dedicato non solamente al libro ma anche a quel preciso periodo storico e alla grande passione dell&#8217;autore per pirati e affini. Ogni commento &egrave; ben accetto e anche le critiche o i suggerimenti sono sempre utili per potersi migliorare, per questo l&#8217;autore cerca sempre nuove amicizie in questo difficile campo dell&#8217;editoria. <br \/>Per poterlo acquistare basta andare qui<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Occhio della Dea, romanzo acquistabile online storico e fantasy su pirati ed arpie ambientato su di una piccola isola tropicale sul finire del 1500.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[88],"tags":[28995,28994,28996,28993,1496],"class_list":["post-19216","post","type-post","status-publish","format-standard","hentry","category-libri","tag-arpia","tag-corsari","tag-maledizione","tag-pirati","tag-romanzo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Occhio della Dea, romanzo acquistabile online storico e fantasy su pirati ed arpie ambientato su di una piccola isola tropicale sul finire del 1500.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-30T14:35:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Occhio della Dea, Stefano GIovanni Muscolino\",\"datePublished\":\"2011-08-30T14:35:29+00:00\",\"dateModified\":\"2018-07-10T02:21:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/\"},\"wordCount\":463,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-spaacdXzkMY\\\/TlrCtHr8EdI\\\/AAAAAAAAAik\\\/bF-gYzmFoZs\\\/s1600\\\/Occhio+della+dea.jpg\",\"keywords\":[\"arpia\",\"corsari\",\"maledizione\",\"pirati\",\"romanzo\"],\"articleSection\":[\"Libri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/\",\"name\":\"Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-spaacdXzkMY\\\/TlrCtHr8EdI\\\/AAAAAAAAAik\\\/bF-gYzmFoZs\\\/s1600\\\/Occhio+della+dea.jpg\",\"datePublished\":\"2011-08-30T14:35:29+00:00\",\"dateModified\":\"2018-07-10T02:21:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#primaryimage\",\"url\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-spaacdXzkMY\\\/TlrCtHr8EdI\\\/AAAAAAAAAik\\\/bF-gYzmFoZs\\\/s1600\\\/Occhio+della+dea.jpg\",\"contentUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-spaacdXzkMY\\\/TlrCtHr8EdI\\\/AAAAAAAAAik\\\/bF-gYzmFoZs\\\/s1600\\\/Occhio+della+dea.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/occhio-della-dea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Occhio della Dea, Stefano GIovanni Muscolino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/","og_locale":"it_IT","og_type":"article","og_title":"Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing","og_description":"Occhio della Dea, romanzo acquistabile online storico e fantasy su pirati ed arpie ambientato su di una piccola isola tropicale sul finire del 1500.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/","og_site_name":"Article Marketing","article_published_time":"2011-08-30T14:35:29+00:00","article_modified_time":"2018-07-10T02:21:31+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Occhio della Dea, Stefano GIovanni Muscolino","datePublished":"2011-08-30T14:35:29+00:00","dateModified":"2018-07-10T02:21:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/"},"wordCount":463,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg","keywords":["arpia","corsari","maledizione","pirati","romanzo"],"articleSection":["Libri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/","name":"Occhio della Dea, Stefano GIovanni Muscolino - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg","datePublished":"2011-08-30T14:35:29+00:00","dateModified":"2018-07-10T02:21:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#primaryimage","url":"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg","contentUrl":"http:\/\/3.bp.blogspot.com\/-spaacdXzkMY\/TlrCtHr8EdI\/AAAAAAAAAik\/bF-gYzmFoZs\/s1600\/Occhio+della+dea.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/occhio-della-dea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Occhio della Dea, Stefano GIovanni Muscolino"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=19216"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19216\/revisions"}],"predecessor-version":[{"id":58811,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19216\/revisions\/58811"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=19216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=19216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=19216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}