{"id":19314,"date":"2011-09-02T15:02:07","date_gmt":"2011-09-02T13:02:07","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/"},"modified":"2011-09-02T15:02:07","modified_gmt":"2011-09-02T13:02:07","slug":"il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/","title":{"rendered":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT"},"content":{"rendered":"<p><em>Apre finalmente le porte la struttura siracusana. Decisivo l&#8217;intervento del Gruppo Promos, incaricato di commercializzazione e gestione del centro.<\/em> <\/p>\n<p>Il Melilli Outlet &egrave; situato a meno di 10 km da Siracusa, in un&rsquo;area commerciale integrata facilmente raggiungibile dall&rsquo;uscita Belvedere-Siracusa Nord della Superstrada 114, proseguimento dell&rsquo;Autostrada A18 proveniente da Catania. <br \/>La struttura &egrave; caratterizzata da un design moderno, con una peculiare forma ellittica che conferisce un suggestivo aspetto &ldquo;navale&rdquo; al complesso. Ampie terrazze aperte su pi&ugrave; livelli, affacciate su una piazza centrale dotata di coperture mobili, rendono il Melilli Outlet una <em>shopping destination<\/em> ideale in tutte le stagioni e a pochi passi dalla citt&agrave;. <br \/>Vicino alle splendide spiagge sul Mar Ionio e dagli straordinari siti archeologici di Siracusa, il Melilli Outlet potr&agrave; intercettare il grande flusso turistico che interessa la zona con 3,5 milioni di arrivi all&rsquo;anno e godere anche di un ampio bacino d&rsquo;utenza stanziale, con oltre 1 milione di residenti nell&rsquo;isocrona dei 60 minuti. <\/p>\n<p>Promos S.r.l. si occupa della commercializzazione e della promozione del Melilli Outlet per conto dell&rsquo;immobiliare Tecnall S.r.l., proprietaria della struttura e licenziataria in esclusiva per la Sicilia del marchio &ldquo;Fashion District&rdquo;. <br \/>La gestione del centro &egrave; inoltre stata affidata a Promanagement S.r.l., societ&agrave; del Gruppo Promos. <br \/>L&rsquo;investimento complessivo, finanziato da UniCredit, &egrave; di 75 milioni di euro. <\/p>\n<p>Lo sviluppo del progetto prevede l&#8217;inaugurazione, il prossimo 16 settembre, di una prima fase di 15.000 mq di superficie commerciale e la successiva apertura di una seconda fase, che porter&agrave; la struttura a coprire un&#8217;area complessiva di 24.000 mq. <\/p>\n<p><em>&ldquo;La struttura, sul mercato da molto tempo, necessitava di un intervento forte<\/em> &#8211; commenta Carlo Maffioli, Presidente di Promos &#8211; <em>e in questi mesi abbiamo lavorato intensamente per inaugurare i primi negozi nel pi&ugrave; breve tempo possibile. L&#8217;attivit&agrave; di commercializzazione prosegue a pieno ritmo e nuove insegne apriranno i propri punti vendita gi&agrave; nelle settimane immediatamente successive alla soft opening di settembre. Crediamo molto in questa location e siamo convinti che il progetto porter&agrave; benefici all&rsquo;intero distretto della Sicilia orientale, anche in virt&ugrave; delle importanti opportunit&agrave; occupazionali offerte al territorio in un momento economico non facile&rdquo;.<\/em> <\/p>\n<p>A regime, il Melilli Outlet creer&agrave; circa 500 nuovi posti di lavoro, tra dipendenti diretti delle insegne ospitate nella struttura e indotto generato. La societ&agrave; specializzata Gi Group, incaricata dell&rsquo;individuazione dei profili professionali d&#8217;interesse, ha gi&agrave; attivato l&rsquo;indirizzo di posta elettronica <a href=\"mailto:melillioutlet@gigroup.it\">melillioutlet@gigroup.it<\/a> per la raccolta di tutte le candidature in proposito. <\/p>\n<p>A breve verr&agrave; comunicato il programma degli eventi organizzati per il pubblico in occasione dell&rsquo;inaugurazione ufficiale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apre finalmente le porte la struttura siracusana. Decisivo l&#8217;intervento del Gruppo Promos, incaricato di commercializzazione e gestione del centro.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[29075,29076,17460],"class_list":["post-19314","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-melilli-outlet","tag-nuova-apertura","tag-promos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Apre finalmente le porte la struttura siracusana. Decisivo l&#039;intervento del Gruppo Promos, incaricato di commercializzazione e gestione del centro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-02T13:02:07+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT\",\"datePublished\":\"2011-09-02T13:02:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/\"},\"wordCount\":470,\"commentCount\":0,\"keywords\":[\"Melilli Outlet\",\"Nuova apertura\",\"Promos\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/\",\"name\":\"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-09-02T13:02:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/","og_locale":"it_IT","og_type":"article","og_title":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing","og_description":"Apre finalmente le porte la struttura siracusana. Decisivo l'intervento del Gruppo Promos, incaricato di commercializzazione e gestione del centro.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/","og_site_name":"Article Marketing","article_published_time":"2011-09-02T13:02:07+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT","datePublished":"2011-09-02T13:02:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/"},"wordCount":470,"commentCount":0,"keywords":["Melilli Outlet","Nuova apertura","Promos"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/","name":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-09-02T13:02:07+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/il-16-settembre-promos-e-tecnall-inaugurano-il-melilli-outlet-licensed-by-fashion-district\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"IL 16 SETTEMBRE PROMOS E TECNALL INAUGURANO IL MELILLI OUTLET LICENSED BY FASHION DISTRICT"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=19314"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19314\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=19314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=19314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=19314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}