{"id":19403,"date":"2011-09-07T09:37:57","date_gmt":"2011-09-07T07:37:57","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/"},"modified":"2011-09-07T09:37:57","modified_gmt":"2011-09-07T07:37:57","slug":"obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/","title":{"rendered":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto?"},"content":{"rendered":"<p>Nonostante la sempre pi&ugrave; incalzante crisi economica, l&rsquo;<strong>obesit&agrave;<\/strong> in Italia, nello specifico quella <strong>infantile<\/strong>, sembra paradossalmente non conoscere alcun trend recessivo. Sebbene sembra infatti che sempre pi&ugrave; italiani dovranno tirare la cinghia a causa dello spettro della recessione mondiale, il futuro &ldquo;metabolico&rdquo; degli stessi &egrave; in sovrappeso.<br \/>\n<br \/> I bambini italiani, infatti, secondo il rapporto dell&#8217;International Obesity Task Force, hanno stabilito un record europeo di cui sarebbe meglio non vantarsi: il 36% dei bambini di 8 anni ha <strong>problemi di obesit&agrave;<\/strong> e di sovrappeso. Ma &egrave; tutta la popolazione italiana che aumenta di &#8220;circonferenza&#8221;: secondo il rapporto sull&rsquo;obesit&agrave; in Italia stilato dall&rsquo;Istituto Auxologico Italiano, infatti, il tasso di crescita dell&#8217;obesit&agrave; dell&#8217;intera popolazione ogni 5 anni &egrave; del 2,5%. Non si tratta ovviamente solo di un problema estetico: &#8220;Il sovrappeso &egrave; essenzialmente un problema di salute &#8211; dichiara la dottoressa <strong>Monica Dellupi<\/strong>, psicologa di<strong> <\/strong><strong>Psicologo360<\/strong> specializzata in disturbi dell&#8217;alimentazione &#8211; perch&eacute; all&#8217;obesit&agrave; sono legate patologie importanti e gravi come l&#8217;ipertensione, l&#8217;artrosi, malattie respiratorie e patologie cardiovascolari. Sono conseguenze a lungo termine, ma non per questo si deve far finta che non esistano. Anzi, molto meglio intervenire in tempo piuttosto che correre ai ripari quando i danni hanno assunto oramai proporzioni preoccupanti e di difficile risoluzione&rdquo;.<br \/>\nMa in che modo si pu&ograve; intervenire sui <strong>disturbi alimentari<\/strong>, specie nei bambini?<br \/>&#8220;E&#8217; importante un&#8217;educazione alimentare corretta fin da piccoli e un programma di sostegno psicologico per quei bambini che sono schiavi del cibo &#8211; continua la dottoressa Dellupi &#8211; Nel corso degli anni molti studi hanno messo in evidenza come altri metodi per cos&igrave; dire &#8220;fisici&#8221; (come il bypass gastrico) si siano rivelati palliativi in grado di risolvere il problema per brevissimi periodi di tempo. Le ricadute, tolto il bypass, si verificavano in percentuali altissime. L&rsquo;assistenza psicologica, invece, s&rsquo;&egrave; dimostrata in grado di migliorare sensibilmente il disturbo, portandolo a completa risoluzione nella maggioranza dei casi. L&rsquo;importante quindi, non &egrave; semplicemente imporre una dieta restrittiva o obbligare il bambino a esercizi fisici estenuanti, quanto far capire ai bambini e ai loro genitori, la vera importanza del cibo e dell&rsquo;esercizio fisico, indirizzandoli verso un uso consapevole e non compulsivo&#8221;.<br \/>\n<br \/> <strong>Psicologo360<\/strong> nasce per dare una risposta a queste esigenze, sfruttando al meglio le tecnologie esistenti e mettendo a disposizione un team di esperti altamente qualificati in grado di rispondere con competenza alle richieste di chiunque abbia bisogno di supporto. Il team completo di Psicologo360 &egrave; composto da oltre 20 professionisti che lavorano quotidianamente per offrire sempre un servizio innovativo. La consulenza psicologica online fornita dal team di Psicologo360 offre risposte in tempi brevi, fornendo informazioni e prestando il dovuto supporto psicologico, il tutto garantendo la massima professionalit&agrave; e rispettando quelle che sono le norme indicate dal Codice Deontologico degli Psicologi Italiani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 36% dei bambini di 8 anni ha problemi di obesit\u00e0 e di sovrappeso. Ma \u00e8 tutta la popolazione italiana che aumenta di &#8220;circonferenza&#8221;: secondo il rapporto sull\u2019obesit\u00e0 in Italia stilato dall\u2019Istituto Auxologico Italiano, infatti, il tasso di crescita dell&#8217;obesit\u00e0 dell&#8217;intera popolazione ogni 5 anni \u00e8 del 2,5%. Come invertire questa tendenza?<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[162],"tags":[2207,2401,12794,7768,4492,15321],"class_list":["post-19403","post","type-post","status-publish","format-standard","hentry","category-dieta-e-nutrizione","tag-alimentazione","tag-bambini","tag-disturbi-dellalimentazione","tag-obesita","tag-psicologia","tag-psicologo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il 36% dei bambini di 8 anni ha problemi di obesit\u00e0 e di sovrappeso. Ma \u00e8 tutta la popolazione italiana che aumenta di &quot;circonferenza&quot;: secondo il rapporto sull\u2019obesit\u00e0 in Italia stilato dall\u2019Istituto Auxologico Italiano, infatti, il tasso di crescita dell&#039;obesit\u00e0 dell&#039;intera popolazione ogni 5 anni \u00e8 del 2,5%. Come invertire questa tendenza?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-07T07:37:57+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto?\",\"datePublished\":\"2011-09-07T07:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/\"},\"wordCount\":487,\"commentCount\":0,\"keywords\":[\"alimentazione\",\"bambini\",\"disturbi dell'alimentazione\",\"obesit\u00e0\",\"psicologia\",\"psicologo\"],\"articleSection\":[\"Dieta e Nutrizione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/\",\"name\":\"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-09-07T07:37:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/","og_locale":"it_IT","og_type":"article","og_title":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing","og_description":"Il 36% dei bambini di 8 anni ha problemi di obesit\u00e0 e di sovrappeso. Ma \u00e8 tutta la popolazione italiana che aumenta di \"circonferenza\": secondo il rapporto sull\u2019obesit\u00e0 in Italia stilato dall\u2019Istituto Auxologico Italiano, infatti, il tasso di crescita dell'obesit\u00e0 dell'intera popolazione ogni 5 anni \u00e8 del 2,5%. Come invertire questa tendenza?","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/","og_site_name":"Article Marketing","article_published_time":"2011-09-07T07:37:57+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto?","datePublished":"2011-09-07T07:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/"},"wordCount":487,"commentCount":0,"keywords":["alimentazione","bambini","disturbi dell'alimentazione","obesit\u00e0","psicologia","psicologo"],"articleSection":["Dieta e Nutrizione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/","name":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto? - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-09-07T07:37:57+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/obesita-infantile-in-italia-come-intervenire-per-dare-un-aiuto-concreto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Obesit\u00e0 infantile in Italia: come intervenire per dare un aiuto concreto?"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=19403"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19403\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=19403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=19403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=19403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}