{"id":1952,"date":"2009-05-08T18:39:35","date_gmt":"2009-05-08T16:39:35","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/"},"modified":"2009-05-08T18:39:35","modified_gmt":"2009-05-08T16:39:35","slug":"c3-picasso-il-mondo-dentro-ad-orticola-2009","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/","title":{"rendered":"C3 Picasso: Il mondo dentro ad Orticola 2009"},"content":{"rendered":"<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 16pt\">Nell\u2019ambito della rinomata mostra di fiori e piante giunta alla sua 14ma edizione che si terr\u00e0 nei Giardini Pubblici \u2018Indro Montanelli\u2019, Citro\u00ebn ha deciso di sorprendere i visitatori con un progetto affidato al noto designer Angelo Jelmini: C3 PICASSO, UN MONDO DENTRO.<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 16pt\">Gli spazi di C3 Picasso si aprono, cos\u00ec, al mondo del verde per accogliere un vero e proprio paesaggio fatto di giardini, case, colline, alberi. Una space box che pu\u00f2, di fatto, contenere un mondo suggestivo, animato dai suoni tipici del green landscape \u2013 dal cinguettio di uccelli al soffio del vento &#8211; che regalano l\u2019esperienza della natura e dell\u2019aria aperta all\u2019insegna del relax.&nbsp; La magia del mondo green conquista C3 Picasso per trasformarla in una inattesa e sorprendente installazione di green design dove l\u2019audace monovolume di Citro\u00ebn prende forma in un\u2019opera green che conferma i suoi valori e i suoi punti di forza: design, forme d\u2019avanguardia, armonia.<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 17pt\">C3 Picasso \u00e8 nature addicted: i livelli di emissione di CO2 sono tra i migliori della categoria, le motorizzazioni dalle prestazioni brillanti: due diesel che si fregiano del marchio Airdream\u00ae che identifica i veicoli della gamma Citro\u00ebn pi\u00f9 rispettosi dell\u2019ambiente (il motore HDi 90 cv e motore HDi 110 cv FAP) e due benzina che appartengono alla nuova generazione di motori benzina sviluppata in collaborazione con il gruppo BMW (il motore VTi 95 cv e il VTi 120 cv).<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 17pt\">La trasparenza, lo spazio, l\u2019essenzialit\u00e0, la funzionalit\u00e0 e la sicurezza si incontrano nella C3 Picasso per offrire una nuova esperienza di guida. La space box di casa Citro\u00ebn \u00e8 un monovolume spazioso con un design all\u2019avanguardia ed una personalit\u00e0 moderna, affascinante e impertinente. Con 4,08 m di lunghezza, 1,73 m di larghezza e 1,62 m di altezza, regala una luminosit\u00e0 senza precedenti, che lascia spazio alla libert\u00e0 e permette di guidare guardando il mondo da una posizione privilegiata. Il posto guida,infatti, offre una visibilit\u00e0 periferica straordinaria, grazie ad un parabrezza innovativo diviso in tre parti, con montanti sottilissimi e le sedute rialzate.<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 17pt\">Citro\u00ebn C3 Picasso, dal lancio ad oggi, continua ad avere sempre maggiore successo: gli ordini effettivi della vettura sono gi\u00e0 circa 4.000. Il mix di vendite risulta inoltre estremamente equilibrato, vedendo un 49% per le motorizzazioni benzina suddivise in 1.4 e 1.6 e un 51% per le motorizzazioni Diesel: 1.6 HDi 90 cv e 1.6 HDi 110 cv, a conferma del carattere trasversale della vettura.<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt\">Grande apprezzamento ed interesse anche per l\u2019innovativo servizio Free Drive, che, al momento, \u00e8 gi\u00e0 stato acquistato dal 15% dei clienti.<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt\">Free Drive, una proposta ottenibile attraverso il pagamento di una rata mensile, offre un\u2019assoluta libert\u00e0 di movimento grazie all\u2019ampia scelta dei servizi previsti:<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Una nuova C3 Picasso ogni 2 o3 anni<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Garanzia totale<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Polizze assicurative (kasko, furto-incendio, grandine e atti vandalici)<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Manutenzione totale<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Assistenza stradale in tutta Europa<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Sostituzione di un treno di gomme<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Sostituzione di pneumatici su strada in caso di foratura<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Tagliandi con ritiro e consegna dell\u2019auto a domicilio<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 10pt\">\u00b7 Riacquisto con valore garantito dell\u2019auto allo scadere dei 2 o 3 anni<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt\">&nbsp;<\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 17pt\">Con l\u2019operazione GREEN DAYS, Citro\u00ebn C3 Picasso celebra il suo naturale successo.<\/p>\n<p style=\"LINE-HEIGHT: 18pt; TEXT-ALIGN: justify\">Il progetto GREEN DAYS CON C3 PICASSO \u00e8 stato ideato da Weber Shandwick, GoodTimes! e Angelo Jelmini.<\/p>\n<p style=\"LINE-HEIGHT: 18pt; TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"LINE-HEIGHT: 16pt; TEXT-ALIGN: justify\"><strong><em>Breve profilo di Angelo Jelmini<\/em><\/strong><\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 16pt\"><em>Art director, designer e scenografo Angelo Jelmini non \u00e8 nuovo al mondo del green e di Orticola: nel, 2006 insieme alla nota architetto-paesaggista Patrizia Pozzi ha creato l\u2019installazione \u201cIl Giardino Marino\u201d.<\/em><\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 16pt\"><em>Nel 2006\/2007 ha progettato con Patrizia Pozzi il Kitchen Garden per la rivista Ville Giardini presso Ingegnoli.<\/em><\/p>\n<p class=\"Textedesaisie\" style=\"MARGIN: 0cm 0cm 8pt; LINE-HEIGHT: 16pt\"><em>Ha partecipato in qualit\u00e0 di designer, nel 2007, all\u2019installazione \u2018Cow Parade\u2019 con quattro creazioni; nello stesso anno ha inoltre disegnato 3\/4\/3, un sistema vaso-lampada-albero prodotto <\/em><em>da <\/em><em>Serralunga. Nel<\/em><em> 2008, sempre con Patrizia Pozzi, ha creato Milano Green Project, con l\u2019obiettivo di promuovere il design applicato al green. <\/em><em>Si occupa, da sempre, di sviluppare progetti nel campo della moda e del living. Sempre nel 2008 ha disegnato per Italamp le lampade Ramoho, Alberoho e Nidoho.<\/em><\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione di Orticola, a Milano l\u20198, il 9 e il 10 maggio 2009, Citro\u00ebn ha lanciato oggi il secondo appuntamento con i Green Days con C3 Picasso.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[352],"tags":[353,6184,832,6187,6186,1328,6185],"class_list":["post-1952","post","type-post","status-publish","format-standard","hentry","category-auto","tag-auto","tag-c3-picasso","tag-citroen","tag-emissioni","tag-green-days","tag-green-design","tag-orticola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"In occasione di Orticola, a Milano l\u20198, il 9 e il 10 maggio 2009, Citro\u00ebn ha lanciato oggi il secondo appuntamento con i Green Days con C3 Picasso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-08T16:39:35+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"C3 Picasso: Il mondo dentro ad Orticola 2009\",\"datePublished\":\"2009-05-08T16:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/\"},\"wordCount\":661,\"commentCount\":0,\"keywords\":[\"auto\",\"C3 Picasso\",\"citroen\",\"emissioni\",\"green days\",\"green design\",\"Orticola\"],\"articleSection\":[\"Auto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/\",\"name\":\"C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-05-08T16:39:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/c3-picasso-il-mondo-dentro-ad-orticola-2009\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C3 Picasso: Il mondo dentro ad Orticola 2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/","og_locale":"it_IT","og_type":"article","og_title":"C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing","og_description":"In occasione di Orticola, a Milano l\u20198, il 9 e il 10 maggio 2009, Citro\u00ebn ha lanciato oggi il secondo appuntamento con i Green Days con C3 Picasso.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/","og_site_name":"Article Marketing","article_published_time":"2009-05-08T16:39:35+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"C3 Picasso: Il mondo dentro ad Orticola 2009","datePublished":"2009-05-08T16:39:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/"},"wordCount":661,"commentCount":0,"keywords":["auto","C3 Picasso","citroen","emissioni","green days","green design","Orticola"],"articleSection":["Auto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/","name":"C3 Picasso: Il mondo dentro ad Orticola 2009 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-05-08T16:39:35+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/c3-picasso-il-mondo-dentro-ad-orticola-2009\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"C3 Picasso: Il mondo dentro ad Orticola 2009"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}