{"id":19882,"date":"2011-09-22T10:24:17","date_gmt":"2011-09-22T08:24:17","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/"},"modified":"2011-09-22T10:24:17","modified_gmt":"2011-09-22T08:24:17","slug":"marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/","title":{"rendered":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile"},"content":{"rendered":"<p><a href=\"\/uploads\/images\/u_7357\/thumb_G.ASERVIZI_2.gif\" class=\"image\"><img decoding=\"async\" src=\"\/uploads\/images\/u_7357\/thumb_G.ASERVIZI_2.gif\" border=\"0\" \/><\/a>Da un Articolo: <br \/> <em><\/em> Politica: Marcegaglia, io in campo? Assolutamente no ultimo aggiornamento: 15 settembre, ore 12:44 Roma, 15 set. (Adnkronos) &#8211; &#8220;Assolutamente no&#8221;. La presidente di Confindustria, Emma Marcegaglia, torna ad escludere cosi&#8217; una sua possibile discesa in politica. &#8220;E&#8217; la solita logica -risponde a chi le chiede di un suo possibile ingresso in politica- per cui chi dice liberamente e in modo indipendente come stanno le cose, basandosi sui dati e sui fatti vuole scendere in politica: io non lo voglio assolutamente. Sto cercando di fare -prosegue- in un momento difficilissimo il meglio possibile per rappresentare la voce degli imprenditori&#8221;. Da:La Repubblica <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.repubblica.it\/static\/images\/homepage\/2010\/logo_repubblico.gif\" border=\"0\" alt=\"Repubblica.it: il quotidiano online con tutte le notizie in tempo reale.\" width=\"260\" height=\"54\" \/> Marcegaglia: &#8220;Sacrifici per tutti<br \/> tranne la politica, inaccettabile&#8221; La leader degli industriali: &#8220;Tema che va affrontato subito&#8221;. Cos&igrave; anche Veltroni: &#8220;Sui tagli bisogna decidere in queste ore per un segnale di responsabilit&agrave;&#8221;. Fini e Schifani si apprestano a presentare tagli ai costi di Camera e Senato per 110 e 120 milioni di euro nel triennio 2011-2014. Renzi attacca ancora le Province: &#8220;Un pezzo della casta&#8221; <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.repubblica.it\/images\/2011\/07\/20\/161920149-62a70f06-c76b-467e-b937-763f3e2c87ef.jpg\" border=\"0\" alt=\"Marcegaglia: &quot;Sacrifici per tutti tranne la politica, inaccettabile&quot;\" title=\"Marcegaglia: &quot;Sacrifici per tutti tranne la politica, inaccettabile&quot;\" width=\"300\" height=\"450\" \/> <strong>ROMA <\/strong>&#8211; La manovra che chiede sacrifici a tutti senza intaccare il &#8220;Palazzo&#8221; continua a far discutere, con toni che crescono 1 di giorno in giorno. Dopo la bozza di riforma costituzionale 2 di Calderoli e le proposte del Pd 3, sul dibattito oggi si erge la voce di <strong>Emma Marcegaglia<\/strong>. &#8220;E&#8217; inaccettabile &#8211; dice il presidente di Confindustria &#8211; che tutti facciano sacrifici tranne la politica&#8221;. Quello dei tagli ai costi della politica &#8220;&egrave; un tema che va affrontato subito, e che non pu&ograve; essere rimandato &#8211; sottolinea la leader degli industriali -. Nel momento in cui, con la manovra, si chiedono sacrifici a tutti la politica deve dare il buon esempio. Ci aspettiamo che si arrivi velocemente a un taglio dei costi della politica&#8221;.<\/p>\n<p>&#8220;Velocemente&#8221; connota anche il richiamo di <strong>Walter Veltroni<\/strong>, che considera un &#8220;capitolo ineludibile&#8221; il taglio dei costi della politica in un Paese che fa i conti con la crisi. &#8220;Non c&#8217;&egrave; pi&ugrave; tempo &#8211; afferma l&#8217;ex segretario del Pd in un articolo che comparir&agrave; nel prossimo numero della rivista <em>L&#8217;ago e il filo<\/em> &#8211; bisogna decidere in queste ore. Deve venire un segnale di responsabilit&agrave; della politica che corrisponda allo stato d&#8217;animo degli italiani e condivida i sacrifici che ad essi si chiedono&#8221;. &#8220;Bisogna agire con fermezza &#8211; suggerisce Veltroni -, tagliando in maniera decisa e radicale, cominciando dagli emolumenti e dai vitalizi dei parlamentari, costi che appaiono e sono eccessivi e incomprensibili. Questo va fatto insieme a una profonda riorganizzazione della macchina amministrativa per renderla efficiente e meno costosa&#8221;. <\/p>\n<p>Bisogna fare presto. La variabile &#8220;tempo&#8221; sembra essere ben presente nell&#8217;azione del presidente della Camera <strong>Gianfranco Fini<\/strong>, che gi&agrave; domani proporr&agrave; all&#8217;Ufficio di presidenza, dopo averli sottoposti in queste ore ai Questori, tagli ai costi di Montecitorio per circa 110 milioni di euro nel triennio, cifra che si aggiunge ai 60 milioni gi&agrave; decisi nei mesi scorsi. Tra le misure compare il contributo di solidariet&agrave; del 5% ai vitalizi e alle pensioni dei dipendenti che superano i 90 mila euro, come la manovra prevede per tutte le pensioni d&#8217;oro. In pi&ugrave;, per il futuro tanto i vitalizi quanto le pensioni verranno calcolati con il metodo contributivo, come i lavoratori Inps.<\/p>\n<p>Quanto al Senato, il presidente <strong>Renato Schifani<\/strong> si appresta a proporre tagli di circa 120 milioni di euro sui costi di Palazzo Madama per il triennio 2011-2014, concordati con i senatori questori. Secondo lo schema, il senato applicher&agrave; il &#8220;contributo di perequazione&#8221; del 5 e del 10 per cento sui vitalizi degli ex parlamentari e sulle pensioni dei dipendenti che superano, rispettivamente, i 90 e i 150 mila euro. Gi&agrave; nel 2011 il contributo di perequazione porter&agrave; nelle casse statali 1,2 milioni di risparmi. I risparmi raggiungeranno i 3,1 milioni nel 2012 e 3,3 milioni nel 2013.<\/p>\n<p><strong>Matteo Renzi<\/strong>, invece, torna ad attaccare 4 sulla mancata abolizione delle Province, l&#8217;ormai famosa &#8220;occasione mancata&#8221;, con la bocciatura alla Camera, il 5 luglio scorso, della proposta di legge presentata dall&#8217;Italia dei Valori, con l&#8217;astensione del Pd, proprio il partito del sindaco di Firenze. &#8220;Sono un pezzo della cosiddetta casta &#8211; ribadisce oggi Renzi ai microfoni della trasmissione &#8217;24 mattino&#8217; su radio 24 -. Se per un procedimento burocratico uno deve rivolgersi a Circoscrizione, Comune, all&#8217;Ato, alla Comunit&agrave; montana, alla Regione, alla Provincia, all&#8217;Ue e se ci fosse l&#8217;Onu anche quella, con tutti questi livelli le cose non funzionano. Nessuno vuole licenziare i dipendenti della Provincia, mandiamo solo a casa i politici&#8221;. &#8220;In ballo &#8211; aggiunge Renzi, gi&agrave; presidente della provincia di Firenze dal 2004 al 2009 &#8211; ci sono la velocit&agrave; del fare e i costi della politica che deve avere il coraggio di fare alcune cose, per esempio dimezzare il numero dei parlamentari, togliere i vitalizi, dimezzare le indennita&#8221;. Altrimenti, secondo Renzi, &#8220;vorr&agrave; dire che al prossimo giro si voteranno persone che queste cose le fanno e non le dicono&#8221;.<\/p>\n<p>Anche il governatore della Toscana, <strong>Enrico Rossi<\/strong>, rilancia a un &#8220;governo che ha scelto di non decidere&#8221; le sue proposte per una riduzione dei costi della politica. Misure sostanziali, quelle dell&#8217;esponente Pd, come l&#8217;accorpamento delle Province sotto i 500 mila abitanti e fusione dei Comuni sotto i 5 mila abitanti, il dimezzamento dei parlamentari e dei loro stipendi, da portare a livelli europei, l&#8217;abolizione dei vitalizi e dei privilegi nella sanit&agrave; per i parlamentari. &#8220;Anche chi fa politica ha diritto a una pensione &#8211; osserva Rossi -, ma il vitalizio deve essere trasformato in qualcosa di simile a tutte le altri trattamenti previdenziali. Mi auguro che il Consiglio regionale possa su questa questione arrivare rapidamente a un risultato&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il governo ancora una volta non ascolta ne i Sindacati ,ne la Confidustria e non da voce in primis ai cittadini.Contiunua come sempre a fare le stesse uguali manovre finanziarie <br \/>Abbiamo preso dal Blog di Peppe Grillo 120 punti dlla manovra economica dei Cittadini:<br \/>\u2022 I 20 punti della manovra economica dei Cittadini<br \/>Seleziona le proposte a tuo avviso migliori<br \/>\u2022 Le proposte: <br \/> Eliminazione delle consulenze esterne per lo Stato e gli enti locali Recupero dei 98 miliardi di euro evasi dalle societ\u00e0 di slot machines Asta pubblica per i canali del digitale terrestre Copertura finanziaria di ogni opera pubblica Abolizione del denaro contante Ridimensionamento delle spese del Quirinale Legalizzazione e tassazione della prostituzione Abolizione degli incarichi multipli degli amministratori pubblici Adozione di software open source per la Pubblica Amministrazione (P.A.) Sfruttamento e utilizzo degli immobili del demanio da parte dalla P.A. Eliminazione delle agevolazioni fiscali e contributi alla Chiesa Cattolica, tra cui l&#8217;ICI Abolizione dei comuni sotto i 5.000 abitanti Riduzione delle spese militari e rientro immediato dall&#8217;Aghanistan Eliminazione di ogni privilegio a Province e Regioni a statuto speciale Abolizione del finanziamento pubblico ai partiti Abolizione del finanziamento pubblico all&#8217;editoria Conteggio retributivo per tutti e ricalcolo pensioni, inclusi i vitalizi parlamentari Soppressione di tutte le Province Adeguamento stipendi dei politici a media europea e diminuzione del numero parlamentari del 50% Scaricabilit\u00e0 di ogni singola spesa dalle tasse <\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[19],"tags":[29598,29599,29602,29600,29595,29593,29596,29601,29597,29590,29591,29594,29589,29592],"class_list":["post-19882","post","type-post","status-publish","format-standard","hentry","category-politica","tag-assistenza-anziani","tag-assistenza-ospedaliera","tag-baby","tag-baby-sitter","tag-badanti","tag-barista","tag-colf","tag-dama-di-compagnia","tag-domestiche","tag-personale-alberghiero","tag-personale-di-cucina","tag-personale-sala-bar","tag-personale-turistico","tag-stagionali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il governo ancora una volta non ascolta ne i Sindacati ,ne la Confidustria e non da voce in primis ai cittadini.Contiunua come sempre a fare le stesse uguali manovre finanziarie Abbiamo preso dal Blog di Peppe Grillo 120 punti dlla manovra economica dei Cittadini:\u2022 I 20 punti della manovra economica dei CittadiniSeleziona le proposte a tuo avviso migliori\u2022 Le proposte: Eliminazione delle consulenze esterne per lo Stato e gli enti locali Recupero dei 98 miliardi di euro evasi dalle societ\u00e0 di slot machines Asta pubblica per i canali del digitale terrestre Copertura finanziaria di ogni opera pubblica Abolizione del denaro contante Ridimensionamento delle spese del Quirinale Legalizzazione e tassazione della prostituzione Abolizione degli incarichi multipli degli amministratori pubblici Adozione di software open source per la Pubblica Amministrazione (P.A.) Sfruttamento e utilizzo degli immobili del demanio da parte dalla P.A. Eliminazione delle agevolazioni fiscali e contributi alla Chiesa Cattolica, tra cui l&#039;ICI Abolizione dei comuni sotto i 5.000 abitanti Riduzione delle spese militari e rientro immediato dall&#039;Aghanistan Eliminazione di ogni privilegio a Province e Regioni a statuto speciale Abolizione del finanziamento pubblico ai partiti Abolizione del finanziamento pubblico all&#039;editoria Conteggio retributivo per tutti e ricalcolo pensioni, inclusi i vitalizi parlamentari Soppressione di tutte le Province Adeguamento stipendi dei politici a media europea e diminuzione del numero parlamentari del 50% Scaricabilit\u00e0 di ogni singola spesa dalle tasse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-22T08:24:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_7357\/thumb_G.ASERVIZI_2.gif\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile\",\"datePublished\":\"2011-09-22T08:24:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/\"},\"wordCount\":932,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.repubblica.it\\\/static\\\/images\\\/homepage\\\/2010\\\/logo_repubblico.gif\",\"keywords\":[\"ASSISTENZA ANZIANI\",\"ASSISTENZA OSPEDALIERA\",\"BABY\",\"BABY SITTER\",\"BADANTI\",\"BARISTA\",\"COLF\",\"DAMA DI COMPAGNIA\",\"DOMESTICHE\",\"PERSONALE ALBERGHIERO\",\"PERSONALE DI CUCINA\",\"PERSONALE SALA BAR\",\"PERSONALE TURISTICO\",\"STAGIONALI\"],\"articleSection\":[\"Politica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/\",\"name\":\"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.repubblica.it\\\/static\\\/images\\\/homepage\\\/2010\\\/logo_repubblico.gif\",\"datePublished\":\"2011-09-22T08:24:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.repubblica.it\\\/static\\\/images\\\/homepage\\\/2010\\\/logo_repubblico.gif\",\"contentUrl\":\"http:\\\/\\\/www.repubblica.it\\\/static\\\/images\\\/homepage\\\/2010\\\/logo_repubblico.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/politica\\\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/","og_locale":"it_IT","og_type":"article","og_title":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing","og_description":"Il governo ancora una volta non ascolta ne i Sindacati ,ne la Confidustria e non da voce in primis ai cittadini.Contiunua come sempre a fare le stesse uguali manovre finanziarie Abbiamo preso dal Blog di Peppe Grillo 120 punti dlla manovra economica dei Cittadini:\u2022 I 20 punti della manovra economica dei CittadiniSeleziona le proposte a tuo avviso migliori\u2022 Le proposte: Eliminazione delle consulenze esterne per lo Stato e gli enti locali Recupero dei 98 miliardi di euro evasi dalle societ\u00e0 di slot machines Asta pubblica per i canali del digitale terrestre Copertura finanziaria di ogni opera pubblica Abolizione del denaro contante Ridimensionamento delle spese del Quirinale Legalizzazione e tassazione della prostituzione Abolizione degli incarichi multipli degli amministratori pubblici Adozione di software open source per la Pubblica Amministrazione (P.A.) Sfruttamento e utilizzo degli immobili del demanio da parte dalla P.A. Eliminazione delle agevolazioni fiscali e contributi alla Chiesa Cattolica, tra cui l'ICI Abolizione dei comuni sotto i 5.000 abitanti Riduzione delle spese militari e rientro immediato dall'Aghanistan Eliminazione di ogni privilegio a Province e Regioni a statuto speciale Abolizione del finanziamento pubblico ai partiti Abolizione del finanziamento pubblico all'editoria Conteggio retributivo per tutti e ricalcolo pensioni, inclusi i vitalizi parlamentari Soppressione di tutte le Province Adeguamento stipendi dei politici a media europea e diminuzione del numero parlamentari del 50% Scaricabilit\u00e0 di ogni singola spesa dalle tasse","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/","og_site_name":"Article Marketing","article_published_time":"2011-09-22T08:24:17+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_7357\/thumb_G.ASERVIZI_2.gif","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile","datePublished":"2011-09-22T08:24:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/"},"wordCount":932,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.repubblica.it\/static\/images\/homepage\/2010\/logo_repubblico.gif","keywords":["ASSISTENZA ANZIANI","ASSISTENZA OSPEDALIERA","BABY","BABY SITTER","BADANTI","BARISTA","COLF","DAMA DI COMPAGNIA","DOMESTICHE","PERSONALE ALBERGHIERO","PERSONALE DI CUCINA","PERSONALE SALA BAR","PERSONALE TURISTICO","STAGIONALI"],"articleSection":["Politica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/","name":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.repubblica.it\/static\/images\/homepage\/2010\/logo_repubblico.gif","datePublished":"2011-09-22T08:24:17+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#primaryimage","url":"http:\/\/www.repubblica.it\/static\/images\/homepage\/2010\/logo_repubblico.gif","contentUrl":"http:\/\/www.repubblica.it\/static\/images\/homepage\/2010\/logo_repubblico.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/politica\/marcegaglia-for-presidentecosa-ne-pensatenon-sarebbe-meglio-che-scendesse-in-campo-in-campo-politico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Marcegaglia for Presidente?Cosa ne pensate?Impossibile ma non improbabile"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=19882"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/19882\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=19882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=19882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=19882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}