{"id":20072,"date":"2011-09-26T19:51:48","date_gmt":"2011-09-26T17:51:48","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/"},"modified":"2011-09-26T19:51:48","modified_gmt":"2011-09-26T17:51:48","slug":"come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/","title":{"rendered":"Come le fiabe possono condurci alla conoscenza del S\u00e8?"},"content":{"rendered":"<p>L&rsquo;origine delle fiabe ( a qualsiasi latitudine ed in qualsiasi cultura) si perde nella notte dei tempi. &Egrave; diffusa opinione, inoltre, che le fiabe siano tradizionalmente pensate per intrattenere i bambini, ma questo non corrisponde del tutto a verit&agrave;. Lungi dall&rsquo;essere (soltanto) un trastullo per infanti insonni, le fiabe hanno ricoperto, attraverso la storia dell&rsquo;uomo, una valenza magica, onirica, oserei dire quasi rivelatrice. Definite vere e proprie mappe per la guida e lo sviluppo di esseri umani completi, sono caratterizzate e quasi sempre contengono una saggezza di base che pu&ograve; aiutarci a districarci tra le contraddizioni e gli ostacoli che incontriamo sul cammino verso la felicit&agrave;, la realizzazione di noi stessi e la pace interiore. Re e regine, principi e principesse, nani e streghe, non sono soltanto personaggi utili allo svolgimento di una trama fiabesca, ma vengono interpretati dal lettore intuitivamente come elementi della propria psiche, frammenti della nostra stessa personalit&agrave;, con cui dobbiamo fare i conti quotidianamente. Dentro di noi convivono la strega e l&rsquo;orco, che devono essere affrontati o ci consumeranno (divoreranno, appunto) le fate, che rappresentano un&rsquo;antica guida nei territori della sopravvivenza, nelle foreste e nelle lande oscure della nostra psiche; tutti questi personaggi e le loro storie ci ricordano che vale la pena porsi alla ricerca del nostro vero S&egrave;, ossia quel luogo\/non luogo dove tutti i conflitti interiori si esauriscono, dove le trame spezzate delle nostre esistenze si ricompongono, dove finalmente potremo vivere felici per sempre, ovvero nel qui e ora senza tempo. Personaggio ricorrente in una quantit&agrave; smisurata di fiabe &egrave; quello del bambino (o della bambina) del principino o della principessina, alle prese con lo smarrimento di un oggetto (ad esempio il gomitolo d&rsquo;oro).<br \/> In tutti noi &egrave; racchiuso un principe o una principessina, costantemente alla ricerca di quell&rsquo;et&agrave; in cui emanavamo purezza ed innocenza, qualit&agrave; che ancora oggi potremmo irradiare se soltanto ci mettessimo in cammino alla loro ricerca (riscoperta).<\/p>\n<p> Il poeta americano Robert Bly, indica nell&rsquo;et&agrave; di otto anni circa, la perdita del nostro &ldquo;gomitolo d&rsquo;oro&rdquo; simbolico. Dal momento in cui si percepisce questo distacco, lo si elabora e si cerca di porvi rimedio, possono trascorrere anche trenta, quarant&rsquo;anni o addirittura una vita intera alla ricerca spasmodica di qualcosa che non sappiamo bene neppure che cosa sia.<\/p>\n<p> Premessa indispensabile di ogni tipo di ricerca interiore &egrave; riconoscere in noi quel bambino o quella bambina, farli emergere da quegli anfratti bui dell&rsquo;inconscio dove li abbiamo relegati. Questo pu&ograve; costare dolore e smarrimento, la sensazione di avere a che fare con territori ignoti e misteriosi, ma &egrave; qualcosa che va invariabilmente fatto. Le cultura buddista &egrave; forse quella che pi&ugrave; di ogni altra &egrave; riuscita, attraverso i secoli, a rappresentare con un&rsquo;espressione artistica tra le pi&ugrave; raffinate, questi aspetti terrificante della psiche umana. Nel pantheon delle divinit&agrave; buddiste (che non sono, ovviamente, vere e proprie divinit&agrave; ma rappresentazioni di aspetti dell&rsquo;attivit&agrave; della nostra mente) sono presenti tutta una serie di essere demoniaci e figure grottesche, che non sono per&ograve; vissute come prsenze malvagie, ma piuttosto come &ldquo;strumenti&rdquo; da utilizzare (e poi sconfiggere) per sviluppare tutto il potenziale umano che risiede nell&rsquo;essere umano. Lo strumento per compiere tutto ci&ograve; &egrave; ovviamente la meditazione. In una storia della tradizione buddista, ad esempio, per raggiungere l&rsquo;uomo imprigionato sotto lo stagno occorre togliere l&rsquo;acqua, secchio dopo secchio, con un lavoro paziente e altamente ripetitivo. Ovviamente ci&ograve; sta a simboleggiare il lavoro interiore teso a prendere coscienza della propria psiche , una sorta di iniziazione. Occorre disciplina e perseveranza per svuotare uno stagno, ma il risultato sar&agrave; la conquista di S&egrave;, la conoscenza dei tortuosi labirinti della propria mente, delle nostre paure ed in generale di tutto ci&ograve; che opprime la nostra crescita spirituale. <\/p>\n<p> Un&#8217;altra importante direzione nello studio della fiaba nasce dalla psicologia di Carl Gustav Jung e della sua scuola. Jung sostiene che ogni essere umano desidera sviluppare le sue innate potenzialit&agrave; e che a questo scopo l&#8217;inconscio e la coscienza devono cooperare. Se questo processo non si sviluppa in modo armonico, ha luogo una reazione dell&#8217;inconscio che si esprime nei sogni, nelle fantasie e nelle fiabe, che mostrano appunto profonde affinit&agrave; presso i popoli di tutto il mondo. Queste modalit&agrave; di relazione sono chiamate da Jung archetipi. Pertanto l&#8217;inconscio pu&ograve; esprimersi nell&#8217;immagine archetipa del grande bosco o del mare che l&#8217;eroe o l&#8217;eroina della fiaba devono attraversare. Jung interpreta anche i personaggi come figure archetipiche. Se l&#8217;eroe, egli dice, non riesce pi&ugrave; ad andare avanti e viene un vecchio in suo aiuto, il vecchio rappresenta uno degli archetipi dell&#8217;anima, del giudizio, della concentrazione mentale, ossia un modello etico di comportamento. Straordinarie analogie si possono rinvenire nello studio delle fiabe, analogie tra culture apparentemente lontane anni luce sul piano dello spazio e addirittura sul piano temporale. Per farti un esempio, ci&ograve; a cui la psicologia occidentale &egrave; giunta soltanto verso la fine del XIX&deg; secolo, il buddismo era riuscito a teorizzarlo ben due millenni prima e grazie ad uno strumento d&rsquo;indagine interiore tra i pi&ugrave; potenti mai messi appunto da essere umano:la meditazione. Termino qui questa breve dissertazione tra fiaba e psiche, spero che ti abbia fornito qualche strumento in pi&ugrave; per dare inizio al pi&ugrave; bello e avvincente tra i viaggi che l&rsquo;uomo possa intraprendere, quello dentro se stesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lungi dall\u2019essere (soltanto) un trastullo per infanti insonni, le fiabe hanno ricoperto, attraverso la storia dell\u2019uomo, una valenza magica, onirica, oserei dire quasi rivelatrice. Definite vere e proprie mappe per la guida e lo sviluppo di esseri umani completi, sono caratterizzate e quasi sempre contengono una saggezza di base che pu\u00f2 aiutarci a districarci tra le contraddizioni e gli ostacoli che incontriamo sul cammino verso la felicit\u00e0, la realizzazione di noi stessi e la pace interiore.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[265],"tags":[17858,29746,29744,29745,13086],"class_list":["post-20072","post","type-post","status-publish","format-standard","hentry","category-salute-e-benessere","tag-buddismo","tag-conoscenza-di-se","tag-fiabe","tag-jung","tag-psiche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%25c3%25a8\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Lungi dall\u2019essere (soltanto) un trastullo per infanti insonni, le fiabe hanno ricoperto, attraverso la storia dell\u2019uomo, una valenza magica, onirica, oserei dire quasi rivelatrice. Definite vere e proprie mappe per la guida e lo sviluppo di esseri umani completi, sono caratterizzate e quasi sempre contengono una saggezza di base che pu\u00f2 aiutarci a districarci tra le contraddizioni e gli ostacoli che incontriamo sul cammino verso la felicit\u00e0, la realizzazione di noi stessi e la pace interiore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%25c3%25a8\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-26T17:51:48+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Come le fiabe possono condurci alla conoscenza del S\u00e8?\",\"datePublished\":\"2011-09-26T17:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/\"},\"wordCount\":954,\"commentCount\":0,\"keywords\":[\"buddismo\",\"conoscenza di s\u00e8\",\"fiabe\",\"jung\",\"psiche\"],\"articleSection\":[\"Salute e benessere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/\",\"name\":\"Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-09-26T17:51:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come le fiabe possono condurci alla conoscenza del S\u00e8?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%25c3%25a8\/","og_locale":"it_IT","og_type":"article","og_title":"Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing","og_description":"Lungi dall\u2019essere (soltanto) un trastullo per infanti insonni, le fiabe hanno ricoperto, attraverso la storia dell\u2019uomo, una valenza magica, onirica, oserei dire quasi rivelatrice. Definite vere e proprie mappe per la guida e lo sviluppo di esseri umani completi, sono caratterizzate e quasi sempre contengono una saggezza di base che pu\u00f2 aiutarci a districarci tra le contraddizioni e gli ostacoli che incontriamo sul cammino verso la felicit\u00e0, la realizzazione di noi stessi e la pace interiore.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%25c3%25a8\/","og_site_name":"Article Marketing","article_published_time":"2011-09-26T17:51:48+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Come le fiabe possono condurci alla conoscenza del S\u00e8?","datePublished":"2011-09-26T17:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/"},"wordCount":954,"commentCount":0,"keywords":["buddismo","conoscenza di s\u00e8","fiabe","jung","psiche"],"articleSection":["Salute e benessere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/","name":"Come le fiabe possono condurci alla conoscenza del S\u00e8? - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-09-26T17:51:48+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/come-le-fiabe-possono-condurci-alla-conoscenza-del-s%2525c3%2525a8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Come le fiabe possono condurci alla conoscenza del S\u00e8?"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/20072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=20072"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/20072\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=20072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=20072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=20072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}