{"id":20486,"date":"2011-10-10T09:12:21","date_gmt":"2011-10-10T07:12:21","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/aerosolterapia\/"},"modified":"2011-10-10T09:12:21","modified_gmt":"2011-10-10T07:12:21","slug":"aerosolterapia","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/","title":{"rendered":"Aerosolterapia &#8211; Apparecchi per aerosol a pistone e ultrasuoni"},"content":{"rendered":"<p>La terapia delle affezzioni respiratorie tramite <strong>Aerosol<\/strong>, si basa sulla tecnica della <strong>nebulizzazione<\/strong> del farmaco che, ridotto in piccole particelle e per il tramite di un mezzo gassoso (aria) riesce a penetrare nelle profondit&agrave; dell&#8217;apparato respiratorio del paziente.<\/p>\n<p>La somministrazione del farmaco avviene tramite l&#8217;utilizzo di <strong><a href=\"http:\/\/www.shoppalo.it\/sport-e-medicina\/aerosol\">apparecchi aerosol<\/a><\/strong>, costituiti da compressori a membrana o pistone, o tramite sistemi a ultrasuoni.<\/p>\n<p>Le particelle nebulizzate hanno una grandezza molto piccola, si arriva a scendere sotto la dimensione di 1 Micron ovvero di un millesimo di millimetro.<br \/>Le particelle del farmaco ridotte a queste piccole dimensioni, riescono a raggiungere con facilit&agrave; i bronchi, gli alveoli polmonari, ecc, penetrando nei meandri dell&#8217;apparato respiratorio.<\/p>\n<p>La <strong>terapia ad Aerosol<\/strong> &egrave; molto usata per curare: tosse, raffreddore, catarro, sinusite, bronchiti ma anche per altre affezzioni sempre a cario dell&#8217;apparato respiratorio.<\/p>\n<p>La tecnica tramite nebulizzazione, offre inoltre il vantaggio della somministrazione locale e quindi consente di utilizzare bassi dosaggi di principi attivi ottenendo l&#8217;effetto desiderato con concentra&shy;zioni pi&ugrave; basse. <br \/>Allo stesso modo gli effetti collaterali su altri organi risultano minori in quanto solo a titolo di esempio il farmaco non &egrave; assunto tramite il metodo tradizionale della pillola e quindi non passa dallo stomaco.<\/p>\n<p>Gli apparecchi aerosolt, sono di diverso tipo e offrono prestazioni diverse.<br \/>Tra le caratteristiche salienti vi sono: la grandezza delle particelle nebulizzate, la qualit&agrave; del nebulizzatore e la capacit&agrave; di erogazione.<\/p>\n<p><strong>I nebulizzatori pneumatici<\/strong> sono costituiti da un&#8217;ampolla e da un compressore.<br \/>Viene forzato un getto d&#8217;aria (flusso) dentro l&#8217;ampolla che tramite la differenza di pressione risucchia piccole quantit&agrave; di farmaco che nel frattempo ha ridotto in piccolissime goccioline.<\/p>\n<p><strong>I nebulizzatori ad ultrasuoni<\/strong>, pi&ugrave; silenziosi di quelli a tecnologia pneumatica, riducono in piccole parti il farmaco per mezzo di una vibrazione generata da una corrente elettrica ad alta frequenza.<\/p>\n<p>Un buon <strong>apparecchio aerosol<\/strong> da solo non basta, chi lo utilizza deve conoscere il modo con cui eseguire la respirazione e soprattutto come tenerlo pulito e igienizzato per evitare la contaminazione di batteri sull&#8217;ampolla o sulle altre parti della macchina.<br \/>La macchina per aerosolterapia va pulita dopo ogni seduta, inoltre in base alle modalit&agrave; indicate dai produttori, &egrave; necessario eseguire le necessarie revisioni periodiche.<br \/>A titolo d&#8217;esempio, la sostituzione dei filtri presenti nell&#8217;ampolla o in altre parti della macchina, soprattutto per evitare la proliferazione di batteri.<\/p>\n<p>Quando discutete col medico dell&#8217;acquisto di un apparecchio aerosol dovete farvi indicare quali caratteristiche deve avere il macchinario per aerosol in quanto deve rispettare le esigenze terapeutiche e le caratteristiche del paziente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo dedicato alla tecnica dell&#8217;Aerosolterapia per la cura delle affezzioni respiratorie.<br \/>Viene spiegato il principio di funzionamento degli apparecchi per Aerosol a pistone e ad ultrasuoni.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[70],"tags":[12305,30077,30076,30075],"class_list":["post-20486","post","type-post","status-publish","format-standard","hentry","category-medicina","tag-aerosol","tag-aerosol-a-pistone","tag-aerosol-a-ultrasuoni","tag-aerosolterapia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Articolo dedicato alla tecnica dell&#039;Aerosolterapia per la cura delle affezzioni respiratorie.Viene spiegato il principio di funzionamento degli apparecchi per Aerosol a pistone e ad ultrasuoni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-10T07:12:21+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Aerosolterapia &#8211; Apparecchi per aerosol a pistone e ultrasuoni\",\"datePublished\":\"2011-10-10T07:12:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/\"},\"wordCount\":431,\"commentCount\":0,\"keywords\":[\"aerosol\",\"aerosol a pistone\",\"aerosol a ultrasuoni\",\"aerosolterapia\"],\"articleSection\":[\"Medicina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/\",\"name\":\"Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-10-10T07:12:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/aerosolterapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aerosolterapia &#8211; Apparecchi per aerosol a pistone e ultrasuoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/","og_locale":"it_IT","og_type":"article","og_title":"Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing","og_description":"Articolo dedicato alla tecnica dell'Aerosolterapia per la cura delle affezzioni respiratorie.Viene spiegato il principio di funzionamento degli apparecchi per Aerosol a pistone e ad ultrasuoni.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/","og_site_name":"Article Marketing","article_published_time":"2011-10-10T07:12:21+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Aerosolterapia &#8211; Apparecchi per aerosol a pistone e ultrasuoni","datePublished":"2011-10-10T07:12:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/"},"wordCount":431,"commentCount":0,"keywords":["aerosol","aerosol a pistone","aerosol a ultrasuoni","aerosolterapia"],"articleSection":["Medicina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/","name":"Aerosolterapia - Apparecchi per aerosol a pistone e ultrasuoni - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-10-10T07:12:21+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/aerosolterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Aerosolterapia &#8211; Apparecchi per aerosol a pistone e ultrasuoni"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/20486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=20486"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/20486\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=20486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=20486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=20486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}