{"id":21468,"date":"2011-11-15T14:32:51","date_gmt":"2011-11-15T13:32:51","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/"},"modified":"2018-07-10T04:54:44","modified_gmt":"2018-07-10T02:54:44","slug":"perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/","title":{"rendered":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti"},"content":{"rendered":"<p>La prima cosa da capire &egrave; in che consiste un corso di perfezionamento; questo &egrave; un corso che consente di apprendere delle nuove capacit&agrave; nell&#8217;ambito della didattica infantile.<br \/>Attraverso la frequenza di un corso di formazione per docenti, l&#8217;insegnante acquisisce una formazione aggiuntiva, un attestato di partecipazione e la possibilit&agrave; di ottenere dei punti per la graduatoria degli insegnanti.<br \/>Oltre a tutti questi meriti, i corsi di aggiornamento permettono di entrare in contatto con nuove opportunit&agrave; di lavoro sempre legate all&#8217;insegnamento.<br \/>Nella memoria collettiva, l&#8217;insegnante lavora nelle scuole ed insegna comodamente seduto in cattedra. Questo approccio didattico sta lentamente morendo e l&#8217;insegnamento si sta dirigendo verso altri metodi.<br \/>Un insegnante, che sia un insegnante della scuola primaria o secondaria, che decide di seguire uno di questi corsi, dovrebbe sceglierlo con un certo criterio e cercando di sceglierne un corso che sia al passo con i tempi.<br \/>L&#8217;insegnante pu&ograve; lavorare tradizionalmente in una scuola ma pu&ograve; anche scegliere di insegnare in altri ambiti. Per esempio una grande richiesta &egrave; nell&#8217;insegnamento delle lingue; sempre pi&ugrave; spesso &egrave; richiesta la professionalit&agrave; di un docente in grado di insegnare le lingue ai bambini.<br \/>Esistono alcuni corsi che preparano i docenti a queste richieste, anche se loro stessi non conoscono l&#8217;inglese o altre lingue straniere.<br \/>Hocus e Lotus &egrave; un approccio alla didattica infantile e allo studio delle lingue straniere; attraverso uno speciale format narrativo, il docente sar&agrave; in grado di insegnarle ai bambini.<br \/>La seriet&agrave; di un corso di formazione per insegnanti va valutata sotto 3 specifici aspetti:<\/p>\n<ul>\n<\/p>\n<li>il corso di aggiornamento deve \tessere riconosciuto dal MIUR<\/li>\n<p><\/p>\n<li>i corsi devono avere degli \tobiettivi validi e utili all&#8217;insegnante<\/li>\n<p><\/p>\n<li>i corsi devono poter offrire \tvalide alternative all&#8217;insegnamento tradizionale<\/li>\n<p>\n<\/ul>\n<p>Molti corsi di perfezionamento per insegnanti nascono su idee alquanto retrograde e spesso sono proposti da strutture non istituzionali. I migliori corsi di perfezionamento sono quelli che nascono da professionisti o da strutture universitarie come il format narrativo nato da una collaborazione con l&#8217;Universit&agrave; di Roma La Sapienza ed altre importantissime universit&agrave; europee.<\/p>\n<p>Perch&egrave; scegliere un corso di perfezionamento che prepara ad insegnare le lingue? Perch&egrave; &egrave; un campo professionale che offre molte opportunit&agrave; di lavoro, anche in proprio. La necessit&agrave; di imparare le lingue sta diventando urgente e sempre pi&ugrave; genitori vogliono che i propri figli siano bambini bilingui<br \/>Il bilinguismo, causa o merito della globalizzazione, &egrave; una concreta esigenza ed ormai non &egrave; pi&ugrave; possibile ignorarla. Un insegnante pu&ograve; scegliere di strutturare un corso di inglese o un corso di qualunque altra lingua che abbia un importanza globale.<br \/>Qualunque corso di perfezionamento si decida di seguire, l&#8217;importante &egrave; farlo con la giusta predisposizione e le giuste nozioni. Quindi, verificare la seriet&agrave; attraverso i meriti delle strutture che propongono questi corsi, verificare l&#8217;approvazione degli enti pubblici e per finire considerare bene la scelta di un corso che apra nuove strade lavorative.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I corsi di perfezionamento sono dei corsi che servono per acquisire una maggiore conoscenza e maggiori abilit\u00e0 lavorative<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[747],"tags":[31073,6062,31072,31074,31075],"class_list":["post-21468","post","type-post","status-publish","format-standard","hentry","category-corsi","tag-corsi-di-formazione-per-docenti","tag-corsi-di-inglese","tag-corsi-di-perfezionamento","tag-insegnare-le-lingue","tag-punteggio-nelle-graduatorie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%c3%a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"I corsi di perfezionamento sono dei corsi che servono per acquisire una maggiore conoscenza e maggiori abilit\u00e0 lavorative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%c3%a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-15T13:32:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:54:44+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti\",\"datePublished\":\"2011-11-15T13:32:51+00:00\",\"dateModified\":\"2018-07-10T02:54:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/\"},\"wordCount\":499,\"commentCount\":0,\"keywords\":[\"corsi di formazione per docenti\",\"Corsi di inglese\",\"corsi di perfezionamento\",\"insegnare le lingue\",\"punteggio nelle graduatorie\"],\"articleSection\":[\"Corsi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/\",\"name\":\"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-11-15T13:32:51+00:00\",\"dateModified\":\"2018-07-10T02:54:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%c3%a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing","og_description":"I corsi di perfezionamento sono dei corsi che servono per acquisire una maggiore conoscenza e maggiori abilit\u00e0 lavorative","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%c3%a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/","og_site_name":"Article Marketing","article_published_time":"2011-11-15T13:32:51+00:00","article_modified_time":"2018-07-10T02:54:44+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti","datePublished":"2011-11-15T13:32:51+00:00","dateModified":"2018-07-10T02:54:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/"},"wordCount":499,"commentCount":0,"keywords":["corsi di formazione per docenti","Corsi di inglese","corsi di perfezionamento","insegnare le lingue","punteggio nelle graduatorie"],"articleSection":["Corsi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/","name":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-11-15T13:32:51+00:00","dateModified":"2018-07-10T02:54:44+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/perch%25c3%25a8-seguire-dei-corsi-di-perfezionamento-per-insegnanti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e8 seguire dei corsi di perfezionamento per insegnanti"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=21468"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21468\/revisions"}],"predecessor-version":[{"id":60211,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21468\/revisions\/60211"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=21468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=21468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=21468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}