{"id":21536,"date":"2011-11-17T17:53:05","date_gmt":"2011-11-17T16:53:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nuovo-studio-su-dieta-diabete-3\/"},"modified":"2018-07-10T04:51:16","modified_gmt":"2018-07-10T02:51:16","slug":"nuovo-studio-su-dieta-diabete-3","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/","title":{"rendered":"Nuovo studio su dieta diabete"},"content":{"rendered":"<p>L&rsquo;importanza di una alimentazione corretta &egrave; nota ed indiscussa e rappresenta uno dei cardini della terapia dietetica nel diabete mellito.<br \/>Varie scuole di pensiero hanno dato nel tempo interpretazioni non sempre univoche su come impostare un programma alimentare mirato ad una <strong>dieta diabete<\/strong><br \/>Importanti le sollecitazioni che, attraverso il Piano Sanitario Nazionale, il Ministero della Salute ha trasmesso alle Associazioni Scientifiche sulla necessit&agrave; di modificare lo stile di vita attraverso una corretta alimentazione, inducendo l&rsquo;Associazione Italiana di Dietetica e Nutrizione Clinica e l&rsquo;Associazione Medici Diabetologi a compiere uno sforzo comune creando un gruppo di studio misto su Diabete e Nutrizione.<br \/>Le finalit&agrave; del gruppo di studio sono quelle di fornire strumenti per aiutare il medico a lavorare al meglio in campo nutrizionale e individuare linee di condotta univoche e razionali.<br \/>In questa pubblicazione viene affrontato l&rsquo;argomento fondamentale e cio&egrave; la stesura di raccomandazioni per la terapia medica nutrizionale del diabete mellito: a tale proposito, pur facendo riferimento agli studi pi&ugrave; recenti in campo nazionale d internazionale, si &egrave; per&ograve; cercato di adattarle allo stile di vita del nostro paese.<br \/>Queste raccomandazioni sono ovviamente sempre in evoluzione e perfettibili ed il compito del gruppo di studio sar&agrave; quello di prodigarsi in modo da fornire alla classe medica strumenti sempre pi&ugrave; aggiornati andando anche ad individuare le esigenze del medico e del paziente al fine di dare un servizio utile nella pratica clinica di tutti i giorni nel campo della terapia dietetica del diabete mellito.<br \/>Le ultime raccomandazioni nutrizionali italiane per il trattamento del diabete mellito sono state stilate nel 2010 dal Gruppo di Studio di Nutrizione della SID e si rifanno a quelle elaborate nel 2005 dal Gruppo Europeo su Diabete e Nutrizione dell&rsquo;EASD.<br \/>Negli ultimi anni diversi studi sono stati effettuati per valutare l&rsquo;effetto dei macroe micronutrienti sul compenso glicometabolico del paziente diabetico.<br \/>L&rsquo;Associazione Italiana di Dietetica e Nutrizione Clinica (ADI) e l&rsquo;Associazione Medici Diabetologi (AMD) avvertono l&rsquo;esigenza di aggiornare le ultime raccomandazioni nutrizionali e ci&ograve; per tre motivi principali:<br \/>1. Nonostante i progressi ottenuti negli ultimi anni nel trattamento farmacologico del paziente diabetico, l&rsquo;alimentazione resta comunque il cardine della terapia del diabete mellito. E&rsquo; quindi importante che il diabetologo e il nutrizionista siano continuamente aggiornati sui nuovi aspetti nutrizionali.<br \/>2. Gli studi nutrizionali degli ultimi dieci anni hanno portato a meglio comprendere il ruolo di alcuni macro e micronutrienti sul compenso glicometabolico e tali conoscenze hanno in parte variato l&rsquo;approccio nutrizionale nel paziente diabetico.<br \/>3. Il Gruppo di Studio su Diabete e Nutrizione dell&rsquo;EASD e, pi&ugrave; recentemente l&rsquo;ADA hanno pubblicato le loro nuove linee guida che, anche se sostanzialmente simili fra di loro, evidenziano in alcuni punti delle differenze dovute principalmente a diverse tradizioni ed abitudini alimentari, ma anche a differente interpretazione di alcuni dati sperimentali.<br \/>Le due Societ&agrave; Scientifiche, pertanto, hanno dato mandato al Gruppo di Studio di Nutrizione e Diabete ADI &#8211; AMD di concordare e sottoporre alle comunit&agrave; scientifiche dietologica e diabetologica le nuove Raccomandazioni Nutrizionali.<br \/>Il gruppo di studio sta elaborando queste nuove Raccomandazioni adattando alle tradizioni alimentari italiane le raccomandazioni del Gruppo di Studio su Diabete e Nutrizione dell&rsquo;EASD che sono sia da un punto di vista scientifico, che per tradizioni alimentari, le pi&ugrave; adatte ai pazienti diabetici italiani e verranno presto rese note. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;importanza di una alimentazione corretta &egrave; nota ed indiscussa e rappresenta uno dei cardini della terapia dietetica nel diabete mellito.Varie scuole di pensiero hanno dato nel tempo interpretazioni non sempre univoche su come impostare un programma alimentare mirato ad una dieta diabeteImportanti le sollecitazioni che, attraverso il Piano Sanitario Nazionale, il Ministero della Salute ha trasmesso alle Associazioni Scientifiche sulla necessit&agrave; di modificare lo stile di vita attraverso una corretta<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[162],"tags":[31123],"class_list":["post-21536","post","type-post","status-publish","format-standard","hentry","category-dieta-e-nutrizione","tag-dieta-diabete"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo studio su dieta diabete - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo studio su dieta diabete - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;importanza di una alimentazione corretta &egrave; nota ed indiscussa e rappresenta uno dei cardini della terapia dietetica nel diabete mellito.Varie scuole di pensiero hanno dato nel tempo interpretazioni non sempre univoche su come impostare un programma alimentare mirato ad una dieta diabeteImportanti le sollecitazioni che, attraverso il Piano Sanitario Nazionale, il Ministero della Salute ha trasmesso alle Associazioni Scientifiche sulla necessit&agrave; di modificare lo stile di vita attraverso una correttaContinue reading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-17T16:53:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:51:16+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Nuovo studio su dieta diabete\",\"datePublished\":\"2011-11-17T16:53:05+00:00\",\"dateModified\":\"2018-07-10T02:51:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/\"},\"wordCount\":581,\"commentCount\":0,\"keywords\":[\"dieta diabete\"],\"articleSection\":[\"Dieta e Nutrizione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/\",\"name\":\"Nuovo studio su dieta diabete - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-11-17T16:53:05+00:00\",\"dateModified\":\"2018-07-10T02:51:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/nuovo-studio-su-dieta-diabete-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo studio su dieta diabete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo studio su dieta diabete - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo studio su dieta diabete - Article Marketing","og_description":"L&rsquo;importanza di una alimentazione corretta &egrave; nota ed indiscussa e rappresenta uno dei cardini della terapia dietetica nel diabete mellito.Varie scuole di pensiero hanno dato nel tempo interpretazioni non sempre univoche su come impostare un programma alimentare mirato ad una dieta diabeteImportanti le sollecitazioni che, attraverso il Piano Sanitario Nazionale, il Ministero della Salute ha trasmesso alle Associazioni Scientifiche sulla necessit&agrave; di modificare lo stile di vita attraverso una correttaContinue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/","og_site_name":"Article Marketing","article_published_time":"2011-11-17T16:53:05+00:00","article_modified_time":"2018-07-10T02:51:16+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Nuovo studio su dieta diabete","datePublished":"2011-11-17T16:53:05+00:00","dateModified":"2018-07-10T02:51:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/"},"wordCount":581,"commentCount":0,"keywords":["dieta diabete"],"articleSection":["Dieta e Nutrizione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/","name":"Nuovo studio su dieta diabete - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-11-17T16:53:05+00:00","dateModified":"2018-07-10T02:51:16+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/nuovo-studio-su-dieta-diabete-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Nuovo studio su dieta diabete"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=21536"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21536\/revisions"}],"predecessor-version":[{"id":60047,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/21536\/revisions\/60047"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=21536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=21536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=21536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}