{"id":22396,"date":"2011-12-14T20:34:21","date_gmt":"2011-12-14T19:34:21","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/sistema-roulette\/"},"modified":"2011-12-14T20:34:21","modified_gmt":"2011-12-14T19:34:21","slug":"sistema-roulette","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/","title":{"rendered":"Sistema Roulette Sistema Roulette"},"content":{"rendered":"<p><strong>Sistema Roulette<\/strong><br \/>Sei alla ricerca di un valido <em>sistema roulette<\/em> ? allora visita <strong>http:\/\/www.sistemaroulette.it<\/strong> Caro lettore oggi voglio presentarti un sistema alquanto semplice ma di grande efficacia.<br \/> Il sistema base del &ldquo;3&deg; Sovrapposto&rdquo; trae fondamento dal fatto che se poniamo uno sotto l&#8217;altro due schemi di quattro posizioni ciascuno, contenenti le otto &#8220;figure di 3&#8221; di una chance semplice, la legge del terzo tende a far coincidere verticalmente, nelle stesse colonne, due delle otto figure ivi inserite. Una volta compreso questo comportamento tendenziale, non abbiamo fatto altro che rilevare quattro &ldquo;figure di 3&rdquo; a &ldquo;iniziale obbligata&rdquo; (che chiameremo Semichances), inserirle nello schema di riferimento superiore, e giocare le stesse figure durante l&rsquo;inserimento di quattro nuove &ldquo;figure di 3&rdquo;, a iniziale obbligata contraria, (ma potrebbe anche essere uguale) nello schema inferiore. Se la tendenza si realizza, almeno due di queste quattro nuove figure dovrebbero coincidere in una colonna comune. Poi, per non subire passivamente la &ldquo;legge sulla distribuzione delle figure&rdquo;, abbiamo messo in campo alcuni accorgimenti come la &ldquo;Prepuntata contraria&rdquo;, o il consiglio finale di alternare il colore dello schema di riferimento con quello di gioco sottostante. Per rendere il gioco pi&ugrave; sicuro, poi, abbiamo deciso di accettare soltanto l&#8217;inserimento di una configurazione ottimale (3 figure presenti e una mancante) e quindi, a seconda di ci&ograve; che era accaduto nella precedente permanenza, stabilivamo le nuove figure da giocare nello schema inferiore, escludendo dal gioco la stessa figura che mancava nello schema superiore. Sono convinto, per&ograve;, che anche se mettessimo nello schema di riferimento tre posizioni a caso, l&rsquo;esito del gioco dovrebbe avere le stesse probabilit&agrave; di completamento di un qualsiasi altro caso di gioco a costruzione reale. Voglio dire che l&rsquo;inserimento di quattro figure realmente succedutesi nella permanenza passata, o l&rsquo;inserimento di quattro figure scelte a caso, dovrebbe portare allo stesso risultato. In questo modo il gioco sar&agrave; molto pi&ugrave; breve, e inoltre non ci saranno da compiere risalite fra una partita e l&rsquo;altra. L&rsquo;unico punto interrogativo sar&agrave; costituito dalla scelta di quale figura escludere di volta in volta dal gioco. Se prima la scelta era dettata 1dalle tre figure presenti nello schema di riferimento, ora l&rsquo;esclusione di una figura potrebbe avvenire scegliendo fra tre modi diversi. 1&deg;) Scelta casuale di partita in partita; 2&deg;) Esclusione ordinata di una figura alla volta, partendo dalla prima fino alla quarta, per poi ricominciare dalla prima; 3&deg;) Esclusione ordinata, o casuale, delle figure 2,3,4, sia per il gioco a R che per quello a N, in modo da evirare l&rsquo;esclusione della figura 1, che da, come controfigura perdente, un filotto a N o a R. Certo un filotto non &egrave; diverso da qualsiasi altra figura ma, se teniamo sempre in gioco la figura 1, eliminiamo una configurazione che ci precluderebbe il buon esito delle prepuntate. Personalmente preferisco il terzo modo, con l&rsquo;opzione della casualit&agrave;, perch&eacute; la scelta casuale cambia continuamente la linea di condotta ed evita lo stazionamento in giochi sempre uguali, che prima o poi, incontrerebbero inevitabilmente le figure contrarie al gioco praticato. Comunque, per non dare adito al sospetto di una scelta di una permanenza opportunamente adatta, nell&rsquo;esemplificazione pratica che segue, sar&agrave; utilizzato il secondo modo, con l&rsquo;esclusione ordinata delle figure 1R, 2N, 3R, 4N, alternando cio&egrave; gli schemi a R e N. Una volta raggiunto il primo esito, positivo o negativo, ogni partita deve essere abbandonata e, nel caso si sia perdenti, si cercher&agrave; il recupero in prepuntata contraria nello schema successivo. E&rsquo;, infatti, consigliabile evitare di soffermarsi nella ricerca a tutti i costi di un risultato in un&rsquo;unica partita. L&rsquo;esperienza ha dimostrato che le maggiori esposizioni sono causate proprio da questo comportamento. Montante. Per questo gioco voglio proporre un nuovo tipo di montante che chiamer&ograve; &ldquo;Martingala + D&rsquo;Alembert a pezzo doppio&rdquo;. Consiste nell&rsquo;eseguire i primi quattro colpi in &ldquo;Martingala&rdquo; (1-2-4-8) costituiti da un pezzo di base minimo (per esempio 10 Euro) e nel proseguire, dal quinto colpo in poi, in &ldquo;D&rsquo;Alembert&rdquo;, da un pezzo doppio (che sar&agrave; di 20 Euro); cio&egrave; puntando 5 pezzi da 20 Euro, poi 6-7-8 ecc&hellip; In questo modo il recupero dei primi colpi persi sar&agrave; pi&ugrave; veloce ed efficace. I primi quattro colpi poi, ci danno la possibilit&agrave; di vincere un pezzo di utile e quindi di ricominciare da capo la montante. Iniziamo con una giornata a R\/N. Gioco a R\/N. Gioco a R. Escludo la figura 1R. Con il 17 vinco l&rsquo;anticipo per le figure 3-4R. Completo la figura con il 3. Gioco a N. Escludo la figura 2N. 2Con il 29 perdo l&rsquo;anticipo per le figure 3-4N e con il 23 perdo la figura 1N. Faremo una prepuntata a N al prossimo schema. Gioco a R. Escludo la figura 3R. Con il 27 perdo la prepuntata a N. Con il 32 vinco l&rsquo;anticipo per le fig. 1-2R. Completo la fig. con il 20. Gioco a N. Escludo la figura 4N. Con il 17 vinco l&rsquo;anticipo per le figure 1-2N. Con il 30 completo la figura. Gioco a R. Escludo la figura 1R. Con il 6 vinco per le figure 3-4R. Co il 3 completo la figura. Gioco a N. Escludo la figura 2 N. Con il 9 vinco l&rsquo;anticipo per le figure 3-4N. Con l&rsquo;8 completo la figura. Gioco a R. Escludo la figura 3R. Con il 9 vinco l&rsquo;anticipo per le figure 1-2R. Con il 21 completo la figura. Gioco a N. Escludo la figura 4N. Con il 30 perdo l&rsquo;anticipo per le figure 1-2N e con il 31 vinco la figura 3N. Gioco a R. Escludo la figura 1R. Con il 34 perdo l&rsquo;anticipo per le figure 3-4R e con il 16 perdo la figura 2R. Prepuntata a R al prossimo schema. Gioco a N. Escludo la figura 2N. Con il 13 perdo la prepuntata a N. Con il 7 vinco l&rsquo;anticipo per le figure 3-4N. Con il 24 completo la figura. 3Gioco a R. Escludo la figura 3R. Con il 13 perdo l&rsquo;anticipo per le figure 1-2R e con l&rsquo;1 perdo la figura 4R. Prepuntata a R al prossimo schema. Gioco a N. Escludo la figura 4N. Con l&rsquo;11 perdo la prepuntata. Con il 18 perdo l&rsquo;anticipo per le figure 1-2N e con il 10 vinco la figura 3N. Prepuntata a N al prossimo schema. Gioco a R. Escludo la figura 1R. Con il 33 libero la mise imprigionata dallo zero e con il 32 perdo la prepuntata. Con il 17 vinco l&rsquo;anticipo per le figure 3-4R e con il 28 completo la figura. Prepuntata a R al prossimo schema. Gioco a N. Escludo la figura 2N. Con il 16 vinco la prepuntata e ricomincio la montante da un pezzo. Con il 7 vinco l&rsquo;anticipo per le figure 3-4N e con il 13 completo la figura. Gioco a R. Escludo la figura 3R. Con il 27 vinco l&rsquo;anticipo per le figure 1-2R e con il 22 completo la figura. Gioco a N. Escludo la figura 4N. Con il 20 vinco l&rsquo;anticipo per le figure 1-2N e con il 27 completo la figura. Abbiamo eseguito 16 partite per quattro cicli completi, seguendo una linea che, seppur sempre uguale nella scelta della figura da eliminare, varia nell&rsquo;alternanza degli schemi a R e a N. Abbiamo realizzato un utile di 16 pezzi con un impegno massimo di 25. Segue ora lo stesso gioco applicato a P\/D e M\/P, utilizzando l&rsquo;esclusione ordinata del terzo modo. 4GIOCO A P\/D La figura che &egrave; di volta in volta esclusa &egrave; evidenziata con una sottolineatura posta in corrispondenza delle figure 2-3-4 a rotazione alternando, di riga in riga, la chance di competenza. Permanenza Non di comp. Di comp. Con il 17 vinco l&rsquo;anticipo e con il 3 completo la figura. Con il 23 vinco l&rsquo;ant. e con il 27 completo la figura. Con il 20 vinco l&rsquo;ant. e con il 10 completo. Con il 30 vinco l&rsquo;ant. e con il 28 completo. Con il 3 perdo l&rsquo;ant. e con il 28 perdo la fig. 4P. Prepuntata a P. Con il 9 perdo la prep. Con l&rsquo;8 perdo l&rsquo;ant. e con il 27 vinco lafig. 3D. Prepuntata a D. Con il 9 vinco la prep. Con il 10 perdo l&rsquo;ant. e con il 30 vinco la fig. 1P. Con il 21 vinco l&rsquo;ant. e con il 34 completo. Con il 13 perdo l&rsquo;ant. Con il 7 perdo la fig. 3P. Prepuntata a P Con il 24 vinco la prep. Con l&rsquo;1 perdo l&rsquo;ant. e con l&rsquo;11 vinco la fig.1 D. Con il 10 vinco l&rsquo;ant. e con il 33 completo la figura. Con il 28 perdo l&rsquo;ant. e con il 16 perdo la fig. 3D. Prep. a D. Con il 33 vinco la prepuntata. Con il 27 vinco l&rsquo;ant. e con il 22 completo la figura. Con il 9 vinco l&rsquo;ant. e col 23 completo. Con il 32 vinco l&rsquo;ant. e con il 27 completo. Con il 31 perdo l&rsquo;ant. e con il 20 perdo la fig. 1D. Prep. a D. Con il 27 libero la mise ma con il 18 perdo la prep. Con l&#8217;1 perdo l&#8217;ant. E con il 4 perdo la fig. 4P. Prepuntata aP. Con il 34 e con il 30 vinco due prep. Con il 14 e con il 12 perdo l&rsquo;ant. e la fig. 3D. Prepuntata a D. Con l&rsquo;11 e con il 15 vinco due prep. Con il 22 perdo l&rsquo;ant. e con il 24 vinco la fig. 1P. Prepuntata a P. Con il 30 vinco la prep. Con il 36 e con il 5 perdo l&rsquo;ant. e la fig. 4D. Prepuntata a D. Con il 10 perdo la prep. Con il 18 vinco l&rsquo;ant. e con il 6 completo. Con il 18 libero la mise e con il 33 completo la fig. (non saprei quale figura scegliere tra 3D e 4D). Con il 5 perdo l&rsquo;ant. e con il 17 vinco la fig. 4P. Con il 3 vinco l&rsquo;anticipo. L&rsquo;utile realizzato &egrave; stato di 22 pezzi con un impegno massimo di 37. <strong>Per saperne di piu&#8217; visita il sito <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sistema roulette dedicato agli appassionati della materia.<br \/>Questo sistema roulette \u00e8 particolarmente adatto a tutti coloro che approcciano in maniera scientifica il gioco in questione<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[813],"tags":[31226,2345,31225],"class_list":["post-22396","post","type-post","status-publish","format-standard","hentry","category-giochi","tag-roulette","tag-sistema","tag-sistema-roulette"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema Roulette Sistema Roulette - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema Roulette Sistema Roulette - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Sistema roulette dedicato agli appassionati della materia.Questo sistema roulette \u00e8 particolarmente adatto a tutti coloro che approcciano in maniera scientifica il gioco in questione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-14T19:34:21+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Sistema Roulette Sistema Roulette\",\"datePublished\":\"2011-12-14T19:34:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/\"},\"wordCount\":1740,\"commentCount\":0,\"keywords\":[\"roulette\",\"sistema\",\"sistema roulette\"],\"articleSection\":[\"Giochi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/\",\"name\":\"Sistema Roulette Sistema Roulette - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-12-14T19:34:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/giochi\\\/sistema-roulette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema Roulette Sistema Roulette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema Roulette Sistema Roulette - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/","og_locale":"it_IT","og_type":"article","og_title":"Sistema Roulette Sistema Roulette - Article Marketing","og_description":"Sistema roulette dedicato agli appassionati della materia.Questo sistema roulette \u00e8 particolarmente adatto a tutti coloro che approcciano in maniera scientifica il gioco in questione","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/","og_site_name":"Article Marketing","article_published_time":"2011-12-14T19:34:21+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Sistema Roulette Sistema Roulette","datePublished":"2011-12-14T19:34:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/"},"wordCount":1740,"commentCount":0,"keywords":["roulette","sistema","sistema roulette"],"articleSection":["Giochi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/","name":"Sistema Roulette Sistema Roulette - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-12-14T19:34:21+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/giochi\/sistema-roulette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Sistema Roulette Sistema Roulette"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=22396"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22396\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=22396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=22396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=22396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}