{"id":22582,"date":"2011-12-21T11:24:52","date_gmt":"2011-12-21T10:24:52","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/"},"modified":"2011-12-21T11:24:52","modified_gmt":"2011-12-21T10:24:52","slug":"tombola-vajassa-una-scostumatissima-tombola-napoletana","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/","title":{"rendered":"Tombola Vajassa: una scostumatissima tombola napoletana"},"content":{"rendered":"<p><a><\/a><a>Come dice il proverbio &ldquo;Non c&rsquo;&egrave; due senza tre&rdquo; ed &egrave; ovvio che proprio l&rsquo;associazione culturale Insolitaguida, sempre ligia a far conoscere la cultura popolare napoletana, non pu&ograve; non rispettarlo e lo fa introducendo un terzo appuntamento per la sua Tombola Vajassa: una scostumatissima tombola napolatena.<\/a><br \/>Nuova la location, in un locale &ldquo;adatto&rdquo; a tale tipo di spettacolo &ldquo;La cage aux folles&rdquo;,&nbsp; nuovo men&ugrave; pi&ugrave; ricco ed invitante, solo il format della serata ed il contributo di partecipazione restano invariati.<br \/>Ma che cos&rsquo;&egrave; questa &ldquo;Tombola Vajassa&rdquo;? &rdquo; E&rsquo; quella tombola che tutte le notti e tutti i giorni ancora oggi viene giocata&nbsp; nei bassi dei Quartieri Spagnoli o del Borgo S. Antonio Abate: una versione del gioco simbolo del Natale, resa piccante&nbsp; e coinvolgente dalla presenza di un femminiello D.O.C. capace di restituire con una travolgente affabulazione il pi&ugrave; palpitante vissuto dei vicoli napoletani.<br \/>Prima la cena ( aperitivo con stuzzicheria, antipasto, primo piatto, dolce e limoncello), servita ai tavoli&nbsp; accompagnata da acqua e vino, consigliabile per il tono della serata. Poi la tombola che come vuole la tradizione, sar&agrave; condotta da &ldquo;o femminiello&rdquo;, che tirer&agrave; l&#8217;estrazione con la caratteristica espressione: &#8220;Jammo, numeri e ffore&#8221;, secondo la smorfia pi&ugrave; colorita che abbiate mai sentito!&nbsp; Inoltre collegando il significato dei numeri che man mano vengono estratti lo stesso provveder&agrave; a concatenare in una sequenza logica e cronologica i relativi significati, creando una storia che si forma man mano che il gioco prosegue, fino ad assumere chiss&agrave; quale piega. <br \/>&nbsp; La location scelta &egrave; quanto di pi&ugrave; adeguato allo svolgimento dello spettacolo: un nuovissimo locale dal nome che &egrave; tutto un programma &ldquo;La cage aux folles&rdquo;, sito in prossimit&agrave; del nuovo Policlino ( Via Toscanella 56 ) dotato di parcheggio interno e facilmente raggiungibile sia dai napoletani che non.<br \/>Non sono previste n&eacute; scommesse n&eacute; vincite ma solo tante risate e premi peperini gentilmente offerti dal sexy shop 69 (&nbsp; viale Farnese 51 &#8211; Colli Aminei &ndash; NA ).<br \/>Per partecipare (contributo associativo di 25 &euro;) occorre prenotarsi ed &egrave; possibile farlo telefonando al 338 81 05 370 oppure on-line sul sito www.insolitaguida.it, dove &egrave; possibile trovare ulteriori informazioni e foto dell&rsquo;evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tombola col femminiello pi\u00f9 divertente a Napoli. Una cena spettacolo piacevole che ti far\u00e0 divertire senza scadere nel volgare.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[295],"tags":[11276,32053,32052,472,11275],"class_list":["post-22582","post","type-post","status-publish","format-standard","hentry","category-tempo-libero","tag-femminiello","tag-insolitaguida","tag-napoletana","tag-natale","tag-tombola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La tombola col femminiello pi\u00f9 divertente a Napoli. Una cena spettacolo piacevole che ti far\u00e0 divertire senza scadere nel volgare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-21T10:24:52+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Tombola Vajassa: una scostumatissima tombola napoletana\",\"datePublished\":\"2011-12-21T10:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/\"},\"wordCount\":397,\"commentCount\":0,\"keywords\":[\"femminiello\",\"insolitaguida\",\"napoletana\",\"natale\",\"tombola\"],\"articleSection\":[\"Tempo libero\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/\",\"name\":\"Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2011-12-21T10:24:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/tempo-libero\\\/tombola-vajassa-una-scostumatissima-tombola-napoletana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tombola Vajassa: una scostumatissima tombola napoletana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/","og_locale":"it_IT","og_type":"article","og_title":"Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing","og_description":"La tombola col femminiello pi\u00f9 divertente a Napoli. Una cena spettacolo piacevole che ti far\u00e0 divertire senza scadere nel volgare.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/","og_site_name":"Article Marketing","article_published_time":"2011-12-21T10:24:52+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Tombola Vajassa: una scostumatissima tombola napoletana","datePublished":"2011-12-21T10:24:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/"},"wordCount":397,"commentCount":0,"keywords":["femminiello","insolitaguida","napoletana","natale","tombola"],"articleSection":["Tempo libero"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/","name":"Tombola Vajassa: una scostumatissima tombola napoletana - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2011-12-21T10:24:52+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/tempo-libero\/tombola-vajassa-una-scostumatissima-tombola-napoletana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Tombola Vajassa: una scostumatissima tombola napoletana"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=22582"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22582\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=22582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=22582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=22582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}