{"id":22669,"date":"2011-12-25T22:59:28","date_gmt":"2011-12-25T21:59:28","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/"},"modified":"2011-12-25T22:59:28","modified_gmt":"2011-12-25T21:59:28","slug":"perdita-di-peso-diete-calcolo-del-peso-forma-ideale","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/","title":{"rendered":"Perdita di peso diete (Calcolo del peso forma ideale)"},"content":{"rendered":"<p>L&#8217;obiettivo di qualsiasi dieta per dimagrire &egrave; quello di raggiungere un apporto quotidiano di energia che &egrave; inferiore alla spesa quotidiana di energia. Il dispendio energetico giornaliero pu&ograve; essere stimata utilizzando formule comuni in base a et&agrave;, sesso e altezza. Le regolazioni possono essere effettuate in base all&#8217;attivit&agrave; fisica.<br \/>\n<img decoding=\"async\" src=\"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg\" border=\"0\" \/><br \/>\nLa maggior parte dei programmi di perdita di peso tenta di creare un deficit giornaliero di 500 calorie. Perch&eacute; un chilo di grasso equivale a 3500 calorie, questo deficit si tradurr&agrave; in una perdita di peso di un chilo a settimana. Per esempio, una persona che richiede 1800 calorie al giorno per mantenere il suo peso attuale avrebbe bisogno di ingerire 1300 calorie al giorno per perdere un chilo alla settimana.<\/p>\n<p>Studi su diete di perdita di peso indicano che il pi&ugrave; delle volte una perdita media di peso tra 5% e il 10% del <a href=\"http:\/\/peso-forma-ideale.nuovadieta.it\/peso-forma-ideale.htm\" title=\"Peso forma ideale\"><strong>peso forma ideale <\/strong><\/a>in 6-12 mesi di follow-up. Cio&egrave;, una persona che inizia una dieta a 100 Kg perder&agrave; un chilo tra 10 e 20 giorni. Tutti gli studi, tuttavia, mostrano una grande variabilit&agrave; tra gli individui. Mentre molti pazienti sono vicini alla media, alcuni pazienti perdono notevolmente di pi&ugrave;. L&#8217;adesione al programma di controllo del peso &egrave; un fattore importante di successo rispetto alla dieta fai da te.<\/p>\n<p>Gran parte della controversia sulle diete perdita di peso negli ultimi anni si &egrave; concentrata sulla composizione ideale macronutrienti (proporzione di grassi, carboidrati e proteine), delle diete. In realt&agrave;, le differenze nella composizione di macronutrienti sono stati la base di diete popolari perdita di peso per decenni, in particolare le diete che hanno sostenuto basso apporto di carboidrati.<\/p>\n<p>Tradizionalmente, consigli per le diete perdita di peso sono parallele a quelle per il mantenimento del <strong>peso forma ideale <\/strong>e &#8220;dieta sana&#8221;. Diete di questo tipo sono tradizionalmente raccomandano pi&ugrave; bassi introiti di grassi come strategia primaria per l&rsquo;apporto inferiore di calorie. La maggior parte delle diete vegetariane e in stile mediterraneo dieta rientrano anche all&#8217;interno di questo intervallo e possono essere progettati per raggiungere un deficit energetico per la perdita di peso. Una caratteristica fondamentale delle diete di perdita peso equilibrata &egrave; l&rsquo;attenzione alla dimensione delle porzioni. Il marcato aumento porzioni consumate, in particolare nei fast-food e altri ristoranti &egrave; ben documentato. Uno stretto contatto con i dietologi e gli altri operatori sanitari &egrave; fondamentale per i pazienti per imparare a stimare le dimensioni delle porzioni e contenuto calorico, cos&igrave; come i metodi per aumentare l&#8217;attivit&agrave; fisica e per fornire supporto. Il Programma di Prevenzione del Diabete, per esempio, funziona a condizione che i soggetti seguano 16 visite di un&#8217;ora per aiutarli a padroneggiare il programma completo. <\/p>\n<p>Un altro approccio importante per raggiungere il <strong>peso forma ideale <\/strong>&egrave; l&#8217;uso di sostituti del pasto. Si tratta di diete a basso contenuto calorico in cui sono forniti tutti o la maggior parte degli alimenti dal piano di perdita di peso. Questi possono essere pasti pre-confezionati o come combinazioni di barrette, frullati e zuppe. I Programmi con pasto sostitutivo aiutano molti pazienti, eliminando molte delle decisioni relative alla pianificazione degli alimenti, la preparazione del cibo, e controllo delle porzioni. In questo modo, si pu&ograve; pi&ugrave; facilmente raggiungere la restrizione calorica per alcuni individui. Sebbene anche la maggior parte dei programmi pasto sostitutivo mirano ad un deficit energetico di 500 calorie al giorno, pu&ograve; essere raggiunta una maggiore restrizione. Quando tali diete forniscono meno di 800 calorie al giorno sono conosciuti come molto-diete a basso contenuto calorico (VLCDs). VLCDs hanno dimostrato di portare ad una maggiore perdita di peso iniziale, pi&ugrave; vicina a 1 Kg. a settimana, rispetto alle tipiche diete a basso contenuto calorico (LCD). In media tale risultato &egrave; del 15% del peso iniziale perso un anno, di nuovo con una grande variazione tra gli individui. Un confronto tra 400, 600 e 800 calorie al giorno ha dimostrato che 800 al giorno &egrave; pi&ugrave; sicuro e altrettanto efficace.<\/p>\n<p>Tuttavia, il ritmo pi&ugrave; rapido di perdita di peso che pu&ograve; essere raggiunto con diete a bassissimo contenuto calorico le rende molto utili in casi clinici in cui rapida perdita di peso &egrave; particolarmente utile. Gli esempi includono la perdita di peso prima di un intervento chirurgico, compresi quelli di chirurgia ortopedica, chirurgia dei trapianti e della chirurgia bariatrica, molto scarsamente controllano il diabete mellito di tipo 2, e altre condizioni invalidanti correlati all&#8217;obesit&agrave;. Le diete a bassissimo contenuto calorico devono essere usate in programmi globali che offrono una stretta sorveglianza medica e servizi interprofessionale per assistere ad aumenti di attivit&agrave; fisica, terapia comportamentale, e il supporto sociale. I pazienti che con successo perdono grandi quantit&agrave; di peso rapidamente possono avere importanti problemi psicologici inaspettati che devono essere affrontati. Particolare attenzione deve inoltre essere immessi sul passaggio indietro a una dieta normale per evitare il riacquisto del peso e il mantenimento del <strong>peso forma ideale<\/strong>.<br \/>Per calcolare il tuo <strong>peso forma ideale <\/strong>puoi utilizzare il formulario che trovi a questo sito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran parte della controversia sulle diete perdita di peso negli ultimi anni si \u00e8 concentrata sulla composizione ideale macronutrienti (proporzione di grassi, carboidrati e proteine), delle diete. In realt\u00e0, le differenze nella composizione di macronutrienti sono stati la base di diete popolari perdita di peso per decenni, in particolare le diete che hanno sostenuto basso apporto di carboidrati.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[162],"tags":[32115,32114,20596,32116,31500],"class_list":["post-22669","post","type-post","status-publish","format-standard","hentry","category-dieta-e-nutrizione","tag-cacolo-peso-foma-ideale","tag-calcolare-peso-forma-ideale","tag-peso-forma","tag-peso-forma-ideale","tag-peso-ideale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Gran parte della controversia sulle diete perdita di peso negli ultimi anni si \u00e8 concentrata sulla composizione ideale macronutrienti (proporzione di grassi, carboidrati e proteine), delle diete. In realt\u00e0, le differenze nella composizione di macronutrienti sono stati la base di diete popolari perdita di peso per decenni, in particolare le diete che hanno sostenuto basso apporto di carboidrati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-25T21:59:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Perdita di peso diete (Calcolo del peso forma ideale)\",\"datePublished\":\"2011-12-25T21:59:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/\"},\"wordCount\":837,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.nuovadieta.it\\\/immagini\\\/pesoforma05.jpg\",\"keywords\":[\"cacolo peso foma ideale\",\"Calcolare peso forma ideale\",\"peso forma\",\"peso forma ideale\",\"peso ideale\"],\"articleSection\":[\"Dieta e Nutrizione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/\",\"name\":\"Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.nuovadieta.it\\\/immagini\\\/pesoforma05.jpg\",\"datePublished\":\"2011-12-25T21:59:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.nuovadieta.it\\\/immagini\\\/pesoforma05.jpg\",\"contentUrl\":\"http:\\\/\\\/www.nuovadieta.it\\\/immagini\\\/pesoforma05.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/dieta-e-nutrizione\\\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perdita di peso diete (Calcolo del peso forma ideale)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/","og_locale":"it_IT","og_type":"article","og_title":"Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing","og_description":"Gran parte della controversia sulle diete perdita di peso negli ultimi anni si \u00e8 concentrata sulla composizione ideale macronutrienti (proporzione di grassi, carboidrati e proteine), delle diete. In realt\u00e0, le differenze nella composizione di macronutrienti sono stati la base di diete popolari perdita di peso per decenni, in particolare le diete che hanno sostenuto basso apporto di carboidrati.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/","og_site_name":"Article Marketing","article_published_time":"2011-12-25T21:59:28+00:00","og_image":[{"url":"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Perdita di peso diete (Calcolo del peso forma ideale)","datePublished":"2011-12-25T21:59:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/"},"wordCount":837,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#primaryimage"},"thumbnailUrl":"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg","keywords":["cacolo peso foma ideale","Calcolare peso forma ideale","peso forma","peso forma ideale","peso ideale"],"articleSection":["Dieta e Nutrizione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/","name":"Perdita di peso diete (Calcolo del peso forma ideale) - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#primaryimage"},"thumbnailUrl":"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg","datePublished":"2011-12-25T21:59:28+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#primaryimage","url":"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg","contentUrl":"http:\/\/www.nuovadieta.it\/immagini\/pesoforma05.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/dieta-e-nutrizione\/perdita-di-peso-diete-calcolo-del-peso-forma-ideale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Perdita di peso diete (Calcolo del peso forma ideale)"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=22669"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22669\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=22669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=22669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=22669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}