{"id":22854,"date":"2012-01-05T16:21:35","date_gmt":"2012-01-05T15:21:35","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/"},"modified":"2018-07-10T04:28:26","modified_gmt":"2018-07-10T02:28:26","slug":"settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/","title":{"rendered":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica"},"content":{"rendered":"<p>Anche in Italia, cos&igrave; come in molti altri paesi in Europa e nel mondo, il 2011 non &egrave; stato esattamente l&rsquo;anno migliore dal punto di vista economico: la tanto declamata crisi, il cui spettro incombe minaccioso su di noi ormai da un po&rsquo; di anni, sembra aver cominciato a manifestarsi pi&ugrave; prepotentemente in Italia proprio negli ultimi mesi, colpendo moltissimi settori diversi. Nonostante la crisi, per&ograve;, ci sono alcuni settori che hanno retto meglio di altri il colpo, e che anzi, in questi mesi neri per l&rsquo;economia nazionale, fanno registrare dei dati confortanti. &Egrave; il caso, per esempio, del settore della produzione e lavorazione di materie plastiche (tra le quali polietilene, policarbonato compatto e altro ancora) e della gomma.<br \/>\n<br \/>In particolare, a far ben sperare per il futuro sono le aziende specializzate nella realizzazione delle macchine utensili per la lavorazione della plastica e della gomma, un settore che rappresenta una sorta di isola felice del made in Italy. Un&rsquo;isola felice che, a dispetto della crisi, nei primi nove mesi del 2011 ha dimostrato di non aver ceduto al periodo negativo che stiamo attraversando: in base ai dati raccolti dall&rsquo;ISTAT relativi ai primi nove mesi dell&rsquo;anno, infatti, Assocomaplast (l&rsquo;associazione nazionale costruttori di macchine e stampi per materie plastiche e gomma), ha calcolato le proiezioni per l&rsquo;intero anno, sia per quanto riguarda l&rsquo;import che l&rsquo;export dei macchinari per la produzione di PVC film, polietilene e altre materie plastiche. Ne emerge un quadro sicuramente positivo: se nel mercato interno si evidenzia una certa staticit&agrave;, infatti, le esportazioni sono invece in aumento. In particolare, si parla di una stima attorno ai 4 miliardi di euro (il che significa, in percentuale, un aumento dell&rsquo;11%) per quanto riguarda la produzione totale del 2011 (dato che si avvicina a quello del 2008), e di un aumento ancora pi&ugrave; eclatante per quanto riguarda l&rsquo;export, con una crescita del 19,3% fino a toccare i 4 miliardi di euro e un saldo commerciale attivo per 1,8 miliardi, che di traduce in un +24,6%.<\/p>\n<p>Dati positivi, soprattutto se si considera che stiamo parlando di un settore di nicchia in Italia, un settore che conta meno di 200 aziende specializzate nella realizzazione di macchine utensili per la realizzazione di plastica e gomma. Un numero esiguo di aziende che riesce per&ograve; a contribuire al 7% del saldo commerciale nazionale non energetico. Ma dove va la maggior parte dei macchinari realizzati in Italia ed esportati all&rsquo;estero? In testa a tutti gli altri paesi rimane la Germania: negli ultimi anni le esportazioni verso questo paese sono cresciute moltissimo, anche se c&rsquo;&egrave; da dire che, secondo il presidente di Assocomplast, la situazione si sta ora ridimensionando. Altri paesi in cui i macchinari italiani per la produzione e lavorazione di politene e altre materie plastiche vanno per al maggiore sono gli Stati Uniti, il Brasile, la Russia e la Turchia: le speranze per il 2012 sono in gran parte riposte in questi paesi, e ci si aspetta qualcosa in pi&ugrave; anche dai cosiddetti mercati emergenti, che pur non comparendo ancora tra i maggiori importatori di macchinari italiani fanno ben sperare per il futuro. Si tratta di paesi quali l&rsquo;Indonesia e la Malesia.<\/p>\n<p>In conclusione, in Italia il mercato delle macchine per la produzione di materie plastiche fa ben sperare anche per il futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante la crisi, il settore delle macchine per la produzione della plastica e della gomma in Italia fa registrare un confortante aumento delle esportazioni.<\/p>\n<p><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[32273,32274,32272,32271,32270],"class_list":["post-22854","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-export-macchinari","tag-lavorazione-gomma","tag-macchine-lavorazione-plastica","tag-produzione-gomma","tag-produzione-plastica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la??export-delle-macchine-per-la-lavorazione-della-plastica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nonostante la crisi, il settore delle macchine per la produzione della plastica e della gomma in Italia fa registrare un confortante aumento delle esportazioni.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-05T15:21:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:28:26+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica\",\"datePublished\":\"2012-01-05T15:21:35+00:00\",\"dateModified\":\"2018-07-10T02:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/\"},\"wordCount\":581,\"commentCount\":0,\"keywords\":[\"export macchinari\",\"lavorazione gomma\",\"macchine lavorazione plastica\",\"produzione gomma\",\"produzione plastica\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/\",\"name\":\"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-01-05T15:21:35+00:00\",\"dateModified\":\"2018-07-10T02:28:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la??export-delle-macchine-per-la-lavorazione-della-plastica\/","og_locale":"it_IT","og_type":"article","og_title":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing","og_description":"Nonostante la crisi, il settore delle macchine per la produzione della plastica e della gomma in Italia fa registrare un confortante aumento delle esportazioni.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la??export-delle-macchine-per-la-lavorazione-della-plastica\/","og_site_name":"Article Marketing","article_published_time":"2012-01-05T15:21:35+00:00","article_modified_time":"2018-07-10T02:28:26+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica","datePublished":"2012-01-05T15:21:35+00:00","dateModified":"2018-07-10T02:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/"},"wordCount":581,"commentCount":0,"keywords":["export macchinari","lavorazione gomma","macchine lavorazione plastica","produzione gomma","produzione plastica"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/","name":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-01-05T15:21:35+00:00","dateModified":"2018-07-10T02:28:26+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/settori-in-crescita-la%80%99export-delle-macchine-per-la-lavorazione-della-plastica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Settori in crescita: l\u2019export delle macchine per la lavorazione della plastica"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=22854"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22854\/revisions"}],"predecessor-version":[{"id":59141,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22854\/revisions\/59141"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=22854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=22854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=22854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}