{"id":22950,"date":"2012-01-15T23:52:59","date_gmt":"2012-01-15T22:52:59","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/"},"modified":"2012-01-15T23:52:59","modified_gmt":"2012-01-15T22:52:59","slug":"il-catalogo-labbraccio-di-solitudini-oltre-memoria","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/","title":{"rendered":"Il Catalogo, l&#8217;abbraccio di solitudini oltre memoria"},"content":{"rendered":"<p><\/p>\n<p><em style=\"padding: 0px; margin: 0px;\"><strong style=\"padding: 0px; margin: 0px;\">Al Lauro Rossi la piece con Ennio Fantastichini e Isabella Ferrari<\/strong><\/em><\/p>\n<p><em style=\"padding: 0px; margin: 0px;\"><strong style=\"padding: 0px; margin: 0px;\"><\/strong><\/em><a href=\"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo.jpg\" class=\"cboxElement\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-single-post-thumbnail colorbox-79576 wp-post-image\" src=\"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg\" border=\"0\" alt=\"il catalogo\" title=\"il catalogo\" width=\"250\" height=\"355\" \/><\/a><br \/>\nMACERATA, 2012-01-15 &#8211; Il Catalogo di Jean Claude Carri&egrave;re messo in scena da Valerio Binasco con due protagonisti d&rsquo;eccezione, Ennio Fantastichini e Isabella Ferrari, approda al Lauro Rossi di Macerata con ben due date. Il sipario si &egrave; aperto nella serata di ieri e la replica &egrave; fissata per le 21 di oggi.<br \/>\nUn lavoro ingannevole, che ammalia con una certa leggerezza guidata dal facile sorriso e da una colonna sonora minimalista e scanzonata nella tessitura di violini, fisarmoniche e pianoforte. Ma il punctum va ben al di l&agrave; di quel che appare.<br \/>\nEsiste un modo per provare ad ingannare il senso di morte e di spaesamento che attanaglia gli animi degli esseri pensanti. &Egrave; quello che restituisce il dominio sulle cose indomabili. Organizzare, precisare, ordinare, catalogare eventi, cose, persone. Quello cio&egrave; che offre il senso del possesso di ci&ograve; che &egrave; stato, di ci&ograve; che &egrave; e probabilmente di ci&ograve; che sar&agrave;.<br \/>\nAl di l&agrave; dell&rsquo;incasellamento, oltre il riporre nei cassetti ogni cosa da trattenere, conservare e ritrovare c&rsquo;&egrave; la memoria. Ma come? Se si conserva per ricordare, come &egrave; allora possibile che oltre la catalogazione vi sia la memoria?<br \/>\nLa memoria, Beckett docet, ridisegna il passato con l&rsquo;occhio del presente guidato dalla coscienza. Mente.<br \/>\nEd allora, parafrasando lo scrittore dublinese, quello che disegna il ricordo vero &egrave; l&rsquo;estrema disattenzione, l&rsquo;operare fuori dai cardini dell&rsquo;abitudine, oltre il filo spinato della volont&agrave;.<br \/>\nIl ricordo &egrave; oltre l&rsquo;ordine, oltre la precisione, oltre il mondo incasellato di Jaen Jacques, un eccellente Ennio Fantastichini. Piacente avvocato single della Parigi bene vive le sue giornate tra lavoro, cambi d&rsquo;abito, cene con amici e notti bollenti con avvenenti sconosciute, numeri dalle curve sinuose contabilizzati sul proprio catalogo pro-memoria.<br \/>\nTre scalini in legno al di qua della porta d&rsquo;ingresso e poi la camera da letto stretta tra un bagno e un cucinotto, due blocchi che nel ritaglio dei muri rivolti al pubblico, non lasciano niente all&rsquo;intuizione, libero accesso all&rsquo;occhio dello spettatore.<br \/>\nQui, nell&rsquo;ordine di spazi si consuma l&rsquo;ordine di tempi. Eppure come in ogni opera che si rispetti il caos arriva inaspettatamente e dall&rsquo;entrata principale.<br \/>\nPantaloni a zampa, borsa frangiata e cappotto celeste bordato di pelliccia, un simpatico accento straniero e una valigia che trascina faticosamente. Entra cos&igrave; nell&rsquo;intimit&agrave; di Jean Jacques, una donna (Isabella Ferrari), straniera in senso lato, chiedendo di un certo signor Ferrand. Varcata la soglia, la bionda strampalata signora non uscir&agrave; pi&ugrave; dall&rsquo;appartamento (&ldquo;Le dispiace se resto un po&rsquo; qui? Lei esca pure&rdquo;), dalla vita e dall&rsquo;intima solitudine dell&rsquo;uomo, nonostante la sua ovvia resistenza.<br \/>\nNel turbine di comicit&agrave; del primo approccio, nel paradosso divertente di irriverenze ed assurdit&agrave;, pian piano inspiegabilmente si fa spazio un senso di angoscia. L&rsquo;incunearsi di Suzanne, questo il nome faticosamente strappato alla confessione dell&rsquo;intrusa, in spazi cinestetici e mentali, il prendere possesso del letto, dell&rsquo;armadio e del prezioso catalogo, &egrave; un gioco tra solitudini equidistanti ed equipollenti.<br \/>\nPerch&egrave; prendere nota delle 134 donne sedotte? &ldquo;Se non lo scrivo e come se non fosse successo&rdquo; confessa Jean Jacques. E lo stesso ammette Suzanne di se stessa: &ldquo;Tutto quello che dico &egrave; vero, tutto quello che non dico non esiste&rdquo;. &Egrave; del vuoto che si ha paura, &egrave; l&igrave; che si rifugge il dubbio, che si ricerca il vero, ed &egrave; l&igrave; che non v&rsquo;&egrave; spazio per la bugia.<\/p>\n<p>Eppure tutto lo spettacolo &egrave; una passeggiata funambolesca tra il vero e il falso, il reale e l&rsquo;immaginato, l&rsquo;essere e il fingersi. Non a caso i due protagonisti pi&ugrave; volte si gridano addosso le parole &ldquo;Chi &egrave; lei? Non so nulla di lei!&rdquo;. Quel congelare la terza persona nonostante i giorni passino nella condivisione dei luoghi, e quel raccontarsi senza comunicare, riportano a galla il tema dell&rsquo;identit&agrave;. Ognuno &egrave;, solo e soltanto, nella descrizione che ne fa l&rsquo;altro: prostituta o seduttore, vergine o imbranato, donna o uomo normale, estraneo o amico.<\/p>\n<p>Non si &egrave; mai e basta, ma si diviene nella trasformazione continua che si attua al cambiare dell&rsquo;altro.<br \/>\nEd allora, nella pur sempre presente ambiguit&agrave; del reale, i due protagonisti divengono solitudini appaiate che sono ben altro dalla compagnia. Come in una storia della Nouvelle Vogue, i due creano dipendenze temibili, degenerate e degenerative. La vita evolve in una attesa del nulla. Jean Jacques lascia il lavoro per stare con Suzanne, e Suzanne continua a vegetare fingendo di cercare una casa altra dove andare a vivere la sua non vita. Senza lavoro, incapace di imparare, senza casa, stanca di un sonno che non la lascia se non di notte, la donna condivide l&rsquo;indolenza alla Godot e assorbe lo spaesamento di Jean Jacques.<br \/>\nNon c&rsquo;&egrave; una storia d&rsquo;amore, un bacio, una condivisione di sentimenti. L&rsquo;uomo che voleva disfarsi dell&rsquo;intrusa si converte in uno zerbino pronto a soddisfare quelli che nella sua percezione sono i desideri della donna.<br \/>\nMa qui &egrave; l&rsquo;incomunicabilit&agrave;. Quel gioco di ripicche, di gelosie fomentate, di minacce allacciate alla paura della perdita, non conducono ad una comunicazione reale.<br \/>\nJean Jacques lascia tutto, convinto che il desiderio di Suzanne sia quello di stare con lui, di vivere insieme e in quella piccola casa. Di contro Suzanne ha desiderio dell&rsquo;uomo sono nell&rsquo;assenza di quest&rsquo;ultimo e quel senso di attaccamento dimostrato precedentemente viene quasi irriso nella confessione d&rsquo;amore dell&rsquo;uomo.<br \/>\nChe importanza ha chi &egrave; l&rsquo;altro quando si &egrave; spaventati dalla propria solitudine? Ed allora Suzanne pu&ograve; tranquillamente essere la donna che, di fronte allo scoramento e alla esasperazione di Jean Jacques per la paura del distacco, ha finto di cercare e di aver trovato un&rsquo;altra casa. E Jean Jacques pu&ograve; divenire l&rsquo;uomo del passato, il signor Ferrand.<br \/>\nIn fondo in quel non luogo vi &egrave; tutto quello che serve, una solitudine che si consola con un&rsquo;altra fingendosi compagnia.<br \/>\nTeatro pieno e pubblico che sospinto dagli applausi azzarda una standing ovation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Catalogo di Jean Claude Carri\u00e8re messo in scena da Valerio Binasco con due protagonisti d\u2019eccezione, Ennio Fantastichini e Isabella Ferrari, approda al Lauro Rossi di Macerata con ben due date. Il sipario si \u00e8 aperto nella serata di ieri e la replica \u00e8 fissata per le 21 di oggi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[31665,32366,32365,32367,12661,32369,32368],"class_list":["post-22950","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-emanuela-sabbatini","tag-ennio-fantastichini","tag-il-catalogo","tag-isabella-ferrari","tag-macerata","tag-teatro-lauro-rossi","tag-valerio-binasco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Catalogo, l&#039;abbraccio di solitudini oltre memoria - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Catalogo, l&#039;abbraccio di solitudini oltre memoria - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il Catalogo di Jean Claude Carri\u00e8re messo in scena da Valerio Binasco con due protagonisti d\u2019eccezione, Ennio Fantastichini e Isabella Ferrari, approda al Lauro Rossi di Macerata con ben due date. Il sipario si \u00e8 aperto nella serata di ieri e la replica \u00e8 fissata per le 21 di oggi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-15T22:52:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Il Catalogo, l&#8217;abbraccio di solitudini oltre memoria\",\"datePublished\":\"2012-01-15T22:52:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/\"},\"wordCount\":1097,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ilmascalzone.it\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/il-catalogo-250x355.jpg\",\"keywords\":[\"Emanuela Sabbatini\",\"Ennio Fantastichini\",\"Il Catalogo\",\"Isabella Ferrari\",\"macerata\",\"Teatro Lauro Rossi\",\"Valerio Binasco\"],\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/\",\"name\":\"Il Catalogo, l'abbraccio di solitudini oltre memoria - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ilmascalzone.it\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/il-catalogo-250x355.jpg\",\"datePublished\":\"2012-01-15T22:52:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.ilmascalzone.it\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/il-catalogo-250x355.jpg\",\"contentUrl\":\"http:\\\/\\\/www.ilmascalzone.it\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/il-catalogo-250x355.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Catalogo, l&#8217;abbraccio di solitudini oltre memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Catalogo, l'abbraccio di solitudini oltre memoria - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/","og_locale":"it_IT","og_type":"article","og_title":"Il Catalogo, l'abbraccio di solitudini oltre memoria - Article Marketing","og_description":"Il Catalogo di Jean Claude Carri\u00e8re messo in scena da Valerio Binasco con due protagonisti d\u2019eccezione, Ennio Fantastichini e Isabella Ferrari, approda al Lauro Rossi di Macerata con ben due date. Il sipario si \u00e8 aperto nella serata di ieri e la replica \u00e8 fissata per le 21 di oggi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/","og_site_name":"Article Marketing","article_published_time":"2012-01-15T22:52:59+00:00","og_image":[{"url":"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Il Catalogo, l&#8217;abbraccio di solitudini oltre memoria","datePublished":"2012-01-15T22:52:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/"},"wordCount":1097,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg","keywords":["Emanuela Sabbatini","Ennio Fantastichini","Il Catalogo","Isabella Ferrari","macerata","Teatro Lauro Rossi","Valerio Binasco"],"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/","name":"Il Catalogo, l'abbraccio di solitudini oltre memoria - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg","datePublished":"2012-01-15T22:52:59+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#primaryimage","url":"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg","contentUrl":"http:\/\/www.ilmascalzone.it\/wp-content\/uploads\/2012\/01\/il-catalogo-250x355.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/il-catalogo-labbraccio-di-solitudini-oltre-memoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Il Catalogo, l&#8217;abbraccio di solitudini oltre memoria"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=22950"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/22950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=22950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=22950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=22950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}