{"id":2327,"date":"2009-07-06T11:56:34","date_gmt":"2009-07-06T09:56:34","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/"},"modified":"2018-06-04T20:16:09","modified_gmt":"2018-06-04T18:16:09","slug":"fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/","title":{"rendered":"Fracia: biberon di plastica banditi. &#8220;Sono pericolosi per i beb\u00e8!&#8221;"},"content":{"rendered":"<p style=\"TEXT-ALIGN: justify\">Nonostante numerosi studi ne confermino gli effetti negativi sulla <u><u>salute<\/u><\/u> umana, la comunit\u00e0 scientifica non \u00e8 ancora giunta ad un accordo sulla pericolosit\u00e0 del Bisfenolo A.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">In Francia si riapre il dibattito sulla pericolosit\u00e0 del Bisfenolo A (BPA), una sostanza chimica utilizzata per rendere trasparente la plastica e per questo presente anche nei biberon per beb\u00e8. <\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">Come spiegato sul sito dell&#8217;Istituto Superiore di Sanit\u00e0 &quot;il Bisfenolo A, chimicamente 2,2-bis (4-idrossifenil) propano, \u00e8 una delle sostanze chimiche utilizzate per produrre plastiche e resine. In particolare viene impiegato nella produzione di policarbonato, una plastica utilizzata per biberon, stoviglie, contenitori per alimenti e nella produzione di rivestimenti epossidici per materiali metallici, per lattine per bevande e grandi contenitori per vino&quot;.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">Il Ministro della Salute francese, Roselyne Bachelot, ha dichiarato che secondo la letteratura medica attuale la sicurezza dei prodotti plastici, quindi anche dei biberon, \u00e9 garantita. Le sue affermazioni sono confermate dalle ultime evidenze in questo campo, delineate dagli studi dell&#8217;Agenzia Nazionale per la Sicurezza Alimentare e Sanitaria.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">Eppure, nonostante le rassicurazioni delle autorit\u00e0 mediche, il Municipio di Parigi ha deciso di prendere provvedimenti: tutti gli asili nido dovranno abolire i vecchi biberon di plastica. Questo per evitare ogni rischio.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">E&#8217; stato Christophe Nadjovski, responsabile delle politiche per la prima infanzia, a guidare la campagna comunale di boicottaggio dei contenitori alimentari in plastica per salvaguardare i neonati da eventuali rischi, secondo lui mai smentiti chiaramente dalle ricerche scientifiche. Tutte le forniture di biberon dovranno, d&#8217;ora in poi, essere rigorosamente in vetro o, in alternativa, in plastica garantita senza Bisfenolo A. <\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">&quot;Il Bisfenolo A &#8211; continua l&#8217;ISS &#8211; ad alte dosi pu\u00f2 interferire con il sistema endocrino, ma \u00e8 tuttora controverso se questi effetti possono verificarsi anche a basse dosi. Nel gennaio 2007 l\u2019EFSA ha pubblicato la valutazione sui rischi derivanti da migrazione di Bisfenolo A in alimenti e ha indicato il limite di 0,05 milligrammi\/kg di peso corporeo come assunzione giornaliera tollerabile (TDI).&quot;<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">La Francia non \u00e9 per\u00f2 il primo Paese a mettere in dubbio i dati scientifici finora diffusi dagli enti preposti al controllo. I forti dubbi sugli effetti negativi della sostanza avevano portato, l&#8217;anno scorso, il Canada a bandire non solo i biberon fatti con plastiche contenenti Bisfenolo A ma anche tutti gli altri contenitori alimentari dello stesso tipo.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">&quot;In base alle conoscenze attuali &#8211; ripete l&#8217;ISS &#8211; non ci sono motivi scientifici che precludono l\u2019uso di biberon in plastica. Le stime effettuate dall\u2019EFSA hanno mostrato che l\u2019esposizione della popolazione europea a Bisfenolo A attraverso la dieta anche in neonati allattati esclusivamente con biberon in plastica \u00e8 notevolmente inferiore al valore di assunzione giornaliera tollerabile.&quot; <\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">Eppure numerosi sono gli studi che smentiscono queste tesi confortanti. Una ricerca pubblicata sulla rivista specializzata &#8216;Endocrinology&#8217; accusa il BPA di avere gravi effetti sullo sviluppo cerebrale dei bambini. <\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">Gi\u00e0 nel 2005 alcuni ricercatori della &#8216;University of Cincinnati&#8217; attribuirono alcuni disturbi del tessuto cerebrale dei bambini al BPA, anche se assunto in dosi molto basse. Ad oggi sono pi\u00f9 di 150 gli studi scientifici condotti su roditori che rivelerebbero connessioni tra il Bisfenolo A e varie patologie (tra le quali alcuni tumori). Non va comunque sottovalutato il fatto che nelle plastiche usate negli Stati Uniti le percentuali di Bisfenolo A presente sono maggiori rispetto a quelle consentite in Europa.<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\">&quot;Per evitare problemi &#8211; consiglia Angela Colombini, della Societ\u00e0 Italiana di Pediatria &#8211; \u00e8 buona cosa non sterilizzare i biberon (cos\u00ec da evitare l&#8217;uso di acqua molto calda) ma lavarli con cura con un po&#8217; di sapone. Questo perch\u00e9 un bambino in buona salute ha un sistema immunitario in grado di difendersi dai batteri di un ambiente normalmente pulito. Inoltre sarebbe corretto cambiare il biberon quando d\u00e0 segni di invecchiamento o mostra delle fratture&quot;. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante numerosi studi ne confermino gli effetti negativi sulla salute umana, la comunit\u00e0 scientifica non \u00e8 ancora giunta ad un accordo sulla pericolosit\u00e0 del Bisfenolo A.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[265],"tags":[1235,243],"class_list":["post-2327","post","type-post","status-publish","format-standard","hentry","category-salute-e-benessere","tag-benessere","tag-salute"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fracia: biberon di plastica banditi. &quot;Sono pericolosi per i beb\u00e8!&quot; - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fracia: biberon di plastica banditi. &quot;Sono pericolosi per i beb\u00e8!&quot; - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nonostante numerosi studi ne confermino gli effetti negativi sulla salute umana, la comunit\u00e0 scientifica non \u00e8 ancora giunta ad un accordo sulla pericolosit\u00e0 del Bisfenolo A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-06T09:56:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-04T18:16:09+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Fracia: biberon di plastica banditi. &#8220;Sono pericolosi per i beb\u00e8!&#8221;\",\"datePublished\":\"2009-07-06T09:56:34+00:00\",\"dateModified\":\"2018-06-04T18:16:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/\"},\"wordCount\":640,\"commentCount\":0,\"keywords\":[\"benessere\",\"salute\"],\"articleSection\":[\"Salute e benessere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/\",\"name\":\"Fracia: biberon di plastica banditi. \\\"Sono pericolosi per i beb\u00e8!\\\" - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-07-06T09:56:34+00:00\",\"dateModified\":\"2018-06-04T18:16:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fracia: biberon di plastica banditi. &#8220;Sono pericolosi per i beb\u00e8!&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fracia: biberon di plastica banditi. \"Sono pericolosi per i beb\u00e8!\" - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/","og_locale":"it_IT","og_type":"article","og_title":"Fracia: biberon di plastica banditi. \"Sono pericolosi per i beb\u00e8!\" - Article Marketing","og_description":"Nonostante numerosi studi ne confermino gli effetti negativi sulla salute umana, la comunit\u00e0 scientifica non \u00e8 ancora giunta ad un accordo sulla pericolosit\u00e0 del Bisfenolo A.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/","og_site_name":"Article Marketing","article_published_time":"2009-07-06T09:56:34+00:00","article_modified_time":"2018-06-04T18:16:09+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Fracia: biberon di plastica banditi. &#8220;Sono pericolosi per i beb\u00e8!&#8221;","datePublished":"2009-07-06T09:56:34+00:00","dateModified":"2018-06-04T18:16:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/"},"wordCount":640,"commentCount":0,"keywords":["benessere","salute"],"articleSection":["Salute e benessere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/","name":"Fracia: biberon di plastica banditi. \"Sono pericolosi per i beb\u00e8!\" - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-07-06T09:56:34+00:00","dateModified":"2018-06-04T18:16:09+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/fracia-biberon-di-plastica-banditi-sono-pericolosi-per-i-bebe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Fracia: biberon di plastica banditi. &#8220;Sono pericolosi per i beb\u00e8!&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=2327"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2327\/revisions"}],"predecessor-version":[{"id":55523,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2327\/revisions\/55523"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=2327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=2327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=2327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}