{"id":23365,"date":"2012-01-31T13:54:20","date_gmt":"2012-01-31T12:54:20","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/svelato-il-citrone-racing-trophy-2012\/"},"modified":"2012-01-31T13:54:20","modified_gmt":"2012-01-31T12:54:20","slug":"svelato-il-citrone-racing-trophy-2012","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/","title":{"rendered":"SVELATO IL CITRONE RACING TROPHY 2012"},"content":{"rendered":"<p> <em><strong><br \/>Dopo il successo della prima edizione dello scorso anno, CITRO&Euml;N Racing, CITRO&Euml;N Italia e Procar tornano a proporre il trofeo dedicato ai clienti sportivi, caratterizzato da alcune importanti novit&agrave;. Saranno ancora sei, gl<a href=\"\/uploads\/images\/u_8239\/CITROENDS3R3.jpg\" class=\"image\"><img decoding=\"async\" src=\"\/uploads\/images\/u_8239\/CITROENDS3R3.jpg\" border=\"0\" \/><\/a>i appuntamenti che daranno il valore aggiunto alla stagione dei rallies italiani, con la novit&agrave; dell&rsquo;introduzione di due gare su fondo sterrato. <br \/>Novit&agrave; previste anche per l&rsquo;attribuzione dei punteggi e nel montepremi di gara e finale, cercando di favorire i giovani piloti. <br \/>La protagonista &egrave; sempre CITRO&Euml;N DS3 R3, diventata in una sola stagione di gare la vettura di riferimento della categoria. <\/strong><\/em> <\/p>\n<p>Anche la stagione rally 2012, in Italia come nel resto d&rsquo;Europa, sar&agrave; caratterizzata dalla conferma del CITRO&Euml;N RACING TROPHY, il quale verr&agrave; nuovamente organizzato in ben 9 paesi d&rsquo;Europa<\/p>\n<p>In Italia, lo scorso anno, lo scenario del primo anno del Trofeo ha dimostrato essere tra i pi&ugrave; competitivi e in grado di portare costantemente i piloti ad ottimi risultati sia in categoria che nella classifica assoluta di ogni gara partecipata. Contestualmente hanno potuto disporre di un montepremi importante che li ha aiutati a mettere in pratica la loro passione per il motorsport. <\/p>\n<p>Come lo scorso anno, la presentazione del CITRO&Euml;N RACING TROPHY ITALIA avviene &#8211; oggi &#8211; nel contesto di ExpoRally a Brescia, la Fiera dedicata interamente al mondo del rally rivolta ad appassionati e operatori del settore, il luogo ideale per partire con una nuova ed esaltante avventura sportiva.<\/p>\n<p>Il CITRO&Euml;N RACING TROPHY ITALIA, come &egrave; stato per il 2011, proseguir&agrave; ad essere un forte strumento di comunicazione della CITRO&Euml;N DS3, lanciata due anni fa, che in Italia sta conoscendo un eccellente successo commerciale con circa 11.500 unit&agrave; vendute dal lancio . Per l&rsquo;edizione 2012 del Trofeo si &egrave; lavorato sulla scorta dell&rsquo;esperienza maturata con la prima edizione, ascoltando le impressioni dei trofeisti stessi, degli addetti ai lavori ed anche dei tanti appassionati che l&rsquo;anno scorso hanno seguito con grande attenzione l&rsquo;attivit&agrave; sportiva Citro&euml;n. Arrivano quindi alcune importanti novit&agrave;, partendo per&ograve; dalla base della passata edizione: gli appuntamenti rimarranno sei, individuati su gare in grado di assicurare percorsi ed organizzazione di elevata qualit&agrave;. <\/p>\n<p>Il CITRO&Euml;N RACING TROPHY ITALIA si svolger&agrave; nell&rsquo;arco temporale tra aprile ed ottobre, con introdotte &ndash; ecco la prima novit&agrave; &#8211; due gare su fondo sterrato. Con la scelta delle &ldquo;strade bianche&rdquo; si cerca di contribuire alla crescita tecnica dei trofeisti oltre che per conferire alle sfide pi&ugrave; adrenalina e certamente quel poco di incertezza che le render&agrave; ancora pi&ugrave; affascinanti. <\/p>\n<p>La seconda novit&agrave; riguarda l&rsquo;attribuzione dei punteggi e dei premi per gara, supportata dall&rsquo;introduzione dei coefficienti di punteggio differenziati. Ci&ograve; per rendere ancora pi&ugrave; avvincente ed incerta la stagione, per favorire ed esaltare la prestazione sportiva, la tattica di gara, la visione d&rsquo;insieme del pilota per un&rsquo;intera annata di duelli. <\/p>\n<p>Le gare su terra, che apriranno e chiuderanno la stagione del CITRO&Euml;N RACING TROPHY ITALIA, avranno assegnati quelli pi&ugrave; alti, mentre per la classifica finale saranno validi tutti i risultati, senza alcuno scarto previsto. L&rsquo;assegnazione dei premi sar&agrave; sino all&rsquo;ottavo classificato di ogni gara del Trofeo, quindi crescono gli incentivi rispetto allo scorso anno in cui venivano riconosciuti soltanto ai primi cinque classificati. <\/p>\n<p>Particolare importanza, per Citro&euml;n Racing, Citro&euml;n Italia e Procar, &egrave; data all&rsquo;attivit&agrave; dei giovani piloti dei rallies italiani. Proprio per favorirne l&rsquo;attivit&agrave; e la crescita, per loro, sono previsti ulteriori stimoli: un premio aggiuntivo nella classifica di ogni singola gara &egrave; previsto se il trofeista si classifichi nelle prime tre posizioni assolute del Gruppo R: i premi in denaro (insieme ai punti) saranno riservati per il podio ed al quarto e quinto classificato verranno assegnati soltanto i punti. In pi&ugrave;, nel caso in cui il pilota che si classifichi nelle prime tre posizioni del Gruppo R in ogni gara del Trofeo risulti un &ldquo;Under 23&rdquo;, &egrave; previsto un ulteriore bonus di 1000 Euro.<\/p>\n<p>Il premio finale del CITRO&Euml;N RACING TROPHY ITALIA &egrave; stabilito in 20.000 Euro sotto forma di un buono per l&rsquo;acquisto di ricambi &ldquo;Racing&rdquo; Citro&euml;n. Se invece il vincitore risultasse un pilota &ldquo;Under 23&rdquo; il premio &egrave; decisamente importante, se visto in funzione di una possibile carriera agonistica: la partecipazione come pilota ufficiale Citro&euml;n Italia al Rallye Monte-Carlo del 2013 con Citro&euml;n DS3 R3.<br \/>Ad oggi, il regolamento del CITRO&Euml;N RACING TROPHY ITALIA &egrave; in corso di approvazione da parte della CSAI.<\/p>\n<p>Protagonista sotto i riflettori sar&agrave; CITRO&Euml;N DS3 preparata in Gruppo R, il modello con cui &egrave; stato creato un nuovo corso agonistico. Con esso, per almeno tre anni, si vuole proseguire a cogliere quelle vibranti soddisfazioni che hanno caratterizzato le ultime stagioni sportive di Citro&euml;n sia sotto il profilo sportivo che tecnico.<\/p>\n<p>L&rsquo;attivit&agrave; sportiva accompagner&agrave; anche quest&rsquo;anno la comunicazione di CITRO&Euml;N DS3 grazie all&rsquo;impegno nel WRC con l&rsquo;8 volte Campione del mondo S&eacute;bastien Loeb \/ Daniel Elena, vincitore anche del primo appuntamento di Montecarlo della scorsa settimana e con i 9 trofei promozionali organizzati in Europa. L&rsquo;obiettivo &egrave; quello di proseguire ad essere sempre pi&ugrave; vicini ad un target di clienti giovane, dinamico e sportivo.<\/p>\n<p>IL CALENDARIO<\/p>\n<p>13-14 aprile 32&deg;Rally Conca d&rsquo;Oro (PA) T.R.T coeff.2<br \/>09-10 giugno 28&deg; Rally Lanterna (GE) T.R.A coeff.1<br \/>30 giugno-01 luglio 32&deg; Rally Casentino (AR) IRC coeff.1<br \/>31 agosto-01 settembre 48&deg; Rally del Friuli (UD) T.R.A coeff.1<br \/>21-22 settembre 36&deg; Rally Appennino Reggiano (RE) T.R.A coeff.1,5<br \/>05-06 ottobre 11&deg; Rally Nord Est -Azzano (PN) T.R.T coeff. 2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il successo della prima edizione dello scorso anno, CITRO\u00cbN Racing, CITRO\u00cbN Italia e Procar tornano a proporre il trofeo dedicato ai clienti sportivi, caratterizzato da alcune importanti novit\u00e0.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[352],"tags":[832,2841,30225],"class_list":["post-23365","post","type-post","status-publish","format-standard","hentry","category-auto","tag-citroen","tag-rally","tag-trofeo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dopo il successo della prima edizione dello scorso anno, CITRO\u00cbN Racing, CITRO\u00cbN Italia e Procar tornano a proporre il trofeo dedicato ai clienti sportivi, caratterizzato da alcune importanti novit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-31T12:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_8239\/CITROENDS3R3.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"SVELATO IL CITRONE RACING TROPHY 2012\",\"datePublished\":\"2012-01-31T12:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/\"},\"wordCount\":1015,\"commentCount\":0,\"keywords\":[\"citroen\",\"rally\",\"trofeo\"],\"articleSection\":[\"Auto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/\",\"name\":\"SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-01-31T12:54:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/svelato-il-citrone-racing-trophy-2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SVELATO IL CITRONE RACING TROPHY 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/","og_locale":"it_IT","og_type":"article","og_title":"SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing","og_description":"Dopo il successo della prima edizione dello scorso anno, CITRO\u00cbN Racing, CITRO\u00cbN Italia e Procar tornano a proporre il trofeo dedicato ai clienti sportivi, caratterizzato da alcune importanti novit\u00e0.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/","og_site_name":"Article Marketing","article_published_time":"2012-01-31T12:54:20+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_8239\/CITROENDS3R3.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"SVELATO IL CITRONE RACING TROPHY 2012","datePublished":"2012-01-31T12:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/"},"wordCount":1015,"commentCount":0,"keywords":["citroen","rally","trofeo"],"articleSection":["Auto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/","name":"SVELATO IL CITRONE RACING TROPHY 2012 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-01-31T12:54:20+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/svelato-il-citrone-racing-trophy-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"SVELATO IL CITRONE RACING TROPHY 2012"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=23365"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23365\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=23365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=23365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=23365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}