{"id":23574,"date":"2012-02-06T18:43:58","date_gmt":"2012-02-06T17:43:58","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/abolizone-dps-ecco-cosa-cambia\/"},"modified":"2012-02-06T18:43:58","modified_gmt":"2012-02-06T17:43:58","slug":"abolizone-dps-ecco-cosa-cambia","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/","title":{"rendered":"ABOLIZONE DPS: ECCO COSA CAMBIA"},"content":{"rendered":"<p>Roma, 28 gennaio 2012 &ndash; Con l&rsquo;eliminazione della lettera g) dell&rsquo;art. 34 del DLgs 196\/2003 (&ldquo;tenuta di un aggiornato documento programmatico sulla sicurezza&rdquo;) contenuta nel Decreto Semplificazioni, il Governo ha eliminato dal Codice privacy l&rsquo;obbligo della stesura del DPS, Documento Programmatico sulla Sicurezza. Questo documento andava aggiornato entro il 31 marzo di ogni anno e conteneva tutte le informazioni sulla gestione della privacy in azienda. La mancanza di questo documento comportava, in caso di controllo da parte degli organi preposti, pesanti sanzioni anche di tipo penale.<br \/>Viene eliminato cos&igrave; un adempimento che &egrave; stato sempre mal digerito da parte di tutte le aziende, pubbliche amministrazioni, liberi professionisti o altro.<br \/>Il DPS costituiva di fatto una radiografia di ci&ograve; che veniva fatto in termini di p<a href=\"http:\/\/www.suiteprivacy.it\/pages\/products\/easydps.aspx\" target=\"_blank\">rotezione dei dati personali<\/a> trattati in azienda ed era pertanto una base di partenza nei controlli che venivano effettuati dalla Guardia di Finanza.<br \/>In questa ottica e non solo, il DPS era un importante documento perch&eacute; valorizzava le politiche in materia di privacy adottate dalle aziende e rappresentava sicuramente un virtuosismo per le aziende che seriamente prestano attenzione a queste problematiche.<br \/>Allora certo che aveva un senso il DPS, visto con questa luce e non come un faldone di pagine da produrre e valutato in base al peso, spesso spacciato cos&igrave; dai cosiddetti &ldquo;tipografi del DPS&rdquo;.<br \/>Ci si chiede allora cosa &egrave; rimasto. Sicuramente sono ancora valide tutte le altre regole dell&rsquo;art.34 dell&rsquo;Allegato B, pertanto il Responsabile della sicurezza dovr&agrave; sempre produrre un documento che attesti al Titolare di aver messo in pratica in modo corretto tutte le misure di cui all&rsquo;art. 34, che si chiamer&agrave; DPS o in altro modo questo verr&agrave; reso noto nelle prossime indicazioni derivanti dalla Direttiva Europea.<br \/>Ecco cosa cambia. La proposta della Commissione Europea per il nuovo Regolamento sulla tutela dei dati personali sostituir&agrave; la direttiva 95\/46\/CE e a differenza della direttiva, il Regolamento sar&agrave; legge direttamente applicabile in ogni Stato membro, quindi anche in Italia. Sar&agrave; sicuramente una rivoluzione che avr&agrave; un forte impatto sul Codice Privacy e anche in Italia si dovranno quindi rispettare gli stessi adempimenti del resto dei paesi membri.<br \/>Le aziende quindi, seppur momentaneamente possono tirare un sospiro di sollievo per l&rsquo;abolizione del DPS, saranno sicuramente investite da adempimenti molto pi&ugrave; pesanti e onerosi. La documentazione richiesta sar&agrave; molto pi&ugrave; corposa cos&igrave; come saranno pi&ugrave; pesanti le sanzioni previste. Sar&agrave; prevista l&rsquo;adozione di un vero modello organizzativo per la tutela dei dati, con l&rsquo;introduzione, ad esempio, del principio di responsabilit&agrave; (accountability). In concreto, saranno le aziende a dover dimostrare la conformit&agrave; del loro operato alle regole comunitarie, in caso di controlli.<br \/>Anche le sanzioni infine saranno molto pi&ugrave; pensanti delle attuali, perch&eacute; saranno proporzionate in funzione del fatturato globale annuo dell&rsquo;impresa.<br \/>Cosa fare in questo tempo di transizione? Sicuramente le strutture pi&ugrave; articolate non potranno abbandonare quanto finora prodotto, ossia il DPS. Un&rsquo;azienda che esplica numerosi trattamenti come una banca, un&rsquo;assicurazione, un&rsquo;azienda sanitaria, non potr&agrave; che esigere la redazione di un documento che descriva dettagliatamente l&rsquo;organizzazione e le politiche di privacy adottate e che coincide nella logica con il DPS, senza per&ograve; rispondere ai criteri imposti dal Garante come l&rsquo;elenco degli elementi costitutivi indicati al punto 19 dell&rsquo;Allegato B.<br \/>Il DPS potr&agrave; quindi essere assunto come strumento per prevenire i reati legati al trattamento illecito dei dati e pertanto potr&agrave; continuare ad essere gestito per chi ha gi&agrave; investito finora, in attesa di percepire il nuovo Regolamento della Commissione Europea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 28 gennaio 2012 \u2013 Con l\u2019eliminazione della lettera g) dell\u2019art. 34 del DLgs 196\/2003 (\u201ctenuta di un aggiornato documento programmatico sulla sicurezza\u201d) contenuta nel Decreto Semplificazioni, il Governo ha eliminato dal Codice privacy l\u2019obbligo della stesura del DPS, Documento Programmatico sulla Sicurezza. Questo documento andava aggiornato entro il 31 marzo di ogni anno e conteneva tutte le informazioni sulla gestione della privacy in azienda.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[129],"tags":[483,32998,841],"class_list":["post-23574","post","type-post","status-publish","format-standard","hentry","category-aziende","tag-aziende","tag-gestione-dati","tag-privacy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Roma, 28 gennaio 2012 \u2013 Con l\u2019eliminazione della lettera g) dell\u2019art. 34 del DLgs 196\/2003 (\u201ctenuta di un aggiornato documento programmatico sulla sicurezza\u201d) contenuta nel Decreto Semplificazioni, il Governo ha eliminato dal Codice privacy l\u2019obbligo della stesura del DPS, Documento Programmatico sulla Sicurezza. Questo documento andava aggiornato entro il 31 marzo di ogni anno e conteneva tutte le informazioni sulla gestione della privacy in azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-06T17:43:58+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"ABOLIZONE DPS: ECCO COSA CAMBIA\",\"datePublished\":\"2012-02-06T17:43:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/\"},\"wordCount\":636,\"commentCount\":0,\"keywords\":[\"aziende\",\"gestione dati\",\"privacy\"],\"articleSection\":[\"Aziende\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/\",\"name\":\"ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-02-06T17:43:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/abolizone-dps-ecco-cosa-cambia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABOLIZONE DPS: ECCO COSA CAMBIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/","og_locale":"it_IT","og_type":"article","og_title":"ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing","og_description":"Roma, 28 gennaio 2012 \u2013 Con l\u2019eliminazione della lettera g) dell\u2019art. 34 del DLgs 196\/2003 (\u201ctenuta di un aggiornato documento programmatico sulla sicurezza\u201d) contenuta nel Decreto Semplificazioni, il Governo ha eliminato dal Codice privacy l\u2019obbligo della stesura del DPS, Documento Programmatico sulla Sicurezza. Questo documento andava aggiornato entro il 31 marzo di ogni anno e conteneva tutte le informazioni sulla gestione della privacy in azienda.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/","og_site_name":"Article Marketing","article_published_time":"2012-02-06T17:43:58+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"ABOLIZONE DPS: ECCO COSA CAMBIA","datePublished":"2012-02-06T17:43:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/"},"wordCount":636,"commentCount":0,"keywords":["aziende","gestione dati","privacy"],"articleSection":["Aziende"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/","name":"ABOLIZONE DPS: ECCO COSA CAMBIA - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-02-06T17:43:58+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/abolizone-dps-ecco-cosa-cambia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"ABOLIZONE DPS: ECCO COSA CAMBIA"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=23574"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23574\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=23574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=23574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=23574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}