{"id":23620,"date":"2012-02-08T14:34:56","date_gmt":"2012-02-08T13:34:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/"},"modified":"2012-02-08T14:34:56","modified_gmt":"2012-02-08T13:34:56","slug":"poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/","title":{"rendered":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento"},"content":{"rendered":"<p>Poltrone ortopediche personalizzabili ecco la grande novit&agrave; nel mondo dell&rsquo;arredamento e degli ausili per invalidi o anziani.<br \/>Da poche settimane &egrave; possibile personalizzare la propria poltrona ortopedica, in base ai propri gusti e alle proprie esigenze.<br \/>Queste poltrone hanno il meccanismo di aiuto all&rsquo;alzata e il sistema di reclinazione elettrica a 2 motori permettendo un movimento indipendente delle varie parti della poltrona.<br \/>Questa grande novit&agrave; &egrave; disponibile solo da poche settimane. Ci siamo accorti che <strong>personalizzare la morbidezza dei cuscini<\/strong> era fondamentale per soddisfare l&#8217;utente. infatti molti utenti hanno delle necessit&agrave; diverse. Uno pu&ograve; trovare comodo una poltrona ortopedica con seduta rigida perch&eacute; ha l&rsquo;esigenza di sentirsi mantenuto solidamente quando rilassa i suoi muscoli. Un altro invece non sopporta di appoggiare la schiena indolenzita su di uno schienale duro e predilige un materiale morbido ed accogliente per il suo relax. Altri ancora hanno problemi specifici e vogliono un appoggio anatomico che accompagni ogni curva del corpo. Adesso queste soluzioni sono disponibili con dei semplici abbinamenti. Si sceglie il modello di poltrona che pi&ugrave; ci piace e gli si abbina il cuscino che meglio si addice al nostro relax.<br \/>Sono disponibili dei cuscini di tipo:<\/p>\n<ul>\n<li>Morbido<\/li>\n<li>Rigido<\/li>\n<li>Visco-elastico (memory)<\/li>\n<\/ul>\n<p>Ma non &egrave; tutto, ora si pu&ograve; <strong>personalizzare il rivestimento. <\/strong>Che dire del piacere degli occhi? Le nuove poltrone che presentiamo sono anche completamente sfoderabili. Soddisfare il piacere degli occhi non &egrave; un optional, la poltrona ortopedica spesso si trova nel ambiente domestico pi&ugrave; frequentato, e chi non vorrebbe sfoggiare una bella poltrona che s&rsquo;abbini al ambiente circostante? Ebbene, adesso si pu&ograve; scegliere di cambiare il colore della poltrona in base alla stagione o, perch&eacute; no, in base all&rsquo;umore. Ma il vantaggio non &egrave; tutto qui. Avete mai provato a lavare il rivestimento fisso su di una poltrona ? La rivoluzione &egrave; in questo, la completa sfoderabilit&agrave; delle nostre poltrone ortopediche vi permettono di ottenere l&rsquo;igiene migliore per un tessuto di arredamento perch&eacute; &egrave; lavabile anche in lavatrice.<br \/><strong><\/strong> <strong><\/strong> Ma le novit&agrave; non finiscono qui, adesso si pu&ograve; <strong>personalizzare la propria poltrona anche nelle dimensioni<\/strong>. L&rsquo;esperienza ci ha insegnato che le poltrone ortopediche sono come le scarpe, devono essere della dimensione giusta per fare bene il loro lavoro. Ecco perch&eacute; consigliamo in questo articolo di ricercare le novit&agrave; tra quelle proposte ci sono le poltrone per disabili in 3 diverse dimensioni.<\/p>\n<ul>\n<li>Misura piccola, porta fino a 120 Kg ed &egrave; adatta per persone da 150 &ndash; 165 cm<\/li>\n<li>Misura media, porta fino a 130 Kg ed &egrave; adatta per persone da 165 &ndash; 190 cm<\/li>\n<li>Misura grande, porta fino a 160 Kg ed &egrave; adatta per persone da 180 &ndash; 210 cm<\/li>\n<\/ul>\n<p>L&rsquo;acquisto di una poltrona ortopedica richiede molta attenzione perch&eacute; &egrave; facile comprare una poltrona, ma non lo &egrave; altrettanto comprare LA poltrona fatta per s&eacute;. Le novit&agrave; in questo campo hanno ovviato a questo problema e mettono ora il relax ed il benessere del utente al di sopra di tutto il resto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento e degli ausili per invalidi o anziani.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[574],"tags":[32997,32907,33058],"class_list":["post-23620","post","type-post","status-publish","format-standard","hentry","category-interni","tag-poltrone-disabili","tag-poltrone-ortopediche","tag-poltrone-per-anziani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%252525c3%252525a0-nel-mondo-della%25252580%25252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento e degli ausili per invalidi o anziani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%252525c3%252525a0-nel-mondo-della%25252580%25252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-08T13:34:56+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento\",\"datePublished\":\"2012-02-08T13:34:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/\"},\"wordCount\":525,\"commentCount\":0,\"keywords\":[\"poltrone disabili\",\"poltrone ortopediche\",\"poltrone per anziani\"],\"articleSection\":[\"Interni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/\",\"name\":\"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-02-08T13:34:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/interni\\\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%252525c3%252525a0-nel-mondo-della%25252580%25252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/","og_locale":"it_IT","og_type":"article","og_title":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing","og_description":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento e degli ausili per invalidi o anziani.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%252525c3%252525a0-nel-mondo-della%25252580%25252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/","og_site_name":"Article Marketing","article_published_time":"2012-02-08T13:34:56+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento","datePublished":"2012-02-08T13:34:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/"},"wordCount":525,"commentCount":0,"keywords":["poltrone disabili","poltrone ortopediche","poltrone per anziani"],"articleSection":["Interni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/","name":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-02-08T13:34:56+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/interni\/poltrone-ortopediche-personalizzabili-ecco-la-grande-novit%25252525c3%25252525a0-nel-mondo-della%2525252580%2525252599arredamento-e-degli-ausili-per-invalidi-o-anziani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Poltrone ortopediche personalizzabili ecco la grande novit\u00e0 nel mondo dell\u2019arredamento"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=23620"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/23620\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=23620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=23620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=23620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}