{"id":24150,"date":"2012-02-26T15:22:42","date_gmt":"2012-02-26T14:22:42","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/localizzare-un-software-ai-tempi-del-web-2-0\/"},"modified":"2018-07-10T04:38:31","modified_gmt":"2018-07-10T02:38:31","slug":"localizzare-un-software-ai-tempi-del-web-2-0","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/","title":{"rendered":"Localizzare un software ai tempi del web 2.0"},"content":{"rendered":"<p>Nei tempi del web 2.0, della globalizzazione mediatica e dell&#8217;interscambio delle informazioni la localizzazione di un software web di ogni singola tecnologia informatica diventa imperativa. Per quale motivo?<\/p>\n<p>A partire dalla nascita ed evoluzione dei blog, all&#8217;avvento dei social network fino alle pi&ugrave; attuali strategie di marketing nel web che prevedono lo sviluppo di un piano di contenuti di valori, per posizionare un brand nel web, le informazioni viaggiano ad un ritmo molto elevato, vengono condivise da centinaia e migliaia di persone e non restano pi&ugrave; nel contesto nazionale di origine. Questo significa che la lingua della tecnologia, non &egrave; pi&ugrave; sufficiente pensarla per il solo paese d&#8217;origine, ma va adattata anche per gli altri paesi in cui &egrave; possibile prevedere la diffusione della tecnologia. E&#8217; dunque necessario <strong>localizzare un software in base alla lingua, alla cultura e in funzione delle specifiche esigenze degli utenti del paese nel quale sar&agrave; destinato<\/strong>. La ricerca di tali conformit&agrave; &egrave; definita <strong style=\"font-family: Tahoma, Arial; font-size: 11px;\">localizzazione<\/strong>. E&#8217; possibile localizzare un documento, un testo, un bilancio fino a giungere alla localizzazione del software o di un sito web <\/p>\n<p>Quali sono gli esempi di tecnologie che potrebbero essere interessate da servizi di localizzazione?<\/p>\n<p>Software web <br \/>Un software gestionale, per aziende o per utente finale, quasi raramente viene sviluppato per il solo mercato nazionale. Spesso la loro adozione sar&agrave; internazionale e quindi la lingua originale dovr&agrave; poi essere localizzata per gli altri paesi in cui verr&agrave; adottato;<\/p>\n<p>siti web<br \/>Dagli e-commerce, ai siti web turistici, ogni pagina deve avere una versione in multilingua ed essere accessibile e usabile anche da utenti differenti culturalmente e distanti geograficamente;<\/p>\n<p>Mobile Apps<br \/>Le applicazioni mobile per smartphone di ultima generazione. Un&#8217;applicazione diventa di successo se &egrave; scaricata da migliaia di persone presenti in stati differenti. Pensare allo sviluppo di un&#8217;app tenendo presenti i differenti mercati in cui giunger&agrave; e quelli in cui si evolver&agrave; nelle release successive. Per LISA (Localisation Industry Standards Association) la Localizzazione (L10N), l&#8217;Internazionalizzazione (I18N) o il suo livello pi&ugrave; alto, la Globalizzazione (G11N) sono processi di <strong>adattamento<\/strong>, per conformare l&#8217;interfaccia utente di un Software o di un Sito Web, alla lingua e ai parametri dell&#8217;utente, in funzione delle esigenze di uno specifico ambiente o mercato di destinazione. La localizzazione software si occupa anche del processo di produrre console che possano essere specificamente utilizzate nella regione geografica per la quale sono state ideate e progettate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perch\u00e8 diventa necessario localizzare il software nei tempi del web 2.0. Perch\u00e8 diventa importante offrire un servizio di localizzazione software?<br \/>Lo scenario in cui viviamo e operiamo \u00e8 ormai da anni caratterizzato da una globalizzazione delle economie e dei mercati<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[154],"tags":[33487],"class_list":["post-24150","post","type-post","status-publish","format-standard","hentry","category-web","tag-localizzazione-software"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Localizzare un software ai tempi del web 2.0 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Localizzare un software ai tempi del web 2.0 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Perch\u00e8 diventa necessario localizzare il software nei tempi del web 2.0. Perch\u00e8 diventa importante offrire un servizio di localizzazione software?Lo scenario in cui viviamo e operiamo \u00e8 ormai da anni caratterizzato da una globalizzazione delle economie e dei mercati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-26T14:22:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:38:31+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Localizzare un software ai tempi del web 2.0\",\"datePublished\":\"2012-02-26T14:22:42+00:00\",\"dateModified\":\"2018-07-10T02:38:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/\"},\"wordCount\":412,\"commentCount\":0,\"keywords\":[\"localizzazione software\"],\"articleSection\":[\"Web\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/\",\"name\":\"Localizzare un software ai tempi del web 2.0 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-02-26T14:22:42+00:00\",\"dateModified\":\"2018-07-10T02:38:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/web\\\/localizzare-un-software-ai-tempi-del-web-2-0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Localizzare un software ai tempi del web 2.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Localizzare un software ai tempi del web 2.0 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/","og_locale":"it_IT","og_type":"article","og_title":"Localizzare un software ai tempi del web 2.0 - Article Marketing","og_description":"Perch\u00e8 diventa necessario localizzare il software nei tempi del web 2.0. Perch\u00e8 diventa importante offrire un servizio di localizzazione software?Lo scenario in cui viviamo e operiamo \u00e8 ormai da anni caratterizzato da una globalizzazione delle economie e dei mercati","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/","og_site_name":"Article Marketing","article_published_time":"2012-02-26T14:22:42+00:00","article_modified_time":"2018-07-10T02:38:31+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Localizzare un software ai tempi del web 2.0","datePublished":"2012-02-26T14:22:42+00:00","dateModified":"2018-07-10T02:38:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/"},"wordCount":412,"commentCount":0,"keywords":["localizzazione software"],"articleSection":["Web"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/","name":"Localizzare un software ai tempi del web 2.0 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-02-26T14:22:42+00:00","dateModified":"2018-07-10T02:38:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/web\/localizzare-un-software-ai-tempi-del-web-2-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Localizzare un software ai tempi del web 2.0"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/24150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=24150"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/24150\/revisions"}],"predecessor-version":[{"id":59555,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/24150\/revisions\/59555"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=24150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=24150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=24150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}