{"id":2551,"date":"2009-08-13T11:31:43","date_gmt":"2009-08-13T09:31:43","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/"},"modified":"2018-06-04T20:11:55","modified_gmt":"2018-06-04T18:11:55","slug":"emo-2009-il-futuro-della-lavorazione-dei-metalli","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/","title":{"rendered":"EMO 2009: il futuro della lavorazione dei metalli"},"content":{"rendered":"<p>La crisi economica ha colpito pesantemente vari settori dell\u2019industria<br \/>\nitaliana, formata prevalentemente da PMI che hanno dovuto imparare<br \/>\nun\u2019amara lezione, che devono crescere per rendersi meno vulnerabili.<\/p>\n<p>Il<br \/>\ntessuto industriale italiano \u00e8 formato prevalentemente da piccole e<br \/>\nmedie aziende, in cui prevale ancora la gestione familiare, mentre<br \/>\nsarebbe ormai necessaria una maggiore managerializzazione di queste<br \/>\nimprese. Infatti, l\u2019organizzazione di stampo familiare ancora<br \/>\nprevalente, pu\u00f2 ridurne la competitivit\u00e0. Un processo lungo e che<br \/>\nrichieder\u00e0 ancora molto tempo.<\/p>\n<p>Anche il reparto delle lavorazioni meccaniche e delle lavorazioni meccaniche precisione<br \/>\n\u00e8 stato piuttosto colpito, tuttavia l\u2019EMO di Milano ha registrato dei<br \/>\nsegnali di ripresa in questo settore. Nata nel 1975, EMO, che si svolge<br \/>\ncon cadenza biennale, documenta l\u2019evoluzione del \u201cmondo della<br \/>\nlavorazione dei metalli\u201d, promovendo, attraverso il confronto-incontro<br \/>\ntra costruttori e utilizzatori, la definizione di soluzioni tecniche<br \/>\nsempre pi\u00f9 avanzate.<\/p>\n<p>Sono 1.250 le aziende di costruzioni meccaniche di precisione<br \/>\ne lavorazione dei metalli che saranno presenti in questa edizione dell\u2019<br \/>\nEMO 2009 dal 5 al 10 ottobre a Milano fiera. D\u2019altro canto,<br \/>\nl\u2019internazionalit\u00e0 dell\u2019evento, che giunge a Milano ogni sei anni, \u00e8<br \/>\ntestimoniata dall\u2019ampia presenza di espositori stranieri, il 70% del<br \/>\ntotale, in rappresentanza di 34 paesi.<br \/>Le decine di migliaia di<br \/>\nvisitatori che giungeranno a Milano nel prossimo ottobre potranno<br \/>\nverificare l\u2019offerta afferente a tutti i comparti del settore: dalla<br \/>\ndeformazione alla asportazione, dalla componentistica agli utensili,<br \/>\ndalla robotica alla automazione.<\/p>\n<p>Nonostante la complessa<br \/>\ncongiuntura EMO MILANO 2009 dimostra di essere appuntamento<br \/>\nirrinunciabile per gli operatori del settore. I principali protagonisti<br \/>\ndella scena mondiale saranno infatti presenti alla manifestazione,<br \/>\nanche con spazi espositivi particolarmente estesi. D\u2019altra parte se il<br \/>\nterzo trimestre dell\u2019anno coincider\u00e0 con l\u2019inversione di tendenza, cos\u00ec<br \/>\ncome rilevano alcuni istituti econometrici internazionali, EMO MILANO<br \/>\n2009 sar\u00e0 il momento per pianificare gli investimenti in beni<br \/>\nstrumentali, e chi sar\u00e0 presente alla mostra potr\u00e0 sicuramente trarne<br \/>\nbeneficio.<\/p>\n<p>Bench\u00e9 il prestigio internazionale della<br \/>\nmanifestazione espositiva e la massiccia partecipazione di costruttori<br \/>\nstranieri siano motivo d\u2019orgoglio per gli organizzatori, preoccupano le<br \/>\ndifficolt\u00e0 che stanno incontrando le piccole-medie imprese italiane,<br \/>\nche dispongono di minori risorse da investire rispetto ai competitors<br \/>\ninternazionali e rischiano, quindi, di non poter cogliere le<br \/>\nopportunit\u00e0 connesse alla partecipazione a Emo Milano 2009.<\/p>\n<p>Per<br \/>\nagevolare i costruttori italiani, Ucimu-Sistemi per Produrre &#8211;<br \/>\nl\u2019associazione dei costruttori italiani di macchine utensili, robot e<br \/>\nautomazione che, attraverso le societ\u00e0 partecipate, organizza<br \/>\nl\u2019edizione milanese della Emo \u2013 ha recentemente attivato un accordo con<br \/>\nil Gruppo CREVAL (Credito Valtellinese, Credito Artigiano, Banca<br \/>\ndell\u2019Artigianato e dell\u2019Industria, Credito Piemontese). L\u2019accordo<br \/>\nprevede l\u2019apertura di una linea di credito di 5 milioni di euro<br \/>\nfinalizzata a finanziare le spese di partecipazione alla mostra delle<br \/>\nimprese italiane. Per le sole imprese ucimiste, inoltre, Creval render\u00e0<br \/>\ndisponibili particolari benefici nella gestione del conto corrente e<br \/>\nsugli anticipi delle fatture.<\/p>\n<p>EMO Milano, grazie al suo<br \/>\nrepertorio tecnologico, che comprende un\u2019ampia gamma di macchine e<br \/>\nmacchine utensili, dai torni, ai torni per la tornitura meccanica,<br \/>\na fresatrici, macchine per il taglio e tante altre, si propone come un<br \/>\nlaboratorio di progettazione e innovazione. Un punto di vista<br \/>\nprivilegiato per il mondo della lavorazione dei metalli, dove cercare<br \/>\ncollaborazioni, affari e ammirare le ultimissime novit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crisi economica ha colpito pesantemente vari settori dell\u2019industria italiana, formata prevalentemente da PMI che hanno dovuto imparare un\u2019amara lezione, che devono crescere per rendersi meno vulnerabili.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[6627,6628,8361,8362],"class_list":["post-2551","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-lavorazione-acciaio","tag-lavorazione-lamiere","tag-lavorazioni-meccaniche-di-precisione","tag-tornitura-meccanica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMO 2009: il futuro della lavorazione dei metalli - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMO 2009: il futuro della lavorazione dei metalli - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La crisi economica ha colpito pesantemente vari settori dell\u2019industria italiana, formata prevalentemente da PMI che hanno dovuto imparare un\u2019amara lezione, che devono crescere per rendersi meno vulnerabili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-13T09:31:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-04T18:11:55+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"EMO 2009: il futuro della lavorazione dei metalli\",\"datePublished\":\"2009-08-13T09:31:43+00:00\",\"dateModified\":\"2018-06-04T18:11:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/\"},\"wordCount\":534,\"commentCount\":0,\"keywords\":[\"lavorazione acciaio\",\"lavorazione lamiere\",\"lavorazioni meccaniche di precisione\",\"tornitura meccanica\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/\",\"name\":\"EMO 2009: il futuro della lavorazione dei metalli - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-08-13T09:31:43+00:00\",\"dateModified\":\"2018-06-04T18:11:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/emo-2009-il-futuro-della-lavorazione-dei-metalli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMO 2009: il futuro della lavorazione dei metalli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMO 2009: il futuro della lavorazione dei metalli - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/","og_locale":"it_IT","og_type":"article","og_title":"EMO 2009: il futuro della lavorazione dei metalli - Article Marketing","og_description":"La crisi economica ha colpito pesantemente vari settori dell\u2019industria italiana, formata prevalentemente da PMI che hanno dovuto imparare un\u2019amara lezione, che devono crescere per rendersi meno vulnerabili.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/","og_site_name":"Article Marketing","article_published_time":"2009-08-13T09:31:43+00:00","article_modified_time":"2018-06-04T18:11:55+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"EMO 2009: il futuro della lavorazione dei metalli","datePublished":"2009-08-13T09:31:43+00:00","dateModified":"2018-06-04T18:11:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/"},"wordCount":534,"commentCount":0,"keywords":["lavorazione acciaio","lavorazione lamiere","lavorazioni meccaniche di precisione","tornitura meccanica"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/","name":"EMO 2009: il futuro della lavorazione dei metalli - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-08-13T09:31:43+00:00","dateModified":"2018-06-04T18:11:55+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/emo-2009-il-futuro-della-lavorazione-dei-metalli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"EMO 2009: il futuro della lavorazione dei metalli"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=2551"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2551\/revisions"}],"predecessor-version":[{"id":55298,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/2551\/revisions\/55298"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=2551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=2551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=2551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}