{"id":25547,"date":"2012-04-10T16:10:39","date_gmt":"2012-04-10T14:10:39","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/"},"modified":"2012-04-10T16:10:39","modified_gmt":"2012-04-10T14:10:39","slug":"a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/","title":{"rendered":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo"},"content":{"rendered":"<p>Fondazione Stelline<br \/>Corso Magenta 61<br \/>Milano<\/p>\n<p><strong>17-22 aprile 2012<\/strong><br \/><strong>Orario 10.00 &#8211; 21.00<\/strong><\/p>\n<p>Ogni giorno il giardino ospiter&agrave; dibattiti e conferenze internazionali su tematiche legate all&#8217;ambiente e all&#8217;alimentazione, con l&#8217;obiettivo di regalare alla citt&agrave; un luogo rinnovato, da vivere, coltivare e rispettare. Un luogo presso il quale verranno organizzati workshop e corsi didattici per avvicinare i cittadini al tema dell&#8217;agricoltura, e per produrre un esempio concreto di impegno della comunit&agrave; in vista del prossimo Expo.<br \/>Il progetto, curato da Valeria Gulotta e Andreina Di Maio, organizzato dalla Provincia di Milano &egrave; patrocinato dagli Assessorati Provinciali di Milano alla Moda, Eventi, Eccellenze, Expo, all&rsquo;Agricoltura e all&rsquo;Istruzione, dall&rsquo;Assessorato Regionale della Lombardia all&rsquo;Agricoltura, dalla Fondazione Stelline di Milano, oltre che dall&rsquo; Assemblea Regionale Siciliana e la Provincia Regionale di Palermo.<br \/>In collaborazione con Giuseppe Arena, l&rsquo;AIAB (Associazione Italiana per l&rsquo;Agricoltura Biologica) e Filo d&rsquo;Oro con il loro <strong>orto sensoriale<\/strong>.<br \/>Sempre i Liveinslums realizzeranno a ottobre, presso la Villa Castelnuovo di Palermo un&rsquo;altra installazione di orto verticale simile a quella di Milano in collaborazione con la Facolt&agrave; di Agraria di Palermo. Un orto didattico ed un luogo che diventi un sito Expo in itinere: da mantenere e rispettare e far crescere.<br \/>Durante le manifestazioni &egrave; prevista una raccolta fondi. Saranno messe in vendita piantine monocultura a 5 euro, il cui ricavato andr&agrave; all&rsquo;Associazione Liveinslums.<br \/>coltura Biologica). <\/p>\n<p>&#8220;Il rispetto del nostro pianeta e la promozione di comportamenti eco-sostenibili hanno come <br \/>vantaggio immediato la possibilit&agrave; di migliorare la qualit&agrave; della vita e sono il punto di partenza della <br \/>ri?essione che Expo 2015 offrir&agrave; alle nazioni del mondo. &ldquo;Orto di Leonardo &#8211; Milano plants the Expo ?eld&rdquo; &egrave; un&rsquo;iniziativa originale e innovativa: una grande occasione di adesione collettiva ai valori green, un esperimento di partecipazione, che incoraggia l&rsquo;evoluzione di comportamenti virtuosi. Un progetto che nasce per portare l&rsquo;ecologia al centro del territorio milanese attraverso la diffusione di idee per una provincia ecologica, volgendo <\/p>\n<p>l&rsquo;attenzione all&rsquo;agricoltura biologica, al consumo critico, alle energie alternative, all&rsquo;importanza del <br \/>riuso e del riciclo, alla bioedilizia, alla mobilit&agrave; sostenibile e intende favorire la costruzione di una <br \/>rete di lavoro tra istituzioni, associazioni e mondo scolastico.&#8221; dice l&rsquo;Assessore Silvia Garnero. <br \/>&#8220;L&#8217;installazione che sar&agrave; realizzata nell&#8217;orto che fu di Leonardo &#8211; commenta l&#8217;assessore <br \/>all&#8217;agricoltura di Regione Lombardia, Giulio De Capitani &#8211; stimola, anche idealmente, i cittadini a <br \/>ritrovare un contatto diretto con l&#8217;agricoltura, le sue produzioni e i suoi valori. Un obiettivo che <br \/>Regione Lombardia persegue con politiche di governo attente ai temi dell&#8217;educazione alimentare. Le <br \/>s?de che l&#8217;agricoltura moderna deve affrontare non possono infatti prescindere dal contributo che i <br \/>cittadini potranno dare attraverso il proprio stile di vita e i propri comportamenti alimentari&#8221;. <\/p>\n<p>Si ringraziano Colicodesign, Dyloan Studio, Food design, Enocultura, Aiab, Svetlana Kuliskova <br \/>Plastica Alfa, Richard Ginori, Leroy Merlin, Guida Interni, Domus, DDN e lo Chef Natale Gunta per aver creduto in questa iniziativa. <\/p>\n<p>Media partner: Radio Monte Carlo; DDN, Weekend in auto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milano si appresta ad ospitare l&#8217;Esposizione Universale del 2015 &#8220;Nutrire il pianeta, energia per la vita&#8221; e a riflettere su questi temi dedicando un prezioso angolo della citt\u00e0 all&#8217;agricoltura urbana.<br \/>Durante la settimana del Salone del Mobile, l&#8217;Orto di Leonardo (Fondazione Stelline), accoglier\u00e0 l&#8217;installazione di un orto in verticale realizzato da architetti, paesaggisti, agronomi e artisti del progetto di riqualificazione urbana Liveinslums, organizzazione non governativa, impegnata da anni in contesti di povert\u00e0 estrema nei paesi in via di sviluppo che, in collaborazione con il Master &#8220;Paesaggi Straordinari&#8221; Naba Milano-Politecnico, avvier\u00e0 proprio nell\u2019Orto di Leonardo una produzione alimentare, riproducendo una tecnica agricola sperimentata nei paesi africani.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[],"class_list":["post-25547","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cmilano-plants-the-expo-fielda%80%9d-orto-di-leonardo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Milano si appresta ad ospitare l&#039;Esposizione Universale del 2015 &quot;Nutrire il pianeta, energia per la vita&quot; e a riflettere su questi temi dedicando un prezioso angolo della citt\u00e0 all&#039;agricoltura urbana.Durante la settimana del Salone del Mobile, l&#039;Orto di Leonardo (Fondazione Stelline), accoglier\u00e0 l&#039;installazione di un orto in verticale realizzato da architetti, paesaggisti, agronomi e artisti del progetto di riqualificazione urbana Liveinslums, organizzazione non governativa, impegnata da anni in contesti di povert\u00e0 estrema nei paesi in via di sviluppo che, in collaborazione con il Master &quot;Paesaggi Straordinari&quot; Naba Milano-Politecnico, avvier\u00e0 proprio nell\u2019Orto di Leonardo una produzione alimentare, riproducendo una tecnica agricola sperimentata nei paesi africani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cmilano-plants-the-expo-fielda%80%9d-orto-di-leonardo\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-10T14:10:39+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"\u201cMilano Plants the Expo field\u201d Orto di Leonardo\",\"datePublished\":\"2012-04-10T14:10:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/\"},\"wordCount\":528,\"commentCount\":0,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/\",\"name\":\"\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-04-10T14:10:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cMilano Plants the Expo field\u201d Orto di Leonardo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cmilano-plants-the-expo-fielda%80%9d-orto-di-leonardo\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing","og_description":"Milano si appresta ad ospitare l'Esposizione Universale del 2015 \"Nutrire il pianeta, energia per la vita\" e a riflettere su questi temi dedicando un prezioso angolo della citt\u00e0 all'agricoltura urbana.Durante la settimana del Salone del Mobile, l'Orto di Leonardo (Fondazione Stelline), accoglier\u00e0 l'installazione di un orto in verticale realizzato da architetti, paesaggisti, agronomi e artisti del progetto di riqualificazione urbana Liveinslums, organizzazione non governativa, impegnata da anni in contesti di povert\u00e0 estrema nei paesi in via di sviluppo che, in collaborazione con il Master \"Paesaggi Straordinari\" Naba Milano-Politecnico, avvier\u00e0 proprio nell\u2019Orto di Leonardo una produzione alimentare, riproducendo una tecnica agricola sperimentata nei paesi africani.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cmilano-plants-the-expo-fielda%80%9d-orto-di-leonardo\/","og_site_name":"Article Marketing","article_published_time":"2012-04-10T14:10:39+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo","datePublished":"2012-04-10T14:10:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/"},"wordCount":528,"commentCount":0,"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/","name":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-04-10T14:10:39+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%2580cmilano-plants-the-expo-fielda%2580%259d-orto-di-leonardo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"\u201cMilano Plants the Expo field\u201d Orto di Leonardo"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=25547"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25547\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=25547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=25547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=25547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}