{"id":25751,"date":"2012-04-16T08:24:46","date_gmt":"2012-04-16T06:24:46","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/"},"modified":"2012-04-16T08:24:46","modified_gmt":"2012-04-16T06:24:46","slug":"rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/","title":{"rendered":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#8217;FMC"},"content":{"rendered":"<p>Rivivere le emozioni della Pasqua attraverso gli eventi che hanno caratterizzato la settimana santa nella terra di Ges&ugrave;. Dal Gioved&igrave; Santo alla Resurrezione, dalla Via Dolorosa al Santo Sepolcro attraverso celebrazioni, fede e devozione.<br \/>Attraverso i video del <a href=\"http:\/\/www.fmc-terrasanta.org\/it\/\">Franciscan Multimedia Center<\/a> potrai rivivere ogni istante della Pasqua di Gerusalemme. Dodici servizi giornalistici che raccontano liturgie, processioni ed eventi tenuti nei luoghi della resurrezione.<br \/>I video, visibili all&rsquo;indirizzo http:\/\/www.fmc-terrasanta.org, sono disponibili e consultabili in cinque lingue (Italiano, Inglese, Francese, Spagnolo e Portoghese).<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Archeologia, attualit&agrave;, cultura, eventi, pellegrini, ecumenismo, dialogo interreligioso, fede&#8230; Tanti i temi raccontati nelle <strong style=\"mso-bidi-font-weight: normal;\">videonews<\/strong> che &#8211; pubblicate quotidianamente sul nuovo sito &#8211; compongono anche il &ldquo;<strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\">Terra Santa News<\/em><\/strong>&rdquo;, l&rsquo;ormai noto TG settimanale a diffusione televisiva, trasmesso in diverse lingue dalle pi&ugrave; importanti emittenti cattoliche del mondo. <br \/><strong style=\"mso-bidi-font-weight: normal;\">Reportage<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">interviste<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">documentari<\/strong> e <strong style=\"mso-bidi-font-weight: normal;\">rubriche di spiritualit&agrave;<\/strong> arricchiscono di immagini e contenuti il sito del <strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\">Franciscan Media Center<\/em><\/strong>.<br \/>Il Centro, nato nel 2008 con sede nella citt&agrave; nuova di Gerusalemme, &egrave; in grado di offrire anche dirette delle celebrazioni dai pi&ugrave; importanti Santuari della Terra Santa. Trasmesse da molte emittenti televisive, le <strong style=\"mso-bidi-font-weight: normal;\">liturgie in diretta dai Luoghi Santi<\/strong> sono ora visibili anche via streaming attraverso il nuovo sito web.<br \/>L&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">FMC<\/strong> &egrave; una scelta coraggiosa della Custodia di Terra Santa, ma anche una sfida necessaria e impegnativa sulla quale si vuole proseguire perch&eacute; i Luoghi Santi della salvezza e tutta la loro vitalit&agrave; storica, culturale, umana e spirituale possano continuare a giungere nei cinque continenti. Da oggi con uno strumento in pi&ugrave;.<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Rivivere le emozioni della Pasqua attraverso gli eventi che hanno caratterizzato la settimana santa nella terra di Ges&ugrave;. Dal Gioved&igrave; Santo alla Resurrezione, dalla Via Dolorosa al Santo Sepolcro attraverso celebrazioni, fede e devozione.<br \/>\nAttraverso i video del Franciscan Multimedia Center potrai rivivere ogni istante della Pasqua di Gerusalemme. Dodici servizi giornalistici che raccontano liturgie, processioni ed eventi tenuti nei luoghi della resurrezione.<br \/>\nI video, visibili all&rsquo;indirizzo http:\/\/www.fmc-terrasanta.org, sono disponibili e consultabili in cinque lingue (Italiano, Inglese, Francese, Spagnolo e Portoghese).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rivivere le emozioni della Pasqua attraverso gli eventi che hanno caratterizzato la settimana santa nella terra di Ges\u00f9 grazie al Franciscan Media Center<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[34404,34400,34405,34472,5238,34901,34403,34902],"class_list":["post-25751","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-custodia-francescana-terra-santa","tag-franciscan-media-center","tag-gerusalemme","tag-getsemani","tag-pasqua","tag-santo-sepolcro","tag-terra-santa","tag-via-dolorosa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#039;FMC - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#039;FMC - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Rivivere le emozioni della Pasqua attraverso gli eventi che hanno caratterizzato la settimana santa nella terra di Ges\u00f9 grazie al Franciscan Media Center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-16T06:24:46+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#8217;FMC\",\"datePublished\":\"2012-04-16T06:24:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/\"},\"wordCount\":368,\"commentCount\":0,\"keywords\":[\"Custodia Francescana Terra Santa\",\"Franciscan Media CEnter\",\"Gerusalemme\",\"Getsemani\",\"Pasqua\",\"Santo Sepolcro\",\"Terra Santa\",\"Via Dolorosa\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/\",\"name\":\"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL'FMC - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-04-16T06:24:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#8217;FMC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL'FMC - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/","og_locale":"it_IT","og_type":"article","og_title":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL'FMC - Article Marketing","og_description":"Rivivere le emozioni della Pasqua attraverso gli eventi che hanno caratterizzato la settimana santa nella terra di Ges\u00f9 grazie al Franciscan Media Center","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/","og_site_name":"Article Marketing","article_published_time":"2012-04-16T06:24:46+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#8217;FMC","datePublished":"2012-04-16T06:24:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/"},"wordCount":368,"commentCount":0,"keywords":["Custodia Francescana Terra Santa","Franciscan Media CEnter","Gerusalemme","Getsemani","Pasqua","Santo Sepolcro","Terra Santa","Via Dolorosa"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/","name":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL'FMC - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-04-16T06:24:46+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/rivivi-le-emozioni-della-pasqua-con-i-servizi-dellfmc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"RIVIVI LE EMOZIONI DELLA PASQUA CON I SERVIZI DELL&#8217;FMC"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=25751"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25751\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=25751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=25751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=25751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}