{"id":25968,"date":"2012-04-22T19:22:48","date_gmt":"2012-04-22T17:22:48","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/"},"modified":"2012-04-22T19:22:48","modified_gmt":"2012-04-22T17:22:48","slug":"via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/","title":{"rendered":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori"},"content":{"rendered":"<p><em>Roma, 22 aprile 2012 &ndash; <\/em>I celebri pennelli torneranno a onorare la tradizione con l&rsquo;edizione numero <strong>91 della rassegna &ldquo;Cento Pittori Via Margutta&rdquo;<\/strong>,<strong> <\/strong>aprendo gli storici cavalletti e dando vita alla consueta, pacifica invasione della strada <strong>dal 27 aprile al primo maggio prossimi (orario 10.00-21.00, ingresso gratuito). <\/strong><br \/><strong> <\/strong><br \/>I festeggiamenti in corso gi&agrave; dalla scorsa settimana proseguiranno, dunque, con <strong>questa celebre manifestazione, <\/strong>patrocinata da Roma Capitale, Provincia di Roma e Regione Lazio, <strong>che &#8211; nata negli anni della Dolce Vita &#8211; ha visto esporre, tra gli altri, anche artisti del calibro di Novella Parigini, <\/strong><strong style=\"mso-bidi-font-weight: normal;\">il simbolo pi&ugrave; leggendario e l&rsquo;emblema di Via Margutta<\/strong><strong>.<\/strong><br \/><strong> <\/strong><br \/>&ldquo;Siamo felici <strong style=\"mso-bidi-font-weight: normal;\">&#8211; ha commentato Alberto Vespaziani, da quasi quarant&rsquo;anni Presidente dei Cento Pittori &ndash; <\/strong>che per rendere omaggio a quest&rsquo;angolo di Roma in quanto culla dell&rsquo;arte e strada di pittori e poeti sia stato scelto proprio il periodo in cui, da sempre, si svolge l&rsquo;edizione primaverile della manifestazione. Questo significa molto per la nostra Associazione, che rappresenta una parte significativa della tradizione e della storia di Via Margutta <strong style=\"mso-bidi-font-weight: normal;\">e che ha sempre operato non solo per promuoverne ulteriormente il nome ma per far s&igrave; che vi si continuasse a respirare il profumo dell&rsquo;arte<\/strong>&rdquo;.<strong><\/strong><\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">La manifestazione, la cui istituzionalizzazione &egrave; stata decretata nel 2009<\/strong>,<strong style=\"mso-bidi-font-weight: normal;\"> <\/strong>aveva gi&agrave; <strong style=\"mso-bidi-font-weight: normal;\">ottenuto <\/strong>da tempo<strong style=\"mso-bidi-font-weight: normal;\"> da parte dell&rsquo;Amministrazione Capitolina il riconoscimento di &ldquo;evento caratteristico delle tradizioni e della cultura nella nostra citt&agrave;&rdquo;<\/strong> capace di riportare &ldquo;puntualmente un enorme successo di pubblico, una grande partecipazione e una notevole attenzione della critica giornalistica&rdquo;. &#8220;Sono cresciuto tra i colori e le luci di Via Margutta, un mondo magico, animato dall&rsquo;estro creativo e dal talento artistico dei pittori che, da amministratore, sono fiero di aver contribuito a tutelare e valorizzare. <strong style=\"mso-bidi-font-weight: normal;\">Rappresentando un pilastro fondante del tessuto culturale di Roma e del Centro storico, la mostra &lsquo;Cento Pittori Via Margutta&rsquo; non poteva non meritare una tutela particolare&#8221;, comment&ograve; <\/strong>in quell&rsquo;occasione<strong style=\"mso-bidi-font-weight: normal;\"> Federico Mollicone, presidente della Commissione Cultura del Campidoglio.<\/strong> <\/p>\n<p>Per l&rsquo;intera durata dell&rsquo;esposizione, ancora una volta, <strong style=\"mso-bidi-font-weight: normal;\">la strada si<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">trasformer&agrave; in un&rsquo;immensa e colorata galleria a cielo aperto, mentre i suoi vicoli faranno da cornice a pi&ugrave; di 3.000 opere tra dipinti a olio, disegni, sculture e acquerelli realizzati da un centinaio di artisti rigorosamente selezionati e caratterizzati da estrazione, formazione, tematiche, linguaggi espressivi e tecniche diverse.<\/strong> Non soltanto figurazione, astrattismo, ritrattistica, paesaggismo, simbolismo e surrealismo per i tanti lavori in esposizione, ma anche l&rsquo;&ldquo;effettismo&ldquo;, una corrente innovativa che consiste nella ricerca di mezzi e colori che insieme possono riuscire ad ottenere effetti capaci di &ldquo;impressionare&rdquo; l&rsquo;osservatore.<\/p>\n<p>Accanto a sperimentazioni e soluzioni nuove <strong style=\"mso-bidi-font-weight: normal;\">quanti si ritroveranno a passeggiare nei giorni di mostra fra le tele e gli acquerelli esposti a Via Margutta avranno modo di scoprire o riscoprire il fascino di una manifestazione unica e irrinunciabile che ha trovato la propria sede naturale proprio in questa strada <\/strong>silenziosamente adagiata alle pendici del Pincio. <\/p>\n<p>Immutati nel tempo <strong style=\"mso-bidi-font-weight: normal;\">l&rsquo;entusiasmo con il quale i pittori &#8211; <\/strong>intenti a illustrare il lavoro svolto, a commentare ritratti o paesaggi, a discutere sulle tonalit&agrave; dei colori utilizzati o sulle scelte di tecniche, soggetti e tematiche da sempre rimasti liberi &#8211; <strong style=\"mso-bidi-font-weight: normal;\">continuano a cercare il dialogo con il pubblico e la loro necessit&agrave; di trasmettere ai visitatori le proprie emozioni.<\/strong> <\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">Gli stranieri non mancano, tra il pubblico cos&igrave; come a cavalletto. Dalla Polonia al Per&ugrave;, dalla Grecia al Libano, dall&rsquo;Australia all&rsquo;Argentina, e poi dall&rsquo;Olanda, dal Mozambico e da Cuba<\/strong>, ancora una volta si ripeter&agrave; la tradizionale <strong style=\"mso-bidi-font-weight: normal;\">trasferta degli artisti che arrivano dall&rsquo;estero richiamati dalla fascino della strada e di questa storica mostra che, questa volta, ha colpito anche il paese del Sol Levante, presente con una giovane pittrice, Aiko Miyauchi.<\/strong><\/p>\n<p>&ldquo;Sapere che anche artisti che vivono e lavorano dall&rsquo;altra parte del mondo desiderano partecipare a questa rassegna e vengono appositamente in Italia per farlo &ndash; precisa Alberto Vespaziani, Presidente dell&rsquo;Associazione &ndash; ci riempie d&rsquo;orgoglio e ci stimola ad impegnarci affinch&eacute; il successo e la fama di questa manifestazione continuino ad aumentare e le consentano di ottenere spazi sempre maggiori&rdquo;.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">La mostra rimane <\/strong>anche<strong style=\"mso-bidi-font-weight: normal;\"> la maniera migliore per osservare e studiare i lavori di talenti di tutte le et&agrave; che, <\/strong>tra pennelli e cornici, cercano di far <strong style=\"mso-bidi-font-weight: normal;\">riflettere sul valore intrinseco dell&rsquo;opera d&rsquo;arte, miniera inesauribile di scoperte e sorprese, e sull&rsquo;arte stessa, maestra capace di parlare un linguaggio universale, di unire in un discorso comune popoli e civilt&agrave; lontane o diverse<\/strong>, di abbattere barriere e confini e di avvicinare gli animi sconfiggendo l&rsquo;arroganza e l&rsquo;imbarbarimento che troppo spesso ci circonda.<\/p>\n<p>A prendere parte <strong style=\"mso-bidi-font-weight: normal;\">all&rsquo;attuale edizione della manifestazione, che chiuder&agrave; i battenti il 1 maggio prossimo, diversi volti noti ma anche tante giovani presenze<\/strong> che aspirano ad esporre in questo luogo in cui il tempo sembra essersi fermato accanto a nomi che hanno fatto la storia della pittura di Via Margutta. <\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">Invitati<\/strong> a tagliare il nastro di questa edizione della kermesse, il 27 aprile prossimo alle 17.00, <strong style=\"mso-bidi-font-weight: normal;\">il<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Sindaco di Roma, Gianni Alemanno, l&rsquo;Ambasciatore del Giappone, Masaharu Kohno, l&rsquo;assessore capitolino alle Politiche Culturali e delegato per il Centro storico, Dino Gasperini, il Presidente della Commissione Cultura del Campidoglio, Federico Mollicone, il Presidente del I Municipio, Orlando Corsetti.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 27 aprile al 1 maggio torna la pacifica invasione dei cavalletti dei celebri pennelli. In esposizione pi\u00f9 di 100 artisti, fra i quali anche una pittrice giapponese, autori di oltre 3.000 opere<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[30428,171,31818,1001,2825,3383],"class_list":["post-25968","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-alberto-vespaziani","tag-arte","tag-associazione-cento-pittori-via-margutta","tag-pittura","tag-scultura","tag-via-margutta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91-edizione-della-cento-pittori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dal 27 aprile al 1 maggio torna la pacifica invasione dei cavalletti dei celebri pennelli. In esposizione pi\u00f9 di 100 artisti, fra i quali anche una pittrice giapponese, autori di oltre 3.000 opere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91^-edizione-della-cento-pittori\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-22T17:22:48+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori\",\"datePublished\":\"2012-04-22T17:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/\"},\"wordCount\":948,\"commentCount\":0,\"keywords\":[\"Alberto Vespaziani\",\"arte\",\"Associazione Cento Pittori Via Margutta\",\"pittura\",\"scultura\",\"Via Margutta\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/\",\"name\":\"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-04-22T17:22:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91^-edizione-della-cento-pittori\/","og_locale":"it_IT","og_type":"article","og_title":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing","og_description":"Dal 27 aprile al 1 maggio torna la pacifica invasione dei cavalletti dei celebri pennelli. In esposizione pi\u00f9 di 100 artisti, fra i quali anche una pittrice giapponese, autori di oltre 3.000 opere","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91^-edizione-della-cento-pittori\/","og_site_name":"Article Marketing","article_published_time":"2012-04-22T17:22:48+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori","datePublished":"2012-04-22T17:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/"},"wordCount":948,"commentCount":0,"keywords":["Alberto Vespaziani","arte","Associazione Cento Pittori Via Margutta","pittura","scultura","Via Margutta"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/","name":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-04-22T17:22:48+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/via-margutta-la-festa-dedicata-alla-strada-prosegue-con-la-91%5e-edizione-della-cento-pittori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Via Margutta: la festa dedicata alla strada prosegue con la 91^ edizione della Cento Pittori"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=25968"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/25968\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=25968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=25968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=25968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}