{"id":26185,"date":"2012-05-01T14:31:33","date_gmt":"2012-05-01T12:31:33","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/cosa-vedere-a-barcellona-nel-weekend\/"},"modified":"2012-05-01T14:31:33","modified_gmt":"2012-05-01T12:31:33","slug":"cosa-vedere-a-barcellona-nel-weekend","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/","title":{"rendered":"Cosa vedere a Barcellona nel weekend"},"content":{"rendered":"<p>Barcellona &egrave; la citt&agrave; del momento. Centinaia di migliaia di italiani si riversano nelle strade della capitale della Catalogna per assaporare gioie e bellezze di luoghi che incantano. Le <a href=\"http:\/\/www.offerteweekend.eu\/\">offerte weekend<\/a> verso la citt&agrave; non mancano. Sono numerose infatti le compagnie low cost che offrono voli a meno di 30 euro a tratta, gli hostal poi sono economicissimo, quindi, se si &egrave; accorti, un fine settimana non ci costta pi&ugrave; di 150 euro a persona. <br \/>Cosa vedere a Barcellona in un fine settimana:<br \/><strong>La Sagrada Famiglia<\/strong>: &egrave; il simbolo della citt&agrave;, uno degli edifici pi&ugrave; alti. L&#8217;edificazione fu iniziata nel 1892 con uno stile neogotico, poi venne ripresa da Guad&igrave; che mor&igrave; pero&#8217; nel 1926 e non la termin&ograve; mai. <br \/>Anche se non &egrave; ancora completa, la Sagrada Familia &egrave; un tempio lussureggiante pieno di simbolismo religioso . Ecco alcuni punti salienti: sono stati costruite 8 delle 18 torri disegnate da Gaud&iacute; . L&#8217;architetto ha deciso che dodici di loro fossero dedicate agli Apostoli, i quattro Evangelisti uno verso l&#8217;altro Maria e Ges&ugrave;. Ognuna di esse ha una altezza differente a seconda della gerarchia religiosa che rappresenta. &Egrave; possibile accedere fino alla cima di alcune delle torri per vedere la citt&agrave; dall&#8217;alto e vedere alcuni dettagli degli esterni del tempio a breve distanza.<br \/><strong> Zoo<\/strong>: uno dei pi&ugrave; grandi d&#8217;Europa insieme a quello di Roma. Inaugurato nel 1892 grazie ad una donazione da una collezione privata di animali che sorgeva presso il Parco Ciudadela. Da allora la famiglia dello zoo ha continuato a crescere e conta attualmente pi&ugrave; di 7.000 esemplari di 400 specie diverse .<br \/><strong> Torre Agbar: <\/strong>&egrave; probabilmente il pi&ugrave; grande grattacielo nella citt&agrave; di Barcellona, ??questo affascinante edificio si trova in Badajoz Avenida Diagonal e Calle, vicino alla Plaza de las Glorias hotel in una parte della citt&agrave; dove si possono trovare molti alberghi. La Torre Agbar Torre ha 38 piani di cui 34 visibili, &#8216;edificio &egrave; di circa 145 metri ed &egrave; il terzo edificio pi&ugrave; alto della citt&agrave; dopo l&#8217;Hotel Arts e la Torre Mapfre.<br \/><strong>Spiagge:<\/strong> bellissime e totalmente gratuite le spiagge di Barcellona sono accessibili a tutti.<br \/>\n<strong> Park G&uuml;ell:<\/strong> &egrave; un giardino enorme con unici elementi architettonici disegnati dalla singolare penna dell&#8217;architetto Antonio Gaudi . Il parco prende il nome da Eusebi Guell, un ricco uomo d&#8217;affari con la passione per le opere di Gaud&iacute;. Anche se l&#8217;idea principale era quella di costruire un complesso residenziale di lusso , nel corso degli anni, questa idea &egrave; stata abbandonata ed &egrave; stato invece costruito un parco fantastico. Il parco &egrave; stato inaugurato nel 1922 e da allora &egrave; diventata una delle attrazioni principali della citt&agrave; . Nel 1984 &egrave; stato dichiarato Patrimonio dell&#8217;umanit&agrave; dall&#8217;UNESCO . Si estende su 17 ettari ed &egrave; pieno di superfici decorate con mosaici realizzati con pezzi di ceramica colorati .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcellona \u00e8 la citt\u00e0 del momento. Centinaia di migliaia di italiani si riversano nelle strade della capitale della Catalogna per assaporare gioie e bellezze di luoghi che incantano. Le offerte weekend verso la citt\u00e0 non mancano.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[143],"tags":[681],"class_list":["post-26185","post","type-post","status-publish","format-standard","hentry","category-destinazioni","tag-barcellona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosa vedere a Barcellona nel weekend - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa vedere a Barcellona nel weekend - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Barcellona \u00e8 la citt\u00e0 del momento. Centinaia di migliaia di italiani si riversano nelle strade della capitale della Catalogna per assaporare gioie e bellezze di luoghi che incantano. Le offerte weekend verso la citt\u00e0 non mancano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-01T12:31:33+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Cosa vedere a Barcellona nel weekend\",\"datePublished\":\"2012-05-01T12:31:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/\"},\"wordCount\":475,\"commentCount\":0,\"keywords\":[\"Barcellona\"],\"articleSection\":[\"Destinazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/\",\"name\":\"Cosa vedere a Barcellona nel weekend - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-05-01T12:31:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/cosa-vedere-a-barcellona-nel-weekend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa vedere a Barcellona nel weekend\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosa vedere a Barcellona nel weekend - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/","og_locale":"it_IT","og_type":"article","og_title":"Cosa vedere a Barcellona nel weekend - Article Marketing","og_description":"Barcellona \u00e8 la citt\u00e0 del momento. Centinaia di migliaia di italiani si riversano nelle strade della capitale della Catalogna per assaporare gioie e bellezze di luoghi che incantano. Le offerte weekend verso la citt\u00e0 non mancano.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/","og_site_name":"Article Marketing","article_published_time":"2012-05-01T12:31:33+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Cosa vedere a Barcellona nel weekend","datePublished":"2012-05-01T12:31:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/"},"wordCount":475,"commentCount":0,"keywords":["Barcellona"],"articleSection":["Destinazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/","name":"Cosa vedere a Barcellona nel weekend - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-05-01T12:31:33+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/cosa-vedere-a-barcellona-nel-weekend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Cosa vedere a Barcellona nel weekend"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/26185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=26185"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/26185\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=26185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=26185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=26185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}